{"id":41402,"date":"2013-05-22T00:00:00","date_gmt":"2013-05-22T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/"},"modified":"2025-07-01T07:03:39","modified_gmt":"2025-07-01T12:03:39","slug":"balyk-pugh-2-3","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/ar\/balyk-pugh-2-3\/","title":{"rendered":"Gouvernance en r\u00e9seaux dans les r\u00e9gions fronti\u00e8res en \u00c9quateur"},"content":{"rendered":"<p>Les quelques 135&nbsp;000 migrants forc&eacute;s colombiens qui ont fui leur pays d&rsquo;origine et vivent en &Eacute;quateur depuis 2000 constituent la population de r&eacute;fugi&eacute;s et de demandeurs d&rsquo;asile la plus importante de toute l&rsquo;Am&eacute;rique latine. Dans les villes, l&rsquo;&Eacute;tat est fort et dispose des ressources n&eacute;cessaires pour prot&eacute;ger ces personnes. Par contre, dans les zones fronti&egrave;res cette pr&eacute;sence de l&rsquo;&Eacute;tat est tr&egrave;s faible.<\/p>\n<p>Malgr&eacute; la Constitution progressiste de l&rsquo;&Eacute;quateur qui garantit aux &eacute;trangers les m&ecirc;mes droits fondamentaux qu&rsquo;aux &Eacute;quatoriens, de nombreux Colombiens rencontrent dans la pratique des difficult&eacute;s pour exercer les droits qui leur sont garantis par la Constitution du pays et par le droit international relatifs aux r&eacute;fugi&eacute;s. Ils sont nombreux &agrave; avoir &eacute;t&eacute; accueillis avec hostilit&eacute; dans leur nouveau pays&nbsp;; m&ecirc;me des fonctionnaires locaux charg&eacute;s de faire respecter la loi, l&rsquo;ordre et les droits de l&rsquo;homme ont parfois fait preuve d&rsquo;attitudes et de comportements discriminatoires envers les Colombiens. &nbsp;<\/p>\n<p>Un fonctionnaire des Nations Unies dans la province d&rsquo;Esmeraldas, dans la r&eacute;gion c&ocirc;ti&egrave;re de l&rsquo;&Eacute;quateur proche de la fronti&egrave;re colombienne, a expliqu&eacute; quel &eacute;tait le calcul politique que devait souvent faire les autorit&eacute;s locales dans les provinces : &laquo;&nbsp;Lorsque les revenus d&rsquo;un gouvernement local n&rsquo;atteignent pas les niveaux pr&eacute;vus, celui-ci n&rsquo;est naturellement pas en mesure de servir ad&eacute;quatement les besoins de la population dans son int&eacute;gralit&eacute;, c&rsquo;est pourquoi il donne la priorit&eacute; &agrave; ceux qui vont lui apporter leurs votes et leur soutien politique &ndash; &agrave; savoir les &Eacute;quatoriens&nbsp;&raquo;. &nbsp;<\/p>\n<p>L&rsquo;absence de documents d&rsquo;identit&eacute; r&eacute;duit la capacit&eacute; des migrants ill&eacute;gaux d&rsquo;obtenir de l&rsquo;assistance que ce soit de l&rsquo;&Eacute;tat ou d&rsquo;autres alli&eacute;s politiques potentiels. De fait, alors que la crainte majeure des Colombiens en possession de documents d&rsquo;identit&eacute; est d&rsquo;&ecirc;tre la proie des groupes arm&eacute;s ill&eacute;gaux et de ne pas avoir suffisamment de ressources &eacute;conomiques, c&rsquo;est l&rsquo;&Eacute;tat que les migrants sans papier craignent le plus, l&rsquo;expulsion et l&rsquo;incarc&eacute;ration &eacute;tant leurs pr&eacute;occupations majeures.<\/p>\n<p>Le r&ocirc;le des r&eacute;seaux<\/p>\n<p>Parce que le gouvernement a pour r&ocirc;le d&rsquo;appliquer &agrave; la fois les lois sur l&rsquo;immigration et celles sur l&rsquo;expulsion, et qu&rsquo;il est aussi le protecteur des droits ainsi que la source de la r&eacute;solution des disputes, les migrants h&eacute;sitent souvent par crainte &agrave; se pr&eacute;valoir de l&rsquo;assistance fournie par l&rsquo;&Eacute;tat. Pour r&eacute;pondre &agrave; ces failles pratiques dans les garanties de protection et de s&eacute;curit&eacute; pr&eacute;vues par la Constitution et la l&eacute;gislation colombiennes, les migrants forc&eacute;s colombiens en &Eacute;quateur se tournent vers des contacts informels et des acteurs non-&eacute;tatiques qui les aident &agrave; obtenir la protection n&eacute;cessaire, &agrave; n&eacute;gocier des ressources et &agrave; r&eacute;soudre leurs conflits avec les &Eacute;quatoriens. Les r&eacute;seaux de contacts personnels auxquels les migrants forc&eacute;s ont recours peuvent s&rsquo;av&eacute;rer d&eacute;terminants pour leur survie et leur succ&egrave;s lorsqu&rsquo;ils sont effray&eacute;s et qu&rsquo;ils ne savent pas comment faire valoir leurs droits et obtenir des ressources de l&rsquo;&Eacute;tat.<\/p>\n<p>&nbsp;<\/p>\n<p>Depuis que les personnalit&eacute;s locales et les ONG qui jouent ce r&ocirc;le d&rsquo;interm&eacute;diaires ont acquis davantage d&rsquo;autorit&eacute; en organisant et en repr&eacute;sentant les int&eacute;r&ecirc;ts des migrants aupr&egrave;s de l&rsquo;&Eacute;tat et en fournissant aux migrants des ressources et la protection dont ils ont besoin, leurs connexions avec le gouvernement et les acteurs internationaux ont fini par constituer un r&eacute;seau de gouvernance qui est souvent plus r&eacute;actif et plus accessible aux non-citoyens que les seules agences gouvernementales. La capacit&eacute; de mobiliser la gamme compl&egrave;te des ressources&nbsp;: non-&eacute;tatiques, informelles et &eacute;tatiques, disponibles &agrave; travers ces r&eacute;seaux de gouvernance li&eacute;s aux migrants en &Eacute;quateur est souvent le facteur qui d&eacute;termine le succ&egrave;s des Colombiens dans le pays, comme l&rsquo;illustrent ces deux exp&eacute;riences contrast&eacute;es. &nbsp;<\/p>\n<p>Eduardo est arriv&eacute; &agrave; Quito en 2009 avec ses filles apr&egrave;s avoir perdu sa femme, victime du conflit en Colombie. Sa s&oelig;ur qui se trouvait d&eacute;j&agrave; &agrave; Quito depuis neuf ans a initialement aid&eacute; Eduardo et sa famille en leur procurant &agrave; leur arriv&eacute;e de la nourriture et un abri et, plus important encore, en donnant &agrave; Eduardo de bons conseils. Il a imm&eacute;diatement rencontr&eacute; le HCR pour d&eacute;poser sa demande d&rsquo;asile, et le statut de r&eacute;fugi&eacute; lui a &eacute;t&eacute; accord&eacute; &agrave; lui et &agrave; sa famille. Au cours des mois suivants, il s&rsquo;est cr&eacute;&eacute; un r&eacute;seau avec de nouveaux amis et d&rsquo;autres r&eacute;fugi&eacute;s gr&acirc;ce auxquels il a rencontr&eacute; plusieurs organisations qui procurent de l&rsquo;assistance aux r&eacute;fugi&eacute;s. De ces organisations il a re&ccedil;u de la nourriture et de l&rsquo;aide pour couvrir ses d&eacute;penses de subsistance. Eduardo a fait plusieurs petits travaux dont il a entendu parler gr&acirc;ce &agrave; son r&eacute;seau. D&eacute;but 2011, lui et sa famille ont &eacute;t&eacute; s&eacute;lectionn&eacute;s en vue d&rsquo;une r&eacute;installation au Canada.<\/p>\n<p>En revanche, Maria est arriv&eacute;e &agrave; Quito avec son mari et leurs trois enfants en 2011 sans conna&icirc;tre personne, et ils n&rsquo;ont pas rencontr&eacute; de r&eacute;seaux susceptibles de les aider. Ils craignent d&rsquo;&eacute;tablir le moindre contact et ils &eacute;vitent de quitter leur habitation parce qu&rsquo;ils sont constamment menac&eacute;s par des membres des FARC colombiennes qui les ont attaqu&eacute;s peu de temps apr&egrave;s leur arriv&eacute;e &agrave; Quito et qui continuent de les harceler. Tr&egrave;s clairement, Maria est traumatis&eacute;e par cette rencontre et ne fait confiance &agrave; personne dans sa communaut&eacute; d&rsquo;accueil, et surtout pas aux autres Colombiens parce qu&rsquo;elle ne peut pas &ecirc;tre s&ucirc;re si leurs intentions sont bienveillantes. Maria est pr&eacute;occup&eacute;e par la survie de sa famille&nbsp;; sa qu&ecirc;te de paix et de stabilit&eacute; reste une aspiration toujours aussi distante.<\/p>\n<p>Si les organisations qui travaillent en coop&eacute;ration avec (et parfois &agrave; la place de) l&rsquo;&Eacute;tat dans le cadre d&rsquo;un r&eacute;seau de gouvernance jouent un r&ocirc;le d&eacute;terminant en mati&egrave;re de s&eacute;curit&eacute; humaine et de renforcement de la paix au sein des communaut&eacute;s qui re&ccedil;oivent des migrants, il semble int&eacute;ressant de se poser les questions suivantes&nbsp;: Quelles sont leurs interventions qui ont eu le plus de succ&egrave;s&nbsp;? Et comment l&rsquo;&Eacute;tat, le syst&egrave;me des Nations Unies et le secteur des ONG peuvent-ils les int&eacute;grer &agrave; leurs strat&eacute;gies de programme&nbsp;? L&rsquo;exp&eacute;rience de l&rsquo;&Eacute;quateur montre que des relations de travail qui impliquent une coop&eacute;ration entre les ONG, les agences des Nations Unies et les institutions de l&rsquo;&Eacute;tat qui s&rsquo;occupent de questions li&eacute;es aux migrants peuvent constituer des canaux informels ou non officiels qui leur permettent d&rsquo;obtenir un acc&egrave;s aux droits fondamentaux et aux ressources &eacute;conomiques pour les migrants que ceux-ci ne r&eacute;ussiraient peut-&ecirc;tre pas &agrave; obtenir directement aupr&egrave;s de l&rsquo;&Eacute;tat. Ces r&eacute;seaux de gouvernance ont &eacute;galement le potentiel de cr&eacute;er des espaces institutionnels permettant de favoriser un climat de tol&eacute;rance entre &Eacute;quatoriens et Colombiens.<\/p>\n<p>N&eacute;gocier des droits et une reconnaissance<\/p>\n<p>L&rsquo;Initiative de l&rsquo;enregistrement &eacute;largi, un programme conjoint du Minist&egrave;re &eacute;quatorien des affaires &eacute;trang&egrave;res et du HCR, a organis&eacute; des enregistrements mobiles &agrave; travers l&rsquo;ensemble des provinces frontali&egrave;res en 2009 et 2010, afin de rationaliser le long processus de d&eacute;termination du statut de r&eacute;fugi&eacute; et le rapprocher des endroits o&ugrave; vivent r&eacute;ellement la plupart des migrants forc&eacute;s. Ce travail a r&eacute;ussi &agrave; doubler en l&rsquo;espace d&rsquo;une ann&eacute;e le nombre de r&eacute;fugi&eacute;s enregistr&eacute;s et titulaires de documents l&eacute;gaux. L&rsquo;Initiative de l&rsquo;enregistrement &eacute;largi a fait l&rsquo;objet de louanges au niveau international dans la mesure o&ugrave; il s&rsquo;agissait d&rsquo;un exemple d&eacute;montrant que les r&eacute;seaux de gouvernance pouvaient apporter des avantages concrets aux migrants forc&eacute;s tout en renfor&ccedil;ant la capacit&eacute; de l&rsquo;&Eacute;tat. En plus d&rsquo;augmenter le nombre de bureaux permanents d&rsquo;enregistrement du gouvernement dans les provinces frontali&egrave;res, l&rsquo;initiative a &eacute;galement contribu&eacute; &agrave; forger des relations de travail &eacute;troites et fructueuses entre les fonctionnaires du Minist&egrave;re, les repr&eacute;sentants du HCR et les ONG qui ont accompagn&eacute; ce processus et en ont v&eacute;rifi&eacute; la redevabilit&eacute;. Ces ONG continuent de plaider en faveur d&rsquo;une protection accrue des r&eacute;fugi&eacute;s et de la mise &agrave; disposition d&rsquo;une assistance l&eacute;gale pour les migrants forc&eacute;s qui se rendent aux audiences de d&eacute;termination de leur statut.<\/p>\n<p>Les ONG et les acteurs internationaux peuvent jouer un r&ocirc;le compl&eacute;mentaire &agrave; celui de l&rsquo;&Eacute;tat, non seulement en mettant &agrave; disposition des espaces permettant une action commune &agrave; travers les divisions nationales mais aussi en r&eacute;duisant les in&eacute;galit&eacute;s de pouvoir et les craintes. La constitution de r&eacute;seaux gr&acirc;ce aux relations personnelles est un facteur important dans le contexte latino-am&eacute;ricain. Lors d&rsquo;une enqu&ecirc;te men&eacute;e par CEMPROC, une ONG &eacute;quatorienne, plus des deux tiers des Colombiens qui avaient confi&eacute; n&rsquo;avoir absolument aucune interaction avec des &Eacute;quatoriens &eacute;taient aussi ceux qui indiquaient avoir une perception n&eacute;gative des &Eacute;quatoriens, et aucun d&rsquo;entre eux n&rsquo;a signal&eacute; avoir une perception positive. Par contre, plus de la moiti&eacute; des Colombiens qui rapportaient avoir une v&eacute;ritable interaction avec des &Eacute;quatoriens (&agrave; travers la famille, sur le lieu de travail ou &agrave; l&rsquo;&eacute;cole) ont indiqu&eacute; qu&rsquo;ils avaient d&rsquo;eux une perception positive. &nbsp;<\/p>\n<p>Si les gouvernements, les agences des Nations Unies et les ONG cherchaient activement &agrave; renforcer les r&eacute;seaux de gouvernance et organisaient des campagnes publiques de diffusion et de sensibilisation, un plus grand nombre d&rsquo;exp&eacute;riences ressembleraient &agrave; celle d&rsquo;Eduardo et moins &agrave; celle de Maria, ce qui aurait pour effet de renforcer la s&eacute;curit&eacute; humaine pour tous dans ces r&eacute;gions fragiles qui re&ccedil;oivent des migrants.<\/p>\n<p>&nbsp;<\/p>\n<p>Lana Balyk <a href=\"mailto:balyk.lana@gmail.com\"><em>balyk.lana@gmail.com<\/em><\/a> a &eacute;t&eacute; associ&eacute;e de recherches au Center for Mediation, Peace, and Resolution of Conflict (CEMPROC). Jeff Pugh <a href=\"mailto:jpugh@providence.edu\"><em>jpugh@providence.edu<\/em><\/a> est Professeur assistant en Sciences politiques au Providence College &agrave; Rhode Island et Directeur g&eacute;n&eacute;ral de CEMPROC <a href=\"http:\/\/www.cemproc.org\">www.cemproc.org<\/a><\/p>\n<p>Cet article s&rsquo;appuie sur une enqu&ecirc;te men&eacute;e en 2009 et 2010 aupr&egrave;s de Colombiens vivant &agrave; Quito, par CEMPROC, une ONG bas&eacute;e en &Eacute;quateur. Cette enqu&ecirc;te a &eacute;t&eacute; r&eacute;alis&eacute;e avec l&rsquo;assistance d&rsquo;Emily Ginsberg et de Maribel Melo. Les noms ont &eacute;t&eacute; modifi&eacute;s pour des raisons de protection. Une version plus extensive de l&rsquo;article est disponible en ligne sur&nbsp;: <a href=\"http:\/\/www.cemproc.org\/CWPSPughBalyk.pdf\">www.cemproc.org\/CWPSPughBalyk.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les quelques 135&nbsp;000 migrants forc&eacute;s colombiens qui ont fui leur pays d&rsquo;origine et vivent en &Eacute;quateur depuis 2000 constituent la population de r&eacute;fugi&eacute;s et de demandeurs d&rsquo;asile la plus importante de toute l&rsquo;Am&eacute;rique latine. Dans les villes, l&rsquo;&Eacute;tat est fort et dispose des ressources n&eacute;cessaires pour prot&eacute;ger ces personnes. Par contre, dans les zones fronti&egrave;res&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[91],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[562],"class_list":["post-41402","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-91","fmr_content_type-article","fmr_languages-french","fmr_list_years-562","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gouvernance en r\u00e9seaux dans les r\u00e9gions fronti\u00e8res en \u00c9quateur - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gouvernance en r\u00e9seaux dans les r\u00e9gions fronti\u00e8res en \u00c9quateur - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"Les quelques 135&nbsp;000 migrants forc&eacute;s colombiens qui ont fui leur pays d&rsquo;origine et vivent en &Eacute;quateur depuis 2000 constituent la population de r&eacute;fugi&eacute;s et de demandeurs d&rsquo;asile la plus importante de toute l&rsquo;Am&eacute;rique latine. Dans les villes, l&rsquo;&Eacute;tat est fort et dispose des ressources n&eacute;cessaires pour prot&eacute;ger ces personnes. Par contre, dans les zones fronti&egrave;res&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-01T12:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/\",\"url\":\"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/\",\"name\":\"Gouvernance en r\u00e9seaux dans les r\u00e9gions fronti\u00e8res en \u00c9quateur - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2013-05-22T05:00:00+00:00\",\"dateModified\":\"2025-07-01T12:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gouvernance en r\u00e9seaux dans les r\u00e9gions fronti\u00e8res en \u00c9quateur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gouvernance en r\u00e9seaux dans les r\u00e9gions fronti\u00e8res en \u00c9quateur - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/","og_locale":"ar_AR","og_type":"article","og_title":"Gouvernance en r\u00e9seaux dans les r\u00e9gions fronti\u00e8res en \u00c9quateur - Forced Migration Review","og_description":"Les quelques 135&nbsp;000 migrants forc&eacute;s colombiens qui ont fui leur pays d&rsquo;origine et vivent en &Eacute;quateur depuis 2000 constituent la population de r&eacute;fugi&eacute;s et de demandeurs d&rsquo;asile la plus importante de toute l&rsquo;Am&eacute;rique latine. Dans les villes, l&rsquo;&Eacute;tat est fort et dispose des ressources n&eacute;cessaires pour prot&eacute;ger ces personnes. Par contre, dans les zones fronti&egrave;res&hellip;","og_url":"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-07-01T12:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/","url":"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/","name":"Gouvernance en r\u00e9seaux dans les r\u00e9gions fronti\u00e8res en \u00c9quateur - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2013-05-22T05:00:00+00:00","dateModified":"2025-07-01T12:03:39+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/balyk-pugh-2-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/balyk-pugh-2-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/ar\/"},{"@type":"ListItem","position":2,"name":"Gouvernance en r\u00e9seaux dans les r\u00e9gions fronti\u00e8res en \u00c9quateur"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41402\/revisions"}],"predecessor-version":[{"id":48390,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41402\/revisions\/48390"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/media?parent=41402"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_themes?post=41402"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_region?post=41402"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_issue?post=41402"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_year?post=41402"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content_type?post=41402"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_languages?post=41402"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_list_years?post=41402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}