{"id":41409,"date":"2013-05-22T00:00:00","date_gmt":"2013-05-22T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/seeley-2-3\/"},"modified":"2025-07-01T07:03:39","modified_gmt":"2025-07-01T12:03:39","slug":"seeley-2-3","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/ar\/seeley-2-3\/","title":{"rendered":"La po\u00e9sie comme r\u00e9sistance des femmes face aux cons\u00e9quences du d\u00e9placement des B\u00e9douins en Jordanie"},"content":{"rendered":"<p>Les populations b&eacute;douines au Moyen Orient ont v&eacute;cu un d&eacute;placement significatif qui s&rsquo;est traduit par des pertes de biens ou d&rsquo;acc&egrave;s aux biens, entra&icirc;nant au cours des soixante derni&egrave;res ann&eacute;es une perte progressive de leurs moyens d&rsquo;existence. Les B&eacute;douins des gouvernorats ruraux d&rsquo;Aqaba et Ma&rsquo;an dans le sud de la Jordanie se sont vus interdire de suivre leurs routes migratoires du fait d&rsquo;un renforcement de la fronti&egrave;re avec l&rsquo;Arabie Saoudite et d&rsquo;initiatives gouvernementales qui cherchaient &agrave; inciter les B&eacute;douins &agrave; se s&eacute;dentariser. Tr&egrave;s peu de B&eacute;douins jordaniens d&eacute;pendent aujourd&rsquo;hui de l&rsquo;&eacute;levage transhumant pour leur subsistance, et la plupart des familles survivent gr&acirc;ce aux salaires des hommes (par exemple dans l&rsquo;industrie du tourisme), aux retraites militaires et &agrave; des subventions de l&rsquo;&Eacute;tat.<\/p>\n<p>Ce d&eacute;placement caus&eacute; par la perte d&rsquo;un mode de vie migratoire a significativement affect&eacute; le r&ocirc;le social et familial des femmes b&eacute;douines. La transition &agrave; une vie s&eacute;dentaire et &agrave; une plus grande proximit&eacute; g&eacute;ographique et spatiale avec des personnes ext&eacute;rieures &agrave; la famille a oblig&eacute; les femmes &agrave; adopter des mesures pour &eacute;viter le contact avec des hommes ne faisant pas partie de leur famille. Dans les contextes s&eacute;dentaires denses dans lesquels les B&eacute;douins se sont trouv&eacute;s d&eacute;plac&eacute;s, cet aspect a eu des cons&eacute;quences graves sur la mobilit&eacute; des femmes et a restreint &nbsp;leur capacit&eacute; de contribution &eacute;conomique &agrave; leur famille tout en limitant leur participation aux activit&eacute;s publiques et &agrave; la prise de d&eacute;cisions. Auparavant, dans un contexte d&rsquo;&eacute;levage transhumant le travail des femmes avait une importance d&eacute;terminante pour la survie de la famille, dans la mesure o&ugrave; elles &eacute;taient responsables des soins aux animaux, de la traite et de la transformation des produits laitiers, ainsi que de l&rsquo;entretien, du transport et de l&rsquo;&eacute;rection des tentes. Dans les contextes propres &agrave; l&rsquo;&eacute;levage transhumant, les activit&eacute;s men&eacute;es par les femmes leur permettaient &eacute;galement d&rsquo;occuper un espace plus &eacute;tendu et leurs mouvements &eacute;taient soumis &agrave; moins de restrictions.<\/p>\n<p>Parce que la plupart des familles ne d&eacute;pendent plus des animaux domestiques et que l&rsquo;&eacute;norme majorit&eacute; des salari&eacute;s dans les familles b&eacute;douines sont aujourd&rsquo;hui des hommes, les femmes se sont trouv&eacute;es largement mises &agrave; l&rsquo;&eacute;cart en termes de leur contribution &eacute;conomique, et en cons&eacute;quence leur influence par rapport aux d&eacute;cisions concernant l&rsquo;&eacute;conomie de leurs propres familles s&rsquo;en est trouv&eacute;e consid&eacute;rablement r&eacute;duite. La restriction de leurs mouvements publics et de leur interaction avec des hommes &eacute;trangers &agrave; leur famille rend &eacute;galement difficile toute activit&eacute; politique aux femmes b&eacute;douines.<\/p>\n<p>La forme traditionnelle d&rsquo;art appel&eacute;e po&eacute;sie Nabati (<em>al-sha&rsquo;r al-Nabati<\/em>), un genre po&eacute;tique oral compos&eacute; tant par les hommes que par les femmes &agrave; travers toute la p&eacute;ninsule arabique, s&rsquo;est av&eacute;r&eacute;e une moyen de r&eacute;sistance acceptable. La po&eacute;sie Nabati constitue un mode de r&eacute;sistance de plusieurs mani&egrave;res&nbsp;: en augmentant la mobilit&eacute; spatiale et g&eacute;ographique des femmes, en leur fournissant des opportunit&eacute;s d&rsquo;exprimer des critiques politiques et sociales, et en permettant &agrave; certaines femmes d&rsquo;&eacute;tablir des carri&egrave;res en tant que po&egrave;tes ce qui leur vaut respect, influence et avantages financiers.<\/p>\n<p>Contrairement &agrave; la majorit&eacute; des femmes b&eacute;douines vivant en milieu rural, une femme po&egrave;te (<em>sh\u0101&rsquo;irah<\/em>) peut parcourir hors de chez elle, accompagn&eacute;e de son mari ou d&rsquo;un individu de confiance, de longues distances en voiture pour participer &agrave; une soir&eacute;e po&eacute;tique (<em>umsiyyah<\/em>) ou &agrave; une joute po&eacute;tique (<em>mahraj\u0101n<\/em>). Il s&rsquo;agit-l&agrave; d&rsquo;un contraste flagrant avec les restrictions impos&eacute;es &agrave; de nombreuses femmes b&eacute;douines qui ne sont pas po&egrave;tes et dont les mouvements sont tellement limit&eacute;s qu&rsquo;elles ne peuvent m&ecirc;me pas appara&icirc;tre dans un village en dehors de chez elles. Une femme po&egrave;te, par contre, peut r&eacute;citer son &oelig;uvre devant une audience qui peut compter jusqu&rsquo;&agrave; 500 hommes sans susciter aucune critique concernant sa moralit&eacute;. Les femmes po&egrave;tes qui ont le plus de succ&egrave;s peuvent m&ecirc;me, si elles en ont les moyens, voyager &agrave; l&rsquo;&eacute;tranger pour participer &agrave; des rencontres po&eacute;tiques internationales comme la comp&eacute;tition t&eacute;l&eacute;vis&eacute;e des &Eacute;mirats &lsquo;<em>Sh\u0101&rsquo;r <\/em><em>al-Million<\/em>&rsquo; (&lsquo;Le po&egrave;te du million&rsquo;). Pendant et apr&egrave;s ces rencontres il peut arriver que les femmes po&egrave;tes conversent et mangent avec des hommes ext&eacute;rieurs &agrave; leur famille et, dans ce contexte d&rsquo;une soir&eacute;e po&eacute;tique, cela n&rsquo;engendre habituellement pas la r&eacute;probation sociale.<\/p>\n<p>Les rencontres de po&eacute;sie Nabati permettent &eacute;galement aux femmes b&eacute;douines d&eacute;plac&eacute;es de participer au d&eacute;bat politique et social. Une part importante des po&egrave;mes compos&eacute;s par les femmes abordent des questions controvers&eacute;es comme la corruption politique et des actes per&ccedil;us comme d&eacute;loyaux, les mouvements du printemps arabe et la nature d&rsquo;&ecirc;tre Jordaniens. La limitation de leurs chances de poursuivre des &eacute;tudes sup&eacute;rieures interdit aux femmes la perspective d&rsquo;&ecirc;tre des dirigeantes politiques mais pas celle de composer des po&egrave;mes influents. La famille d&rsquo;une femme po&egrave;te s&rsquo;opposait fermement &agrave; ce qu&rsquo;elle participe &agrave; la politique, mais par contre a soutenu son action politique &agrave; travers un po&egrave;me controvers&eacute; et largement diffus&eacute; critiquant des dirigeants.&nbsp;<\/p>\n<p>Une renomm&eacute;e en tant que po&egrave;te accomplie signifie &eacute;galement qu&rsquo;une femme puisse se forger une position de prestige social en tant que contributrice &agrave; l&rsquo;honneur et &agrave; la r&eacute;putation de sa famille et s&rsquo;&eacute;tablir en tant qu&rsquo;intellectuelle de valeur, digne de se joindre aux discussions politiques des hommes.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Maira Seeley <a href=\"mailto:maira.seeley@hmc.ox.ac.uk\"><em>maira.seeley@hmc.ox.ac.uk<\/em><\/a> est &eacute;tudiante &agrave; l&rsquo;Universit&eacute; d&rsquo;Oxford.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les populations b&eacute;douines au Moyen Orient ont v&eacute;cu un d&eacute;placement significatif qui s&rsquo;est traduit par des pertes de biens ou d&rsquo;acc&egrave;s aux biens, entra&icirc;nant au cours des soixante derni&egrave;res ann&eacute;es une perte progressive de leurs moyens d&rsquo;existence. Les B&eacute;douins des gouvernorats ruraux d&rsquo;Aqaba et Ma&rsquo;an dans le sud de la Jordanie se sont vus interdire&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[91],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[562],"class_list":["post-41409","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-91","fmr_content_type-article","fmr_languages-french","fmr_list_years-562","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La po\u00e9sie comme r\u00e9sistance des femmes face aux cons\u00e9quences du d\u00e9placement des B\u00e9douins en Jordanie - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/seeley-2-3\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La po\u00e9sie comme r\u00e9sistance des femmes face aux cons\u00e9quences du d\u00e9placement des B\u00e9douins en Jordanie - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"Les populations b&eacute;douines au Moyen Orient ont v&eacute;cu un d&eacute;placement significatif qui s&rsquo;est traduit par des pertes de biens ou d&rsquo;acc&egrave;s aux biens, entra&icirc;nant au cours des soixante derni&egrave;res ann&eacute;es une perte progressive de leurs moyens d&rsquo;existence. Les B&eacute;douins des gouvernorats ruraux d&rsquo;Aqaba et Ma&rsquo;an dans le sud de la Jordanie se sont vus interdire&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/seeley-2-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-01T12:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/seeley-2-3\/\",\"url\":\"https:\/\/www.fmreview.org\/seeley-2-3\/\",\"name\":\"La po\u00e9sie comme r\u00e9sistance des femmes face aux cons\u00e9quences du d\u00e9placement des B\u00e9douins en Jordanie - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2013-05-22T05:00:00+00:00\",\"dateModified\":\"2025-07-01T12:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/seeley-2-3\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/seeley-2-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/seeley-2-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La po\u00e9sie comme r\u00e9sistance des femmes face aux cons\u00e9quences du d\u00e9placement des B\u00e9douins en Jordanie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La po\u00e9sie comme r\u00e9sistance des femmes face aux cons\u00e9quences du d\u00e9placement des B\u00e9douins en Jordanie - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/seeley-2-3\/","og_locale":"ar_AR","og_type":"article","og_title":"La po\u00e9sie comme r\u00e9sistance des femmes face aux cons\u00e9quences du d\u00e9placement des B\u00e9douins en Jordanie - Forced Migration Review","og_description":"Les populations b&eacute;douines au Moyen Orient ont v&eacute;cu un d&eacute;placement significatif qui s&rsquo;est traduit par des pertes de biens ou d&rsquo;acc&egrave;s aux biens, entra&icirc;nant au cours des soixante derni&egrave;res ann&eacute;es une perte progressive de leurs moyens d&rsquo;existence. Les B&eacute;douins des gouvernorats ruraux d&rsquo;Aqaba et Ma&rsquo;an dans le sud de la Jordanie se sont vus interdire&hellip;","og_url":"https:\/\/www.fmreview.org\/seeley-2-3\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-07-01T12:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/seeley-2-3\/","url":"https:\/\/www.fmreview.org\/seeley-2-3\/","name":"La po\u00e9sie comme r\u00e9sistance des femmes face aux cons\u00e9quences du d\u00e9placement des B\u00e9douins en Jordanie - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2013-05-22T05:00:00+00:00","dateModified":"2025-07-01T12:03:39+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/seeley-2-3\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/seeley-2-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/seeley-2-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/ar\/"},{"@type":"ListItem","position":2,"name":"La po\u00e9sie comme r\u00e9sistance des femmes face aux cons\u00e9quences du d\u00e9placement des B\u00e9douins en Jordanie"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41409\/revisions"}],"predecessor-version":[{"id":48397,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41409\/revisions\/48397"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/media?parent=41409"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_themes?post=41409"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_region?post=41409"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_issue?post=41409"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_year?post=41409"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content_type?post=41409"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_languages?post=41409"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_list_years?post=41409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}