{"id":41412,"date":"2013-05-22T00:00:00","date_gmt":"2013-05-22T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/meili-2-3\/"},"modified":"2025-07-01T07:03:40","modified_gmt":"2025-07-01T12:03:40","slug":"meili-2-3","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/ar\/meili-2-3\/","title":{"rendered":"Comment un mauvais usage des trait\u00e9s sur les droits humains minimise les chances des demandeurs d\u2019asile"},"content":{"rendered":"<p>On pourrait avancer que le Royaume-Uni conna&icirc;t aujourd&rsquo;hui son &acirc;ge d&rsquo;or en mati&egrave;re de jurisprudence dans le domaine des droits humains pour les r&eacute;fugi&eacute;s. Depuis que la Convention europ&eacute;enne des droits de l&rsquo;homme (CEDH) a &eacute;t&eacute; transpos&eacute;e en droit britannique en 2000 par le biais du <em>Human Rights Act<\/em> (HRA, la loi britannique relative aux droits humains), les juges se sont montr&eacute;s de plus en plus r&eacute;ceptifs aux arguments bas&eacute;s sur les droits humains pr&eacute;sent&eacute;s par des avocats plaidant en faveur de r&eacute;fugi&eacute;s. Auparavant, les avocats repr&eacute;sentant des r&eacute;fugi&eacute;s devant les tribunaux britanniques invoquaient rarement d&rsquo;autres trait&eacute;s sur les droits humains que la Convention de 1951 relative au statut des r&eacute;fugi&eacute;s. Comme l&rsquo;un de ses avocats me l&rsquo;a expliqu&eacute;, les juges auraient r&eacute;agi avec m&eacute;pris face &agrave; une telle pratique: &laquo;Si vous mentionniez la CEDH devant un tribunal d&rsquo;immigration avant l&rsquo;an 2000, ils vous auraient regard&eacute; en vous faisant comprendre que vous leur faisiez perdre leur temps.&raquo;<\/p>\n<p>Lorsque le HRA a &eacute;t&eacute; vot&eacute;, les avocats plaidant devant les tribunaux britanniques avaient soudainement &agrave; leur disposition de nouvelles possibilit&eacute;s qui s&rsquo;&eacute;tendaient au-del&agrave; de la Convention de 1951. Ils n&rsquo;avaient plus besoin de d&eacute;montrer que leur client risquerait d&rsquo;&ecirc;tre pers&eacute;cut&eacute; &laquo;du fait de sa race, de sa religion, de sa nationalit&eacute;, de son appartenance &agrave; un certain groupe social ou de ses opinions politiques&raquo;. Par exemple, l&rsquo;article 3 de la CEDH interdit aux pays de rapatrier un r&eacute;fugi&eacute; vers son pays d&rsquo;origine s&rsquo;il risque d&rsquo;y &ecirc;tre tortur&eacute; ou de subir un traitement ou des sanctions inhumains ou d&eacute;gradants, indiff&eacute;remment de la raison ou du fait qu&rsquo;il ait &eacute;t&eacute; ou non personnellement cibl&eacute;. L&rsquo;article 8, quant &agrave; lui, interdit aux autorit&eacute;s d&rsquo;entraver le droit d&rsquo;une personne &agrave; une vie familiale, ce qui a permis &agrave; de nombreux non-ressortissants de rester au Royaume-Uni m&ecirc;me lorsqu&rsquo;ils ne r&eacute;pondent pas aux crit&egrave;res de la Convention de 1951 concernant le bien fond&eacute; de leur crainte d&rsquo;&ecirc;tre pers&eacute;cut&eacute;s.<a href=\"#_edn1\" name=\"_ednref1\" title=\"\">[1]<\/a><\/p>\n<p>En cons&eacute;quence, il est aujourd&rsquo;hui courant de voir les avocats britanniques s&rsquo;appuyer sur la CEDH dans les tribunaux britanniques. Selon deux avocats: &laquo;La CEDH [&#8230;] fait tout simplement partie de notre vocabulaire quotidien. Elle s&rsquo;applique directement &agrave; la plupart de notre travail&raquo; et &laquo;Lorsque j&rsquo;ai commenc&eacute; [au d&eacute;but des ann&eacute;es 1990] &#8230; [t]out tournait autour de la Convention relative au statut des r&eacute;fugi&eacute;s. [La] Convention europ&eacute;enne n&rsquo;&eacute;tait pratiquement jamais mentionn&eacute;e&#8230;&raquo;<\/p>\n<p>Les avocats invoquent parfois d&rsquo;autres trait&eacute;s sur les droits humains, notamment la Convention relative aux droits de l&rsquo;enfant, aujourd&rsquo;hui transpos&eacute;e en droit britannique.<\/p>\n<p>N&eacute;anmoins, lorsque j&rsquo;ai demand&eacute; aux avocats s&rsquo;il pouvait s&rsquo;av&eacute;rer nuisible aux droits de demandeurs d&rsquo;invoquer les trait&eacute;s sur les droits humains dans les tribunaux britanniques, presque tous ont &eacute;t&eacute; capables de me donner un exemple.<\/p>\n<ul>\n<li>\n\t\t<strong>Lorsque le juge est oppos&eacute; au droit des droits de l&rsquo;homme, ou du moins sceptique<\/strong>: Un avocat ne peut pas faire grand-chose dans ce cas puisqu&rsquo;il pourrait &ecirc;tre difficile d&rsquo;utiliser des arguments relatifs aux droits humains lors de l&rsquo;appel s&rsquo;ils n&rsquo;ont pas &eacute;t&eacute; utilis&eacute;s (et rejet&eacute;s) &agrave; un stade ant&eacute;rieur de la proc&eacute;dure.<\/li>\n<li>\n\t\t<strong>Lorsque l&rsquo;argumentation bas&eacute;e sur le trait&eacute; complique les choses:<\/strong> Plusieurs avocats ont signal&eacute; que les juges, en particulier les juges de premi&egrave;re instance des tribunaux de l&rsquo;immigration, aiment que les choses restent simples. Comme l&rsquo;explique un avocat: &laquo;Cela pourrait pr&ecirc;ter &agrave; confusion. Si vous pouvez trouver ce dont vous avez besoin dans les trait&eacute;s transpos&eacute;s ou dans la l&eacute;gislation nationale, alors vous risquez de rendre les choses plus compliqu&eacute;es et de semer le doute, particuli&egrave;rement au tribunal [&#8230;] en vous reportant aux trait&eacute;s dont ils ne savent rien.&raquo;<\/li>\n<li>\n\t\t<strong>Lorsque les avocats utilisent de mani&egrave;re indiscrimin&eacute;e des arguments bas&eacute;s sur les droits humains:<\/strong> Proc&eacute;dant ainsi, ils brouillent leurs meilleurs arguments et perdent en cr&eacute;dibilit&eacute; devant le tribunal. &laquo;Certaines personnes pensent qu&rsquo;elles doivent tout mentionner. [&#8230;] Il m&rsquo;est arriv&eacute; de nombreuses fois d&rsquo;assister &agrave; une audience et d&rsquo;entendre le juge dire: &ldquo;En quoi cela renforce-t-il votre argumentation?&rdquo; Pourquoi se mettre dans une telle position?&raquo;<\/li>\n<li>\n\t\t<strong>Lorsque le juge interpr&egrave;te les arguments bas&eacute;s sur les droits humains comme une tentative d&eacute;sesp&eacute;r&eacute;e:<\/strong> &laquo;Je pense que ce que cela veut dire, c&rsquo;est que lorsque votre argumentation juridique est solide, vous n&rsquo;avez pas besoin de recourir au <em>Human Rights Act<\/em>, sauf [lorsqu&rsquo;il s&rsquo;agit] strictement [de la question de] la torture&#8230; Sinon, il semble que vous y recourez uniquement parce que vous &ecirc;tes d&eacute;sesp&eacute;r&eacute;, ce qui signifie donc que votre argumentation est peu solide.&raquo;<\/li>\n<\/ul>\n<p>Le risque commun &agrave; toutes ces situations, c&rsquo;est de cr&eacute;er une mauvaise jurisprudence.<\/p>\n<p>Un avocat d&eacute;sesp&eacute;r&eacute; et mal pr&eacute;par&eacute; qui inclut dans son plaidoyer un argument sp&eacute;cieux ou inutile bas&eacute; sur un trait&eacute; pourrait cr&eacute;er un pr&eacute;c&eacute;dent juridique qui aura un effet pr&eacute;judiciable non seulement sur son client mais aussi sur les futurs demandeurs. Il est d&rsquo;ailleurs possible que ce risque s&rsquo;accentue prochainement, puisque les avocats sp&eacute;cialis&eacute;s en droit des r&eacute;fugi&eacute;s semblent s&rsquo;accorder sur le fait que la r&eacute;duction de l&rsquo;aide juridique au Royaume-Uni poussera certains des meilleurs avocats &agrave; abandonner ce domaine, laissant ainsi la porte grande ouverte &agrave; des praticiens moins qualifi&eacute;s. De surcro&icirc;t, plusieurs avocats nous ont confi&eacute; qu&rsquo;ils craignaient que ceux qui resteront se mettent &agrave; adopter une mentalit&eacute; de travail &agrave; la cha&icirc;ne ou de travail en usine. Cette approche aura probablement deux cons&eacute;quences possibles pour les arguments bas&eacute;s sur les droits humains: certains avocats peu familiers avec ces arguments les omettront alors m&ecirc;me qu&rsquo;ils auraient pu aider leurs clients, tandis que d&rsquo;autres les int&eacute;greront &agrave; tous leurs plaidoyers, sans vraiment r&eacute;fl&eacute;chir s&rsquo;ils s&rsquo;appliquent v&eacute;ritablement &agrave; l&rsquo;affaire en cours ou s&rsquo;ils pourraient au contraire indisposer un juge particulier.<\/p>\n<p>Tout en reconnaissant les risques d&rsquo;avancer des arguments bas&eacute;s sur les droits humains dans ces conditions, les avocats ont identifi&eacute; deux principaux moyens de pr&eacute;server et m&ecirc;me d&rsquo;accentuer l&rsquo;impact positif des trait&eacute;s relatifs aux droits humains sur la jurisprudence britannique. Le premier consiste &agrave; jouer sur la perspective de plus en plus internationalis&eacute;e de nombreux juges, en particulier dans les instances sup&eacute;rieures. Selon les avocats, de nombreux juges estiment aujourd&rsquo;hui qu&rsquo;ils op&egrave;rent sur une sc&egrave;ne mondiale o&ugrave; leurs d&eacute;cisions sont analys&eacute;es par les tribunaux, les avocats et les universitaires de toute la plan&egrave;te. Si c&rsquo;est le cas, les avocats sp&eacute;cialis&eacute;s en droit des r&eacute;fugi&eacute;s pourraient alors judicieusement jouer sur le d&eacute;sir du juge d&rsquo;&ecirc;tre &agrave; l&rsquo;avant-garde des &eacute;volutions juridiques mondiales, ou du moins de suivre ces celles-ci.<\/p>\n<p>Une autre strat&eacute;gie expliqu&eacute;e par certains avocats consisterait &agrave; &laquo;continuer et continuer encore [jusqu&rsquo;&agrave;] ce que les choses se mettent enfin &agrave; changer. Les tribunaux mettent du temps &agrave; &eacute;voluer&#8230; On nous rebat les oreilles avec les droits de l&rsquo;enfant depuis des dizaines d&rsquo;ann&eacute;es. Pourtant, cela fait seulement quelques ann&eacute;es qu&rsquo;ils font vraiment la diff&eacute;rence.&raquo; &nbsp;&nbsp;&nbsp;<\/p>\n<p>En effet, plusieurs avocats ont soulign&eacute; l&rsquo;utilit&eacute; de continuer &agrave; soutenir des arguments bas&eacute;s sur les droits humains, mais de mani&egrave;re cr&eacute;ative et non d&eacute;sesp&eacute;r&eacute;e, jusqu&rsquo;&agrave; ce qu&rsquo;un juge d&rsquo;une instance sup&eacute;rieure les accepte.<\/p>\n<p>En fin de compte, la plupart des avocats envisagent le futur r&ocirc;le des trait&eacute;s relatifs aux droits humains dans le domaine du droit des r&eacute;fugi&eacute;s de deux mani&egrave;res: soit comme une lutte constante contre le durcissement des r&egrave;gles &agrave; un endroit &agrave; chaque fois qu&rsquo;a lieu une avanc&eacute;e &agrave; un autre endroit, soit comme un moyen de reconna&icirc;tre que la lutte concernant une interpr&eacute;tation diverse des trait&eacute;s relatifs aux droits humains et leur applicabilit&eacute; aux cas individuels ne sera pas gagn&eacute;e du jour au lendemain: &laquo;Ces batailles se gagnent lentement, par d&eacute;veloppements successifs. Et un jour, vous d&eacute;couvrez que le monde a avanc&eacute; et que les choses qui &eacute;taient controvers&eacute;es il y a dix ans sont aujourd&rsquo;hui devenues la norme.&raquo;<\/p>\n<p>En conclusion, les trait&eacute;s sur les droits humains sont de plus en plus accept&eacute;s par les cours et tribunaux britanniques depuis ces dix derni&egrave;res ann&eacute;es. Il s&rsquo;agit bien entendu d&rsquo;une bonne nouvelle pour les d&eacute;fenseurs des droits humains. Il y a toutefois une ombre au tableau car, comme les avocats sp&eacute;cialis&eacute;s en droit des r&eacute;fugi&eacute;s s&rsquo;accordent g&eacute;n&eacute;ralement &agrave; dire, les arguments bas&eacute;s sur ces trait&eacute;s peuvent parfois porter pr&eacute;judice aux demandeurs d&rsquo;asile, de m&ecirc;me qu&rsquo;&agrave; la cause plus globale de la diffusion du droit international des droits humains. Ces avocats soulignent l&rsquo;importance de pr&eacute;parer avec soin ce type d&rsquo;argument plut&ocirc;t que d&rsquo;adopter une approche uniforme pour tous les cas. Selon eux, la pratique la plus sage est de tenir compte du juge pr&eacute;sident, de la force (et du nombre) des autres arguments disponibles et du degr&eacute; d&rsquo;acceptation des arguments propos&eacute;s par les tribunaux des autres juridictions.<\/p>\n<p>&nbsp;<\/p>\n<p>Stephen Meili <em>smeili@umn.edu <\/em>est membre du corps enseignant de l&rsquo;&Eacute;cole de droit de l&rsquo;Universit&eacute; du Minnesota. Cet article s&rsquo;appuie sur des entretiens avec 42 avocats britanniques qui d&eacute;fendent des demandes d&rsquo;asile et de protection compl&eacute;mentaire devant le tribunal de l&rsquo;asile et de l&rsquo;immigration et des instances sup&eacute;rieures. Ces entretiens s&rsquo;inscrivent dans le cadre d&rsquo;un projet empirique de plus grande envergure visant &agrave; analyser l&rsquo;impact des trait&eacute;s relatifs aux droits humains sur la jurisprudence et la pratique en mati&egrave;re de droit des r&eacute;fugi&eacute;s en Australie, au Canada, en Nouvelle-Z&eacute;lande, au Royaume-Uni et aux &Eacute;tats-Unis. L&rsquo;auteur remercie la National Science Foundation et la Robina Foundation pour leur financement g&eacute;n&eacute;reux.<\/p>\n<div>\n\t<br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[1]<\/a> Les avocats sp&eacute;cialis&eacute;s en droit des r&eacute;fugi&eacute;s s&rsquo;appuient aussi fr&eacute;quemment sur les articles 15 et 23 de la Directive de qualification de l&rsquo;UE, le premier garantissant une protection contre toute &laquo;atteinte grave&raquo; et le second exigeant des &Eacute;tats membres qu&rsquo;ils veillent &agrave; la pr&eacute;servation de la vie familiale.<\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>On pourrait avancer que le Royaume-Uni conna&icirc;t aujourd&rsquo;hui son &acirc;ge d&rsquo;or en mati&egrave;re de jurisprudence dans le domaine des droits humains pour les r&eacute;fugi&eacute;s. Depuis que la Convention europ&eacute;enne des droits de l&rsquo;homme (CEDH) a &eacute;t&eacute; transpos&eacute;e en droit britannique en 2000 par le biais du Human Rights Act (HRA, la loi britannique relative aux&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[91],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[562],"class_list":["post-41412","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-91","fmr_content_type-article","fmr_languages-french","fmr_list_years-562","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comment un mauvais usage des trait\u00e9s sur les droits humains minimise les chances des demandeurs d\u2019asile - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/meili-2-3\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment un mauvais usage des trait\u00e9s sur les droits humains minimise les chances des demandeurs d\u2019asile - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"On pourrait avancer que le Royaume-Uni conna&icirc;t aujourd&rsquo;hui son &acirc;ge d&rsquo;or en mati&egrave;re de jurisprudence dans le domaine des droits humains pour les r&eacute;fugi&eacute;s. Depuis que la Convention europ&eacute;enne des droits de l&rsquo;homme (CEDH) a &eacute;t&eacute; transpos&eacute;e en droit britannique en 2000 par le biais du Human Rights Act (HRA, la loi britannique relative aux&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/meili-2-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-01T12:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/meili-2-3\/\",\"url\":\"https:\/\/www.fmreview.org\/meili-2-3\/\",\"name\":\"Comment un mauvais usage des trait\u00e9s sur les droits humains minimise les chances des demandeurs d\u2019asile - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2013-05-22T05:00:00+00:00\",\"dateModified\":\"2025-07-01T12:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/meili-2-3\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/meili-2-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/meili-2-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment un mauvais usage des trait\u00e9s sur les droits humains minimise les chances des demandeurs d\u2019asile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment un mauvais usage des trait\u00e9s sur les droits humains minimise les chances des demandeurs d\u2019asile - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/meili-2-3\/","og_locale":"ar_AR","og_type":"article","og_title":"Comment un mauvais usage des trait\u00e9s sur les droits humains minimise les chances des demandeurs d\u2019asile - Forced Migration Review","og_description":"On pourrait avancer que le Royaume-Uni conna&icirc;t aujourd&rsquo;hui son &acirc;ge d&rsquo;or en mati&egrave;re de jurisprudence dans le domaine des droits humains pour les r&eacute;fugi&eacute;s. Depuis que la Convention europ&eacute;enne des droits de l&rsquo;homme (CEDH) a &eacute;t&eacute; transpos&eacute;e en droit britannique en 2000 par le biais du Human Rights Act (HRA, la loi britannique relative aux&hellip;","og_url":"https:\/\/www.fmreview.org\/meili-2-3\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-07-01T12:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/meili-2-3\/","url":"https:\/\/www.fmreview.org\/meili-2-3\/","name":"Comment un mauvais usage des trait\u00e9s sur les droits humains minimise les chances des demandeurs d\u2019asile - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2013-05-22T05:00:00+00:00","dateModified":"2025-07-01T12:03:40+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/meili-2-3\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/meili-2-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/meili-2-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/ar\/"},{"@type":"ListItem","position":2,"name":"Comment un mauvais usage des trait\u00e9s sur les droits humains minimise les chances des demandeurs d\u2019asile"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41412\/revisions"}],"predecessor-version":[{"id":48400,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41412\/revisions\/48400"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/media?parent=41412"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_themes?post=41412"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_region?post=41412"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_issue?post=41412"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_year?post=41412"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content_type?post=41412"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_languages?post=41412"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_list_years?post=41412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}