{"id":41564,"date":"2014-11-18T00:00:00","date_gmt":"2014-11-18T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/holdcroft-2-4\/"},"modified":"2025-04-30T04:22:20","modified_gmt":"2025-04-30T09:22:20","slug":"holdcroft-2-4","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/ar\/foi\/holdcroft-2-4\/","title":{"rendered":"La contribution des organisations confessionnelles qui travaillent avec les d\u00e9plac\u00e9s"},"content":{"rendered":"<p>Au d&eacute;but de 2014, j&rsquo;ai rendu visite &agrave; Mavisela, une Zimbabw&eacute;enne qui vivait dans une modeste cabane &agrave; la p&eacute;riph&eacute;rie d&rsquo;une petite ville en Afrique du Sud<a href=\"#_edn1\" name=\"_ednref1\" title=\"\">[1]<\/a>. Elle &eacute;tait arriv&eacute;e en Afrique du Sud pendant la grande migration venue du Zimbabwe en 2008, elle avait obtenu un permis d&rsquo;asile dans le cadre de la d&eacute;rogation g&eacute;n&eacute;rale en vigueur &agrave; cette &eacute;poque, et depuis elle l&rsquo;avait fait renouveler p&eacute;riodiquement sans que jusqu&rsquo;ici son cas n&rsquo;ait jamais &eacute;t&eacute; r&eacute;solu. C&rsquo;est dans un h&ocirc;pital local que le Service J&eacute;suite des R&eacute;fugi&eacute;s (JRS) a rencontr&eacute; Mavisela pour la premi&egrave;re fois. Elle &eacute;tait &agrave; peine vivante, ne pesait que 25kg et souffrait du VIH et d&rsquo;une forme de tuberculose r&eacute;sistante aux m&eacute;dicaments. Depuis cette p&eacute;riode, l&rsquo;organisation l&rsquo;a aid&eacute;e gr&acirc;ce &agrave; s&eacute;rie d&rsquo;interventions diverses qui petit-&agrave;-petit lui ont permis de retrouver la sant&eacute;, d&rsquo;&eacute;tablir des contacts avec la communaut&eacute; (sud-africaine comme migrante) et de commencer &agrave; retrouver du travail.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>La r&eacute;ponse apport&eacute;e par le Service J&eacute;suite des R&eacute;fugi&eacute;s au cas de Mavisela met en lumi&egrave;re le type de contribution qu&rsquo;apportent les organisations confessionnelles qui travaillent dans cette zone de d&eacute;placement forc&eacute; ainsi que les d&eacute;fis et les &eacute;cueils auxquels elles sont confront&eacute;es. Comme bon nombre de ses compatriotes qui vivent en Afrique du Sud, Mavisela n&rsquo;est probablement pas une r&eacute;fugi&eacute;e &laquo;&nbsp;conventionnelle type&nbsp;&raquo;, ce qui la place en marge du mandat fondamental du HCR. Toutefois, comme la plupart des personnes qui migrent pour survivre, elle s&rsquo;est sentie forc&eacute;e de s&rsquo;installer en Afrique du Sud o&ugrave; elle vit une existence des plus pr&eacute;caires dans une pauvret&eacute; profonde. Le programme du Service J&eacute;suite des R&eacute;fugi&eacute;s avait pour avantage &agrave; la fois d&rsquo;&ecirc;tre libre de toute contrainte li&eacute;e &agrave; des&nbsp; questions de d&eacute;finition, et de compter sur un r&eacute;seau sur place capable de r&eacute;pondre &agrave; ses besoins&nbsp;;&nbsp; par la suite en la connaissant mieux ainsi que ses circonstances, nous avons &eacute;t&eacute; en mesure d&rsquo;organiser d&rsquo;autres interventions diff&eacute;rentes. Avec le temps les priorit&eacute;s ont chang&eacute; et il est devenu capital qu&rsquo;elle puisse forger des liens avec la communaut&eacute; locale, principalement avec les autorit&eacute;s civiles et les &eacute;glises avec lesquelles le Service J&eacute;suite des R&eacute;fugi&eacute;s est en r&eacute;seau. L&rsquo;un dans l&rsquo;autre, c&rsquo;est un processus qui aura pris environ six ans en totalit&eacute;, ce qui n&rsquo;est pas un d&eacute;lai inhabituel pour ce type de travail.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>Je suis d&rsquo;avis qu&rsquo;une organisation confessionnelle est particuli&egrave;rement bien plac&eacute;e pour combler les lacunes qui existent entre les pr&eacute;occupations et les responsabilit&eacute;s fondamentales des gouvernements, qui se concentrent principalement sur leurs propres citoyens, et un syst&egrave;me international de protection&nbsp; relativement balbutiant qui &eacute;prouve des difficult&eacute;s &agrave; &eacute;tablir des liens solides avec les communaut&eacute;s locales. Toutefois, les organisations confessionnelles se voient confront&eacute;es &agrave; des difficult&eacute;s et des risques lorsqu&rsquo;elles tentent de pallier ces lacunes. Elles courent en effet le risque, d&rsquo;une part d&rsquo;&ecirc;tre d&eacute;bord&eacute;es et de perdre de vue leurs objectifs, et d&rsquo;autre part de perdre une partie de leur libert&eacute; et de leur audace lorsqu&rsquo;elles sont confront&eacute;es aux exigences des bailleurs et &agrave; l&rsquo;obligation d&rsquo;obtenir des r&eacute;sultats mesurables. Les organisations confessionnelles sont capables de privil&eacute;gier les aspects les plus positifs qui sont au c&oelig;ur de leurs traditions et de laisser la r&eacute;flexion sur ces traditions &eacute;tablir des connexions et op&eacute;rer une remise en question face &agrave; l&rsquo;&eacute;volution des id&eacute;es en mati&egrave;re de gestion professionnelle, d&rsquo;entreprenariat social et de migration forc&eacute;e. Je ne me fais cependant pas d&rsquo;illusions quant &agrave; la difficult&eacute; et &agrave; la complexit&eacute; d&rsquo;une telle t&acirc;che.<\/p>\n<p>Je ne consid&egrave;re pas non plus la contribution des traditions religieuses au travail avec les personnes d&eacute;plac&eacute;es de force comme limit&eacute;e aux organisations confessionnelles. En effet, les r&eacute;seaux que constituent les mosqu&eacute;es et les &eacute;glises sont souvent le premier point d&rsquo;entr&eacute;e d&rsquo;un r&eacute;fugi&eacute; dans une nouvelle soci&eacute;t&eacute;&nbsp;; c&rsquo;est, de bien des fa&ccedil;ons, la contribution la plus importante des groupes religieux et elle est souvent m&eacute;connue. Bien plus, les arguments que je d&eacute;veloppe peuvent &eacute;galement s&rsquo;appliquer &agrave; des organisations &laquo;&nbsp;la&iuml;ques&nbsp;&raquo; non confessionnelles qui travaillent dans le secteur &ndash; les organisations confessionnelles n&rsquo;ont en aucun cas le monopole de l&rsquo;&eacute;thique. Cela &eacute;tant dit, les grandes religions s&rsquo;appuient toutes sur une sagesse qu&rsquo;il est possible de rapprocher de mani&egrave;re cr&eacute;ative avec l&rsquo;identification des besoins et les tendances actuelles de la r&eacute;flexion sur les programmes, ce qui peut aboutir &agrave; un travail bien cibl&eacute;, rentable et &agrave; fort impact.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<\/p>\n<p>Le concept des droits<\/p>\n<p>L&rsquo;id&eacute;ologie &agrave; travers laquelle l&rsquo;&eacute;glise catholique applique ses convictions aux questions sociales et politiques est connue sous le nom de Doctrine sociale catholique. Il en existe de nombreux aspects, mais l&rsquo;un d&rsquo;entre eux nous concerne particuli&egrave;rement&nbsp;: le concept de la dignit&eacute; intrins&egrave;que de la personne humaine, quelles que soient les circonstances dans lesquelles se trouvent cette personne. Cette dignit&eacute; conf&egrave;re &agrave; tout individu le statut d&rsquo;une personne digne de respect en tout point. Il n&rsquo;est pas difficile de percevoir les liens &eacute;troits qu&rsquo;entretient ce concept avec les valeurs inscrites dans la D&eacute;claration universelles des droits de l&rsquo;homme, ainsi que dans de nombreux autres instruments des droits de l&rsquo;homme. La Doctrine sociale catholique met en exergue deux aspects relatifs &agrave; la nature de la dignit&eacute; humaine et &agrave; l&rsquo;appr&eacute;hension de ce qu&rsquo;est la personne humaine qui j&rsquo;en suis convaincu sont particuli&egrave;rement utiles.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>Le premier de ces deux aspects est que la personne soit consid&eacute;r&eacute;e non seulement comme un individu d&eacute;tenteur de droits mais aussi comme un &ecirc;tre en relation avec d&rsquo;autres &ecirc;tres, et de bien des mani&egrave;res d&eacute;pendant de ces autres personnes pour la r&eacute;alisation de son individualit&eacute;. Ainsi, une personne interagit avec d&rsquo;autres d&rsquo;une multitude de mani&egrave;res, &eacute;conomiquement, socialement, culturellement et politiquement, et trouve son identit&eacute; et son sens principalement par le biais de ces interactions. En cons&eacute;quence, la personne a un droit de contribuer de mani&egrave;re constructive &agrave; une communaut&eacute; de personnes. Il n&rsquo;est donc pas difficile d&rsquo;en d&eacute;duire que le m&eacute;canisme politique le plus d&eacute;terminant pour la r&eacute;alisation de ce droit est la communaut&eacute; politique que nous appelons &Eacute;tat. Lorsque l&rsquo;&Eacute;tat, quelle qu&rsquo;en soit la raison, ne r&eacute;ussit pas &agrave; fournir ad&eacute;quatement cet environnement participatif, la personne a alors le droit, et de fait le devoir, de chercher &agrave; redresser cette situation, si n&eacute;cessaire, par le biais de la migration.<\/p>\n<p>Cette r&eacute;flexion nous interpelle et nous invite &agrave; remettre en question notre mani&egrave;re traditionnelle de penser prestataire\/b&eacute;n&eacute;ficiaire. La fuite des r&eacute;fugi&eacute;s devrait &ecirc;tre davantage consid&eacute;r&eacute;e comme l&rsquo;exercice actif d&rsquo;un droit, ce qui diminue la possibilit&eacute; de consid&eacute;rer la personne d&eacute;plac&eacute;e comme une victime impuissante. Il en d&eacute;coule &eacute;galement que les pays ont le devoir d&rsquo;accueillir les migrants forc&eacute;s et de prendre des mesures actives afin de les int&eacute;grer d&rsquo;une mani&egrave;re ou d&rsquo;une autre dans la soci&eacute;t&eacute;.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>Deuxi&egrave;mement, les agences qui ont leurs racines dans cette tradition disposent de param&egrave;tres plus larges et plus flexibles lorsqu&rsquo;elles se trouvent confront&eacute;es &agrave; des questions de d&eacute;finition &ndash; c&rsquo;est-&agrave;-dire lorsqu&rsquo;il s&rsquo;agit de d&eacute;cider qui devrait faire partie de leur sph&egrave;re de pr&eacute;occupation. Ceci devrait fournir une orientation visant &agrave; obtenir une r&eacute;ponse syst&eacute;matique et &eacute;thiquement coh&eacute;rente face aux r&eacute;fugi&eacute;s, migrants de survie, migrants de crise, personnes d&eacute;plac&eacute;es &agrave; l&rsquo;int&eacute;rieur de leur propre pays et autres groupes qu&rsquo;englobe le terme g&eacute;n&eacute;rique de &laquo;&nbsp;d&eacute;plac&eacute;s&nbsp;&raquo;. Cette flexibilit&eacute; accrue s&rsquo;&eacute;tend &agrave; la nature des programmes que les agences con&ccedil;oivent, modifiant ainsi leur pr&eacute;occupation qui n&rsquo;est plus uniquement centr&eacute;e sur les r&eacute;fugi&eacute;s eux-m&ecirc;mes mais sur l&rsquo;appui qui doit &ecirc;tre apport&eacute; &agrave; la soci&eacute;t&eacute; d&rsquo;accueil pour lui donner les moyens d&rsquo;aider les r&eacute;fugi&eacute;s &agrave; contribuer constructivement &agrave; cette soci&eacute;t&eacute;. Cela, &agrave; son tour, permet aux organisations confessionnelles de mettre en place des projets qui impliquent la participation &agrave; la fois des membres de la soci&eacute;t&eacute; d&rsquo;accueil et des r&eacute;fugi&eacute;s, plut&ocirc;t que de cibler uniquement les r&eacute;fugi&eacute;s en risquant de provoquer une r&eacute;action x&eacute;nophobe de la population h&ocirc;te.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>C&rsquo;est cette vision plus sociale de la personne humaine et de ses droits qui, &agrave; la fois interpelle les organisations confessionnelles et conf&egrave;re un bien-fond&eacute; permanent &agrave; leur activit&eacute; dans ce secteur. Elle touche du doigt une incoh&eacute;rence logique dans le discours sur les droits de l&rsquo;homme et dans la r&eacute;ponse politique que les gouvernements apportent aux migrants forc&eacute;s qui tentent de p&eacute;n&eacute;trer sur leur territoire. Le concept d&rsquo;&Eacute;tat s&eacute;culier est n&eacute; aux lendemains des guerres de religion europ&eacute;ennes en vertu d&rsquo;un compromis au nom duquel la religion serait autoris&eacute;e &agrave; poursuivre ses activit&eacute;s, dans une sph&egrave;re plus priv&eacute;e, alors qu&rsquo;en contrepartie les pouvoirs s&eacute;culiers se chargeraient d&rsquo;assurer la s&eacute;curit&eacute; physique des populations vivant &agrave; l&rsquo;int&eacute;rieur des fronti&egrave;res de l&rsquo;&Eacute;tat. &Agrave; mesure que le r&ocirc;le de l&rsquo;&Eacute;tat s&rsquo;est d&eacute;velopp&eacute;, s&rsquo;est &eacute;galement d&eacute;velopp&eacute;e la responsabilit&eacute; des gouvernements de privil&eacute;gier les droits de leurs propres citoyens par rapport &agrave; ceux des autres. L&rsquo;existence du migrant forc&eacute;, qui se pr&eacute;vaut d&rsquo;une cat&eacute;gorie de droits de l&rsquo;homme plus universels, s&rsquo;accommode mal de ce compromis politique. Au cours de notre histoire r&eacute;cente, nous voyons les gouvernements de tous les bords politiques &eacute;prouver des difficult&eacute;s fondamentales dans leur r&eacute;ponse face &agrave; la migration forc&eacute;e dans la mesure o&ugrave; une r&eacute;ponse v&eacute;ritablement et uniquement fond&eacute;e sur des principes n&rsquo;est pas rentable politiquement.&nbsp; Il n&rsquo;y a d&rsquo;exception que si les gouvernements r&eacute;ussissent, et c&rsquo;est difficile, &agrave; d&eacute;montrer publiquement que l&rsquo;immigration comporte des b&eacute;n&eacute;fices qui avantagent la population locale et que ceux-ci d&eacute;passent les aspects n&eacute;gatifs qui accompagnent l&rsquo;acceptation d&rsquo;un groupe d&rsquo;&eacute;trangers &agrave; l&rsquo;int&eacute;rieur des fronti&egrave;res.<\/p>\n<p>Alors que le d&eacute;veloppement d&rsquo;un syst&egrave;me international de protection en est encore &agrave; ses d&eacute;buts et qu&rsquo;il reste soumis aux int&eacute;r&ecirc;ts (et au financement) des &Eacute;tats membres, les organisations confessionnelles occupent, en vertu de leur libert&eacute; op&eacute;rationnelle et de la compr&eacute;hension de la personne humaine que leur accorde leurs traditions, une position id&eacute;ale pour combler cette lacune. Elles sont en position d&rsquo;accomplir ce que les gouvernements veulent voir accompli mais qu&rsquo;ils ne veulent pas n&eacute;cessairement &ecirc;tre vus en train d&rsquo;accomplir. Il ne s&rsquo;agit pas d&rsquo;exon&eacute;rer les gouvernements de leur responsabilit&eacute; d&rsquo;instaurer un r&eacute;gime universel des droits de l&rsquo;homme. Il ne s&rsquo;agit pas non plus de dire que cet aspect du r&ocirc;le des organisations confessionnelles est simple ou &eacute;vident. Les organisations confessionnelles doivent maintenir une double ligne de responsabilit&eacute; et doivent rendre des comptes par rapport &agrave; des normes en mati&egrave;re de prestation de services et &agrave; des lois et r&egrave;glements locaux tout en continuant d&rsquo;exercer cette libert&eacute; que la responsabilit&eacute; envers leurs propres traditions spirituelles exige d&rsquo;elles.<\/p>\n<p>On peut concevoir que la contribution la plus importante des communaut&eacute;s religieuses ne r&eacute;side pas n&eacute;cessairement dans leurs propres organisations mais plut&ocirc;t dans les r&eacute;seaux d&eacute;j&agrave; mentionn&eacute;s et dans la capacit&eacute; que ceux-ci ont de permettre aux personnes en d&eacute;placement d&rsquo;&eacute;tablir des contacts et de trouver un accueil et une hospitalit&eacute; dans un environnement par ailleurs potentiellement hostile.&nbsp; L&rsquo;exp&eacute;rience a montr&eacute; &eacute;galement que c&rsquo;est la nature globale de ces r&eacute;seaux qui, lorsqu&rsquo;ils sont activ&eacute;s peut r&eacute;ellement changer les choses dans les premi&egrave;res quarante-huit heures tellement cruciales qui suivent une situation d&rsquo;urgence.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>Il s&rsquo;ensuit que les entit&eacute;s transnationales feraient bien de reconna&icirc;tre la singularit&eacute; de la contribution apport&eacute;e par les organisations confessionnelles et qu&rsquo;elles devraient apprendre &agrave; mieux collaborer avec elles. Le secteur a le plus grand besoin d&rsquo;une coop&eacute;ration &eacute;largie et d&rsquo;une utilisation optimale des points forts qui surgissent de la diff&eacute;rence de tous ces groupes vari&eacute;s qui offrent leurs services. Parall&egrave;lement, les organisations confessionnelles feraient bien de se d&eacute;barrasser des craintes qu&rsquo;elles ont &agrave; l&rsquo;id&eacute;e de travailler avec des autorit&eacute;s civiles et transnationales. Si elles y parviennent, elles continueront &agrave; jouer un r&ocirc;le vital en comblant l&rsquo;&eacute;cart cr&eacute;&eacute; en toute logique par les politiques en mati&egrave;re de droits de l&rsquo;homme, tout en maintenant un niveau ad&eacute;quat de responsabilit&eacute; envers les autorit&eacute;s civiles et envers les orientations qu&rsquo;elles se fixent &agrave; la lumi&egrave;re de leurs traditions spirituelles .&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fr&egrave;re David Holdcroft &nbsp;SJ <em><a href=\"mailto:southernafrica.director@jrs.net\">southernafrica.director@jrs.net<\/a><\/em> est Directeur r&eacute;gional, r&eacute;gion Afrique Australe, Service J&eacute;suite des R&eacute;fugi&eacute;s (JRS). <em><a href=\"http:\/\/www.jrssaf.org\">www.jrssaf.org<\/a><\/em> ou <em><a href=\"http:\/\/www.jrs.net\">www.jrs.net<\/a><\/em>&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<div>\n\t<br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[1]<\/a> Il ne s&rsquo;agit pas de son v&eacute;ritable nom.<\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au d&eacute;but de 2014, j&rsquo;ai rendu visite &agrave; Mavisela, une Zimbabw&eacute;enne qui vivait dans une modeste cabane &agrave; la p&eacute;riph&eacute;rie d&rsquo;une petite ville en Afrique du Sud[1]. Elle &eacute;tait arriv&eacute;e en Afrique du Sud pendant la grande migration venue du Zimbabwe en 2008, elle avait obtenu un permis d&rsquo;asile dans le cadre de la d&eacute;rogation&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":46519,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[96],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[563],"class_list":["post-41564","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-96","fmr_content_type-article","fmr_languages-french","fmr_list_years-563","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La contribution des organisations confessionnelles qui travaillent avec les d\u00e9plac\u00e9s - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La contribution des organisations confessionnelles qui travaillent avec les d\u00e9plac\u00e9s - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"Au d&eacute;but de 2014, j&rsquo;ai rendu visite &agrave; Mavisela, une Zimbabw&eacute;enne qui vivait dans une modeste cabane &agrave; la p&eacute;riph&eacute;rie d&rsquo;une petite ville en Afrique du Sud[1]. Elle &eacute;tait arriv&eacute;e en Afrique du Sud pendant la grande migration venue du Zimbabwe en 2008, elle avait obtenu un permis d&rsquo;asile dans le cadre de la d&eacute;rogation&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-30T09:22:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/\",\"url\":\"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/\",\"name\":\"La contribution des organisations confessionnelles qui travaillent avec les d\u00e9plac\u00e9s - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2014-11-18T05:00:00+00:00\",\"dateModified\":\"2025-04-30T09:22:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RMF 48 &#8211; La foi et les r\u00e9ponses au d\u00e9placement\",\"item\":\"https:\/\/www.fmreview.org\/foi\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La contribution des organisations confessionnelles qui travaillent avec les d\u00e9plac\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La contribution des organisations confessionnelles qui travaillent avec les d\u00e9plac\u00e9s - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/","og_locale":"ar_AR","og_type":"article","og_title":"La contribution des organisations confessionnelles qui travaillent avec les d\u00e9plac\u00e9s - Forced Migration Review","og_description":"Au d&eacute;but de 2014, j&rsquo;ai rendu visite &agrave; Mavisela, une Zimbabw&eacute;enne qui vivait dans une modeste cabane &agrave; la p&eacute;riph&eacute;rie d&rsquo;une petite ville en Afrique du Sud[1]. Elle &eacute;tait arriv&eacute;e en Afrique du Sud pendant la grande migration venue du Zimbabwe en 2008, elle avait obtenu un permis d&rsquo;asile dans le cadre de la d&eacute;rogation&hellip;","og_url":"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-04-30T09:22:20+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/","url":"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/","name":"La contribution des organisations confessionnelles qui travaillent avec les d\u00e9plac\u00e9s - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2014-11-18T05:00:00+00:00","dateModified":"2025-04-30T09:22:20+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/foi\/holdcroft-2-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/ar\/"},{"@type":"ListItem","position":2,"name":"RMF 48 &#8211; La foi et les r\u00e9ponses au d\u00e9placement","item":"https:\/\/www.fmreview.org\/foi\/"},{"@type":"ListItem","position":3,"name":"La contribution des organisations confessionnelles qui travaillent avec les d\u00e9plac\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41564\/revisions"}],"predecessor-version":[{"id":46627,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41564\/revisions\/46627"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/46519"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/media?parent=41564"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_themes?post=41564"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_region?post=41564"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_issue?post=41564"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_year?post=41564"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content_type?post=41564"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_languages?post=41564"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_list_years?post=41564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}