{"id":41565,"date":"2014-11-18T00:00:00","date_gmt":"2014-11-18T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/ager-2-3\/"},"modified":"2025-04-30T04:22:19","modified_gmt":"2025-04-30T09:22:19","slug":"ager-2-3","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/ar\/foi\/ager-2-3\/","title":{"rendered":"Foi et la\u00efcit\u00e9 : les tensions dans la r\u00e9alisation des principes humanitaires"},"content":{"rendered":"<p>Les organisations confessionnelles et les communaut&eacute;s religieuses locales repr&eacute;sentent une proportion importante de la capacit&eacute; de la soci&eacute;t&eacute; civile dans de nombreux contextes sujets aux crises humanitaires. Un engagement renforc&eacute; aupr&egrave;s de ces groupes est donc un &eacute;l&eacute;ment appropri&eacute; de la panoplie des strat&eacute;gies destin&eacute;es &agrave; renforcer les capacit&eacute;s locales en cas de crise, qu&rsquo;il s&rsquo;agisse de pr&eacute;paration, d&rsquo;att&eacute;nuation ou d&rsquo;intervention. Une &eacute;tude multi-agences r&eacute;alis&eacute;e r&eacute;cemment sur le r&ocirc;le des communaut&eacute;s religieuses locales dans les contextes humanitaires a mis en &eacute;vidence de nombreux &eacute;l&eacute;ments d&eacute;montrant leur contribution dans le cadre de la r&eacute;duction des risques de catastrophe, des interventions d&rsquo;urgence ainsi que leur capacit&eacute; &agrave; faciliter des solutions transitoires comme durables<a href=\"#_edn1\" name=\"_ednref1\" title=\"\">[1]<\/a>. De nombreux rapports couverts par cette &eacute;tude citaient les communaut&eacute;s religieuses locales comme particuli&egrave;rement bien plac&eacute;es pour r&eacute;pondre dans les tous premiers jours qui suivent une situation d&rsquo;urgence, lorsque la capacit&eacute; &agrave; trouver des abris ou &agrave; d&eacute;ployer des b&eacute;n&eacute;voles pour aider les populations d&eacute;plac&eacute;es en d&eacute;tresse peut s&rsquo;av&eacute;rer cruciale. Il est &eacute;galement de plus en plus largement admis que les communaut&eacute;s religieuses locales gr&acirc;ce &agrave; leurs convictions et leurs rites constituent une base solide pour renforcer la r&eacute;silience d&rsquo;une communaut&eacute; aux lendemains imm&eacute;diats d&rsquo;une crise.&nbsp;&nbsp;<\/p>\n<p>Ces &eacute;l&eacute;ments sont g&eacute;n&eacute;ralement interpr&eacute;t&eacute;s par rapport &agrave; la valeur instrumentale des ressources confessionnelles dans le cadre d&rsquo;un programme humanitaire pr&eacute;existant qui est habituellement articul&eacute; dans un langage sp&eacute;cifiquement la&iuml;que. Dans ces termes, il est possible que l&rsquo;implication aupr&egrave;s des communaut&eacute;s religieuses locales soit consid&eacute;r&eacute;e comme justifi&eacute;e &agrave; cause des ressources qu&rsquo;elles mettent &agrave; disposition de l&rsquo;effort humanitaire en s&eacute;parant de la sph&egrave;re humanitaire les autres activit&eacute;s et valeurs per&ccedil;ues comme potentiellement contraires aux principes humanitaires. Pour certains humanitaires, les risques d&rsquo;une implication de ce type continuent d&rsquo;exc&eacute;der largement les avantages instrumentaux potentiels. Ainsi, les changements r&eacute;cents entrepris par le HCR en vue d&rsquo;une collaboration plus cons&eacute;quente avec le secteur confessionnel insistent tout particuli&egrave;rement sur l&rsquo;&eacute;tablissement d&rsquo;un &laquo;&nbsp;code de conduite&nbsp;&raquo; &agrave; l&rsquo;intention des partenaires confessionnels<a href=\"#_edn2\" name=\"_ednref2\" title=\"\">[2]<\/a> qui proscrit les activit&eacute;s &ndash; comme le pros&eacute;lytisme &ndash; consid&eacute;r&eacute;es comme incompatibles avec un engagement humanitaire.<\/p>\n<p>Une telle prudence est compr&eacute;hensible si une approche la&iuml;que est consid&eacute;r&eacute;e comme la garantie permettant de prot&eacute;ger les principes humanitaires. Toutefois, certains d&eacute;veloppements viennent remettre en question cette position. Peter Walker a montr&eacute; comment devrait &eacute;voluer la compr&eacute;hension en vigueur des principes humanitaires afin de traduire l&rsquo;impact de la mondialisation<a href=\"#_edn3\" name=\"_ednref3\" title=\"\">[3]<\/a>. Les secteurs des relations internationales et des sciences politiques tout comme celui de la sociologie en sont tous venus &agrave; abandonner le pr&eacute;suppos&eacute; selon lequel la la&iuml;cit&eacute; gagnerait du terrain avec le d&eacute;veloppement, et ont commenc&eacute; &agrave; s&rsquo;int&eacute;resser &agrave; l&rsquo;av&egrave;nement potentiel d&rsquo;une &laquo;&nbsp;&eacute;poque post-la&iuml;que&nbsp;&raquo;. Il est de plus en plus accept&eacute; qu&rsquo;il n&rsquo;est pas possible de confiner pragmatiquement ou l&eacute;gitimement le monde de la foi &agrave; la sph&egrave;re priv&eacute;e et de continuer &agrave; le maintenir en marge de la sph&egrave;re publique. Il est, en outre, de plus en plus fr&eacute;quemment reconnu que le cadre la&iuml;c refl&egrave;te une id&eacute;ologie occidentale adoss&eacute;e &agrave; une tradition jud&eacute;o-chr&eacute;tienne bien &eacute;loign&eacute;e d&rsquo;une perspective &laquo;&nbsp;neutre&nbsp;&raquo;. La politisation et la militarisation de l&rsquo;aide ont &agrave; juste titre &eacute;t&eacute; consid&eacute;r&eacute;es comme le moteur principal de cette &eacute;rosion de l&rsquo;espace humanitaire, mais une prise de conscience accrue rend &eacute;galement compte du fait que le cadre la&iuml;c dans lequel fonctionne l&rsquo;id&eacute;ologie humanitaire refl&egrave;te des valeurs occidentales n&eacute;olib&eacute;rales qui contribuent &eacute;galement &agrave; cette pression.<\/p>\n<p>Tout cela signale &agrave; quel point s&rsquo;engager aupr&egrave;s des communaut&eacute;s religieuses peut &ecirc;tre complexe. Il est amplement d&eacute;montr&eacute; que les communaut&eacute;s sont tout &agrave; fait capables d&rsquo;apprendre un discours la&iuml;c en vue de faciliter leur travail avec les acteurs humanitaires internationaux. Cela renvoie exactement &agrave; la mani&egrave;re dont les organisations confessionnelles internationales donnent forme &agrave; leur travail en le rendant indiscernable de celui effectu&eacute; par les organisations la&iuml;ques. Cette strat&eacute;gie continuera de sembler pr&eacute;f&eacute;rable &agrave; certains. Mais se conformer strictement &agrave; un discours la&iuml;c comporte pour les acteurs humanitaires deux difficult&eacute;s majeures&nbsp;; premi&egrave;rement, il convient de reconna&icirc;tre que ce sc&eacute;nario la&iuml;c donne &agrave; l&rsquo;assistance humanitaire une forme qui est enti&egrave;rement &eacute;trang&egrave;re &agrave; de nombreuses communaut&eacute;s religieuses locales et qui les coupe de ressources locales importantes particuli&egrave;rement utiles pour les aider &agrave; se r&eacute;tablir apr&egrave;s une crise&nbsp;; et deuxi&egrave;mement, il faut &eacute;galement reconna&icirc;tre que le silence en mati&egrave;re de religion n&rsquo;est pas un signe de neutralit&eacute; et qu&rsquo;il refl&egrave;te bien une id&eacute;ologie particuli&egrave;re.<\/p>\n<p>Le Dialogue de 2012 du HCR sur le th&egrave;me <em>Foi et protection<\/em> s&rsquo;est fait l&rsquo;&eacute;cho de cette sensibilit&eacute; face &agrave; ces deux difficult&eacute;s, et en encourageant un meilleur niveau de connaissance religieuse chez les travailleurs humanitaires, a pris un pas important vers leur r&eacute;solution. La recherche de l&rsquo;impartialit&eacute;, de l&rsquo;ind&eacute;pendance et de la neutralit&eacute; doit rester au centre du programme humanitaire. Engager le dialogue sur des questions de foi n&rsquo;implique pas d&rsquo;abandonner ces principes mais signifie reconna&icirc;tre que dans un contexte de pluralisme nous devons apprendre &agrave; fonctionner en sachant que les convictions religieuses comme la&iuml;ques ne repr&eacute;sentent qu&rsquo; &laquo;&nbsp;une possibilit&eacute; humaine parmi d&rsquo;autres&nbsp;&raquo;<a href=\"#_edn4\" name=\"_ednref4\" title=\"\">[4]<\/a>. N&eacute;gocier l&rsquo;action et le partenariat humanitaires dans cette &eacute;poque post-la&iuml;que comportera des difficult&eacute;s. N&eacute;anmoins, &laquo;&nbsp;la compr&eacute;hension commune&nbsp;&raquo; proclam&eacute;e par les acteurs la&iuml;ques et religieux dans la formulation de la D&eacute;claration universelle des droits de l&rsquo;homme constitue un pr&eacute;c&eacute;dent historique fondamental afin de trouver une voie dans ce d&eacute;bat.<\/p>\n<p>Notre exp&eacute;rience du travail des communaut&eacute;s religieuses locales qui apportent une assistance humanitaire aux r&eacute;fugi&eacute;s syriens en Jordanie, nous am&egrave;ne &agrave; sugg&eacute;rer aux agences humanitaires quelques mesures tr&egrave;s concr&egrave;tes en vue d&rsquo;&eacute;tablir des partenariats plus performants avec les groupes religieux. Parmi celles-ci&nbsp;: s&rsquo;engager &agrave; cartographier l&rsquo;ampleur et la diversit&eacute; de l&rsquo;implication des acteurs confessionnels dans le cadre de la r&eacute;ponse humanitaire&nbsp;; faire preuve de respect face &agrave; cet engagement et le d&eacute;montrer &ndash; faire preuve &eacute;galement d&rsquo;une compr&eacute;hension m&ucirc;re et r&eacute;fl&eacute;chie des principes humanitaires d&rsquo;impartialit&eacute; et de neutralit&eacute; &ndash; par le biais d&rsquo;une pr&eacute;sence physique aupr&egrave;s de divers acteurs religieux&nbsp;; reconna&icirc;tre les pr&eacute;occupations religieuses et spirituelles de ces groupes comme une part int&eacute;grante de leur identit&eacute;, et les traiter comme des partenaires disposant de connaissances locales pr&eacute;cieuses plut&ocirc;t que comme des sous-traitants charg&eacute;s de mettre en &oelig;uvre un intervention pr&eacute;alablement d&eacute;termin&eacute;e.<\/p>\n<p>&nbsp;<\/p>\n<p>Alastair Ager <a href=\"mailto:aa2468@columbia.edu\"><em>aa2468@columbia.edu<\/em><\/a> est Professeur sp&eacute;cialis&eacute; en Population et sant&eacute; familiale au sein du Programme Migration forc&eacute;e et sant&eacute; de l&rsquo;universit&eacute; de Columbia. <a href=\"http:\/\/www.forcedmigration.columbia.edu\"><em>www.forcedmigration.columbia.edu<\/em><\/a><\/p>\n<p>Pour plus de d&eacute;tails, voir Ager A et Ager J (2015)<em> Faith, Secularism and Humanitarian Engagement. <\/em>Palgrave. <a href=\"http:\/\/tinyurl.com\/jliflc-ager-ager-2015\">http:\/\/tinyurl.com\/jliflc-ager-ager-2015<\/a><\/p>\n<div>\n\t<br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[1]<\/a> Fiddian-Qasmiyeh E et Ager A (eds) &lsquo;Local faith communities and the promotion of resilience in humanitarian situations: a scoping study&rsquo;, Joint JLI-RSC <em>Working Paper<\/em>, Oxford, 2013.<\/p>\n<p><a href=\"http:\/\/tinyurl.com\/RSC-JLI-FQasmiyeh-Ager-2013\">http:\/\/tinyurl.com\/RSC-JLI-FQasmiyeh-Ager-2013<\/a><\/p>\n<\/p><\/div>\n<div id=\"edn2\">\n<p><a href=\"#_ednref2\" name=\"_edn2\" title=\"\">[2]<\/a> UNHCR (2012) <em>Accueillir l&rsquo;&eacute;tranger: Affirmations des chefs religieux,<\/em> Gen&egrave;ve: UNHCR (document multilingue). <a href=\"http:\/\/www.unhcr.org\/51b6de419.html\">www.unhcr.org\/51b6de419.html<\/a><\/p>\n<\/p><\/div>\n<div id=\"edn3\">\n<p><a href=\"#_ednref3\" name=\"_edn3\" title=\"\">[3]<\/a> Walker P et Maxwell D (2009) <em>Shaping the Humanitarian World.<\/em> New York: Routledge.<\/p>\n<p><a href=\"http:\/\/tinyurl.com\/Walker-Maxwell-2009\">http:\/\/tinyurl.com\/Walker-Maxwell-2009<\/a><\/p>\n<\/p><\/div>\n<div id=\"edn4\">\n<p><a href=\"#_ednref4\" name=\"_edn4\" title=\"\">[4]<\/a> Taylor C (2007) <em>A Secular Age<\/em>. Harvard: Cambridge<\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les organisations confessionnelles et les communaut&eacute;s religieuses locales repr&eacute;sentent une proportion importante de la capacit&eacute; de la soci&eacute;t&eacute; civile dans de nombreux contextes sujets aux crises humanitaires. Un engagement renforc&eacute; aupr&egrave;s de ces groupes est donc un &eacute;l&eacute;ment appropri&eacute; de la panoplie des strat&eacute;gies destin&eacute;es &agrave; renforcer les capacit&eacute;s locales en cas de crise, qu&rsquo;il&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":46519,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[96],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[563],"class_list":["post-41565","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-96","fmr_content_type-article","fmr_languages-french","fmr_list_years-563","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Foi et la\u00efcit\u00e9 : les tensions dans la r\u00e9alisation des principes humanitaires - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/foi\/ager-2-3\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foi et la\u00efcit\u00e9 : les tensions dans la r\u00e9alisation des principes humanitaires - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"Les organisations confessionnelles et les communaut&eacute;s religieuses locales repr&eacute;sentent une proportion importante de la capacit&eacute; de la soci&eacute;t&eacute; civile dans de nombreux contextes sujets aux crises humanitaires. Un engagement renforc&eacute; aupr&egrave;s de ces groupes est donc un &eacute;l&eacute;ment appropri&eacute; de la panoplie des strat&eacute;gies destin&eacute;es &agrave; renforcer les capacit&eacute;s locales en cas de crise, qu&rsquo;il&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/foi\/ager-2-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-30T09:22:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/foi\/ager-2-3\/\",\"url\":\"https:\/\/www.fmreview.org\/foi\/ager-2-3\/\",\"name\":\"Foi et la\u00efcit\u00e9 : les tensions dans la r\u00e9alisation des principes humanitaires - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2014-11-18T05:00:00+00:00\",\"dateModified\":\"2025-04-30T09:22:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/foi\/ager-2-3\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/foi\/ager-2-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/foi\/ager-2-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RMF 48 &#8211; La foi et les r\u00e9ponses au d\u00e9placement\",\"item\":\"https:\/\/www.fmreview.org\/foi\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Foi et la\u00efcit\u00e9 : les tensions dans la r\u00e9alisation des principes humanitaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foi et la\u00efcit\u00e9 : les tensions dans la r\u00e9alisation des principes humanitaires - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/foi\/ager-2-3\/","og_locale":"ar_AR","og_type":"article","og_title":"Foi et la\u00efcit\u00e9 : les tensions dans la r\u00e9alisation des principes humanitaires - Forced Migration Review","og_description":"Les organisations confessionnelles et les communaut&eacute;s religieuses locales repr&eacute;sentent une proportion importante de la capacit&eacute; de la soci&eacute;t&eacute; civile dans de nombreux contextes sujets aux crises humanitaires. Un engagement renforc&eacute; aupr&egrave;s de ces groupes est donc un &eacute;l&eacute;ment appropri&eacute; de la panoplie des strat&eacute;gies destin&eacute;es &agrave; renforcer les capacit&eacute;s locales en cas de crise, qu&rsquo;il&hellip;","og_url":"https:\/\/www.fmreview.org\/foi\/ager-2-3\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-04-30T09:22:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/foi\/ager-2-3\/","url":"https:\/\/www.fmreview.org\/foi\/ager-2-3\/","name":"Foi et la\u00efcit\u00e9 : les tensions dans la r\u00e9alisation des principes humanitaires - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2014-11-18T05:00:00+00:00","dateModified":"2025-04-30T09:22:19+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/foi\/ager-2-3\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/foi\/ager-2-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/foi\/ager-2-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/ar\/"},{"@type":"ListItem","position":2,"name":"RMF 48 &#8211; La foi et les r\u00e9ponses au d\u00e9placement","item":"https:\/\/www.fmreview.org\/foi\/"},{"@type":"ListItem","position":3,"name":"Foi et la\u00efcit\u00e9 : les tensions dans la r\u00e9alisation des principes humanitaires"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41565\/revisions"}],"predecessor-version":[{"id":46620,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41565\/revisions\/46620"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/46519"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/media?parent=41565"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_themes?post=41565"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_region?post=41565"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_issue?post=41565"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_year?post=41565"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content_type?post=41565"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_languages?post=41565"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_list_years?post=41565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}