{"id":41698,"date":"2015-12-15T00:00:00","date_gmt":"2015-12-15T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/karakayali-kleist-2-3\/"},"modified":"2025-04-01T07:27:41","modified_gmt":"2025-04-01T12:27:41","slug":"karakayali-kleist-2-3","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/ar\/destination-europe-fr\/karakayali-kleist-2-3\/","title":{"rendered":"B\u00e9n\u00e9voles et demandeurs d\u2019asile"},"content":{"rendered":"<p>Les structures d&rsquo;accueil et de traitement des demandes, particuli&egrave;rement dans les pays de premi&egrave;re arriv&eacute;e se sont souvent trouv&eacute; d&eacute;bord&eacute;es face &agrave; l&rsquo;augmentation croissante du nombre des demandeurs d&rsquo;asile qui sont arriv&eacute;s sur les c&ocirc;tes de l&rsquo;Europe au cours des derni&egrave;res ann&eacute;es. Les demandeurs d&rsquo;asile ont &eacute;t&eacute; confront&eacute;s &agrave; une p&eacute;nurie d&rsquo;infrastructure d&rsquo;accueil et d&rsquo;int&eacute;gration, ce qui dans de nombreux cas a entrain&eacute; une migration secondaire. Pendant de nombreuses ann&eacute;es, dans les rues d&rsquo;Ath&egrave;nes, sur l&rsquo;ile de Lampedusa et en Sicile, dans la gare de Milan et dans la &laquo;&nbsp;jungle&nbsp;&raquo; de Calais, les arrivants ont souvent d&ucirc; prendre eux-m&ecirc;mes les choses en mains.<\/p>\n<p>Cette situation &eacute;tait per&ccedil;ue tant au plan public que politique comme un &eacute;chec des politiques d&rsquo;immigration des pays concern&eacute;s, du r&eacute;gime d&rsquo;asile europ&eacute;en commun et de l&rsquo;accord de Dublin. Bruxelles, Strasbourg et de nombreuses autres capitales se concentraient non pas sur les situations telles qu&rsquo;elles se pr&eacute;sentaient localement mais sur les r&egrave;glements et les principes n&eacute;cessaires en vue de r&eacute;tablir un r&eacute;gime d&rsquo;asile ordonn&eacute; soit en for&ccedil;ant certains pays &agrave; se conformer aux normes existantes, soit en cr&eacute;ant un nouveau syst&egrave;me.<\/p>\n<p>Pendant ce temps, les populations locales en Sicile ont aid&eacute; le mouvement en avant en procurant des adresses, en payant des billets de train ou m&ecirc;me en offrant un trajet gratuit aux demandeurs d&rsquo;asile. Dans certains centres de transit importants comme Milan Ath&egrave;nes et Calais, des b&eacute;n&eacute;voles ont apport&eacute; un soutien sous forme de distribution de v&ecirc;tements et de nourriture, et ont offert des conseils juridiques et une assistance m&eacute;dicale.<\/p>\n<p>Ces manifestations d&rsquo;engagement de la part des b&eacute;n&eacute;voles, ressortissants et non ressortissants des pays concern&eacute;s, ont eu lieu dans l&rsquo;ombre&nbsp;; les b&eacute;n&eacute;ficiaires &eacute;taient apr&egrave;s tout, et de mani&egrave;re assez g&eacute;n&eacute;rale, consid&eacute;r&eacute;s comme des migrants clandestins. Cependant, de plus en plus fr&eacute;quemment des r&eacute;sidents locaux qui constataient le d&eacute;sespoir et les besoins des demandeurs d&rsquo;asile se trouvant au sein de leurs communaut&eacute;s se joignaient aux activistes traditionnels. C&rsquo;est ce qui s&rsquo;est pass&eacute; tout particuli&egrave;rement lorsque les demandeurs d&rsquo;asile et les r&eacute;fugi&eacute;s ont &eacute;t&eacute; envoy&eacute;s dans des villes qui n&rsquo;en avaient pas encore re&ccedil;u jusque-l&agrave; et qui hormis la disponibilit&eacute; de logements n&rsquo;avaient qu&rsquo;une infrastructure et des ressources limit&eacute;es. Les r&eacute;sidents venaient pour apporter des produits de premi&egrave;re n&eacute;cessit&eacute; mais aussi pour conna&icirc;tre les nouveaux arrivants. Les b&eacute;n&eacute;voles devenaient ainsi et comme par inadvertance une force d&rsquo;int&eacute;gration.<\/p>\n<p>Se charger des responsabilit&eacute;s de l&rsquo;&Eacute;tat<\/p>\n<p>L&rsquo;engagement des r&eacute;sidents dans leurs quartiers aupr&egrave;s des demandeurs d&rsquo;asile est devenu un ph&eacute;nom&egrave;ne g&eacute;n&eacute;ralis&eacute; &agrave; travers toute l&rsquo;Allemagne, &agrave; mesure que l&rsquo;arriv&eacute;e de demandeurs d&rsquo;asile de plus en plus nombreux impliquait qu&rsquo;il fallait trouver des h&eacute;bergements dans des endroits inhabituels, parfois isol&eacute;s.<\/p>\n<p>Les organisations &eacute;tablies qui travaillent avec les r&eacute;fugi&eacute;s en Allemagne ont estim&eacute; &agrave; environ 70&nbsp;% en moyenne le regain d&rsquo;int&eacute;r&ecirc;t pour le b&eacute;n&eacute;volat cibl&eacute;s sur les r&eacute;fugi&eacute;s sur la p&eacute;riode des trois derni&egrave;res ann&eacute;es, et plus d&rsquo;un tiers des b&eacute;n&eacute;voles menaient leurs activit&eacute;s au sein de groupes et d&rsquo;initiatives autonomes plut&ocirc;t que par l&rsquo;interm&eacute;diaire des ONG d&eacute;j&agrave; &eacute;tablies.<a href=\"#_edn1\" name=\"_ednref1\" title=\"\">[1]<\/a> Il s&rsquo;agit d&rsquo;un b&eacute;n&eacute;volat qui n&rsquo;est comparable &agrave; aucun autre. Les b&eacute;n&eacute;voles actifs aupr&egrave;s des r&eacute;fugi&eacute;s sont, selon ce que montre notre &eacute;tude, principalement des femmes, dans la vingtaine ou de plus de soixante ans et qui dans une proportion plus &eacute;lev&eacute;e que celle du reste de la soci&eacute;t&eacute; sont issues de l&rsquo;immigration et de milieux la&iuml;ques. L&rsquo;engagement de ces personnes n&rsquo;est pas intrins&egrave;quement li&eacute; au b&eacute;n&eacute;volat mais plus sp&eacute;cifiquement au fait d&rsquo;apporter de l&rsquo;aide &agrave; des r&eacute;fugi&eacute;s. Ce que nous avons pu documenter &agrave; travers notre &eacute;tude est l&rsquo;instauration d&rsquo;un mouvement g&eacute;n&eacute;ralis&eacute; de b&eacute;n&eacute;volat &agrave; travers l&rsquo;ensemble de la soci&eacute;t&eacute; en faveur des r&eacute;fugi&eacute;s.<\/p>\n<p>Pendant l&rsquo;&eacute;t&eacute; 2015, des milliers de personnes dans les villes allemandes se sont rassembl&eacute;es pour aider les demandeurs d&rsquo;asile alors que les bureaucraties en &eacute;chec ne parvenaient pas &agrave; enregistrer, loger et nourrir les nouveaux arrivants. Par le pass&eacute;, les principales t&acirc;ches des b&eacute;n&eacute;voles avaient consist&eacute; &agrave; faciliter les visites et les communications avec les autorit&eacute;s, &agrave; traduire et &agrave; donner des cours de langue ainsi qu&rsquo;&agrave; des activit&eacute;s de conseil et d&rsquo;accompagnement autour de l&rsquo;int&eacute;gration. Cette fois, les b&eacute;n&eacute;voles donnaient et distribuaient de la nourriture, des v&ecirc;tements et d&rsquo;autres produits de premi&egrave;re n&eacute;cessit&eacute;. La solidarit&eacute; et l&rsquo;hospitalit&eacute; d&eacute;montr&eacute;es par ces b&eacute;n&eacute;voles apportaient une dimension de bienvenue &agrave; l&rsquo;accueil des r&eacute;fugi&eacute;s que les institutions gouvernementales sont incapables de fournir. L&rsquo;&eacute;quilibre d&eacute;licat entre aider les r&eacute;fugi&eacute;s et soulager l&rsquo;&Eacute;tat de son r&ocirc;le fondamental s&rsquo;est d&eacute;plac&eacute; en faveur des b&eacute;n&eacute;voles qui ont pris le relais en cas d&rsquo;&eacute;chec des bureaucraties. Dans certaines circonstances, les institutions de l&rsquo;&Eacute;tat se sont intentionnellement d&eacute;charg&eacute;es de leurs responsabilit&eacute;s sur les b&eacute;n&eacute;voles.<\/p>\n<p>Les critiques ont pr&eacute;venu qu&rsquo;il fallait se m&eacute;fier des politiques n&eacute;olib&eacute;rales qui consistent &agrave; sous-traiter &agrave; des b&eacute;n&eacute;voles les obligations de l&rsquo;&Eacute;tat &agrave; l&rsquo;&eacute;gard des r&eacute;fugi&eacute;s. Sur le long terme, le r&ocirc;le des b&eacute;n&eacute;voles doit &ecirc;tre d&eacute;fini de mani&egrave;re plus pr&eacute;cise. Il est important que les b&eacute;n&eacute;voles ne se substituent pas &agrave; l&rsquo;&Eacute;tat dans l&rsquo;accomplissement de ses obligations mais qu&rsquo;ils s&rsquo;impliquent dans ce qui concerne l&rsquo;accueil des r&eacute;fugi&eacute;s dans leur nouvelle soci&eacute;t&eacute;. &Agrave; travers les actions qu&rsquo;ils m&egrave;nent en commun, ils contribuent &agrave; la cr&eacute;ation d&rsquo;une soci&eacute;t&eacute; civile ouverte et dispos&eacute;e &agrave; accepter de nouveaux membres. De fait, bon nombre de t&acirc;ches accomplies par les b&eacute;n&eacute;voles couvrent des &eacute;l&eacute;ments fondamentaux du processus d&rsquo;int&eacute;gration des r&eacute;fugi&eacute;s.<\/p>\n<p>En 2015, l&rsquo;engagement civil &agrave; l&rsquo;&eacute;gard des r&eacute;fugi&eacute;s a jailli spontan&eacute;ment &agrave; travers l&rsquo;ensemble de l&rsquo;Europe. Les Europ&eacute;ens ont pratiqu&eacute; la solidarit&eacute; envers les r&eacute;fugi&eacute;s ind&eacute;pendamment des fronti&egrave;res nationales, ce en quoi les politiciens europ&eacute;ens avaient longtemps &eacute;chou&eacute;. Le d&eacute;fi que soul&egrave;ve cet activisme de la base consiste &agrave; prolonger la d&eacute;monstration de solidarit&eacute; au-del&agrave; de la p&eacute;riode d&rsquo;urgence cr&eacute;&eacute;e par les politiques rat&eacute;es impos&eacute;es depuis le sommet. De nombreux b&eacute;n&eacute;voles signalent que le soutien ad hoc qu&rsquo;ils ont apport&eacute; manque d&rsquo;efficacit&eacute; dans son organisation. Des structures efficaces et durables &agrave; l&rsquo;intention des b&eacute;n&eacute;voles doivent &ecirc;tre mises en place. Les ONG et les entreprises peuvent apporter leur exp&eacute;rience et leur savoir-faire non seulement pour accro&icirc;tre et renforcer les capacit&eacute;s et l&rsquo;efficacit&eacute; du b&eacute;n&eacute;volat mais aussi pour g&eacute;rer les attentes de toutes les personnes impliqu&eacute;es.&nbsp;<\/p>\n<p>En dernier ressort, il est probable que l&rsquo;Union europ&eacute;enne b&eacute;n&eacute;ficie de ce mouvement de b&eacute;n&eacute;volat tout autant que les r&eacute;fugi&eacute;s. Elle devrait en financer les structures organisationnelles mais sans chercher &agrave; prendre le contr&ocirc;le de l&rsquo;engagement de la soci&eacute;t&eacute; civile. Pendant longtemps les gouvernements ont sous-estim&eacute; ce vaste potentiel tourn&eacute; vers l&rsquo;accueil, l&rsquo;int&eacute;gration et la protection des r&eacute;fugi&eacute;s au sein de la soci&eacute;t&eacute; europ&eacute;enne. Les &Eacute;tats europ&eacute;ens devraient suivre l&rsquo;exemple des b&eacute;n&eacute;voles en axant les politiques relatives aux r&eacute;fugi&eacute;s sur les besoins des demandeurs d&rsquo;asile de mani&egrave;re &agrave; faire de la soci&eacute;t&eacute; europ&eacute;enne une soci&eacute;t&eacute; aussi accueillante que possible.<\/p>\n<p>&nbsp;<\/p>\n<p>Serhat Karakayali <a href=\"mailto:serhat.karakayali@hu-berlin.de\"><em>serhat.karakayali@hu-berlin.de<\/em><\/a><\/p>\n<p>Chercheur, Berliner Institut for Integration and Migration Research, Universit&eacute; Humboldt de Berlin <a href=\"http:\/\/www.hu-berlin.de\/en?set_language=en\"><em>www.hu-berlin.de\/en?set_language=en<\/em><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>J Olaf Kleist <a href=\"mailto:j.olaf.kleist@outlook.com\"><em>j.olaf.kleist@outlook.com<\/em><\/a><\/p>\n<p>Charg&eacute; de recherche, Centre d&rsquo;&eacute;tudes sur les r&eacute;fugi&eacute;s, Universit&eacute; d&rsquo;Oxford et chercheur &agrave; l&rsquo;Institut de recherche sur la migration et &eacute;tudes interculturelles, Universit&eacute; d&rsquo;Osnabr&uuml;ck www.imis.uni-osnabrueck.de<\/p>\n<div>\n\t<br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[1]<\/a> Tir&eacute; d&rsquo;une enqu&ecirc;te men&eacute;e aupr&egrave;s de plus de 460 b&eacute;n&eacute;voles et plus de 70 organisations. Karakayali S et Kleist J O (2015) <em>EFA-Studie: Strukturen und Motive der ehrenamtlichen Fl&uuml;chtlingsarbeit in Deutschland, 1. Forschungsbericht: Ergebnisse einer explorativen Umfrage vom November\/Dezember 2014.<\/em> Berliner Institute f&uuml;r empirische Integrations- und Migrationsforschung, Humboldt-Universit&auml;t zu Berlin <a href=\"http:\/\/www.bim.hu-berlin.de\/media\/2015-05-16_EFA-Forschungsbericht_Endfassung.pdf\">www.bim.hu-berlin.de\/media\/2015-05-16_EFA-Forschungsbericht_Endfassung.pdf<\/a><\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les structures d&rsquo;accueil et de traitement des demandes, particuli&egrave;rement dans les pays de premi&egrave;re arriv&eacute;e se sont souvent trouv&eacute; d&eacute;bord&eacute;es face &agrave; l&rsquo;augmentation croissante du nombre des demandeurs d&rsquo;asile qui sont arriv&eacute;s sur les c&ocirc;tes de l&rsquo;Europe au cours des derni&egrave;res ann&eacute;es. Les demandeurs d&rsquo;asile ont &eacute;t&eacute; confront&eacute;s &agrave; une p&eacute;nurie d&rsquo;infrastructure d&rsquo;accueil et d&rsquo;int&eacute;gration,&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42645,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[99],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[565],"class_list":["post-41698","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-99","fmr_content_type-article","fmr_languages-french","fmr_list_years-565","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>B\u00e9n\u00e9voles et demandeurs d\u2019asile - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B\u00e9n\u00e9voles et demandeurs d\u2019asile - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"Les structures d&rsquo;accueil et de traitement des demandes, particuli&egrave;rement dans les pays de premi&egrave;re arriv&eacute;e se sont souvent trouv&eacute; d&eacute;bord&eacute;es face &agrave; l&rsquo;augmentation croissante du nombre des demandeurs d&rsquo;asile qui sont arriv&eacute;s sur les c&ocirc;tes de l&rsquo;Europe au cours des derni&egrave;res ann&eacute;es. Les demandeurs d&rsquo;asile ont &eacute;t&eacute; confront&eacute;s &agrave; une p&eacute;nurie d&rsquo;infrastructure d&rsquo;accueil et d&rsquo;int&eacute;gration,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T12:27:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/\",\"url\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/\",\"name\":\"B\u00e9n\u00e9voles et demandeurs d\u2019asile - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2015-12-15T05:00:00+00:00\",\"dateModified\":\"2025-04-01T12:27:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FMR 51 &#8211; Destination : Europe\",\"item\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"B\u00e9n\u00e9voles et demandeurs d\u2019asile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B\u00e9n\u00e9voles et demandeurs d\u2019asile - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/","og_locale":"ar_AR","og_type":"article","og_title":"B\u00e9n\u00e9voles et demandeurs d\u2019asile - Forced Migration Review","og_description":"Les structures d&rsquo;accueil et de traitement des demandes, particuli&egrave;rement dans les pays de premi&egrave;re arriv&eacute;e se sont souvent trouv&eacute; d&eacute;bord&eacute;es face &agrave; l&rsquo;augmentation croissante du nombre des demandeurs d&rsquo;asile qui sont arriv&eacute;s sur les c&ocirc;tes de l&rsquo;Europe au cours des derni&egrave;res ann&eacute;es. Les demandeurs d&rsquo;asile ont &eacute;t&eacute; confront&eacute;s &agrave; une p&eacute;nurie d&rsquo;infrastructure d&rsquo;accueil et d&rsquo;int&eacute;gration,&hellip;","og_url":"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-04-01T12:27:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/","url":"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/","name":"B\u00e9n\u00e9voles et demandeurs d\u2019asile - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2015-12-15T05:00:00+00:00","dateModified":"2025-04-01T12:27:41+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/karakayali-kleist-2-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/ar\/"},{"@type":"ListItem","position":2,"name":"FMR 51 &#8211; Destination : Europe","item":"https:\/\/www.fmreview.org\/destination-europe-fr\/"},{"@type":"ListItem","position":3,"name":"B\u00e9n\u00e9voles et demandeurs d\u2019asile"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41698\/revisions"}],"predecessor-version":[{"id":46168,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/41698\/revisions\/46168"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/42645"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/media?parent=41698"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_themes?post=41698"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_region?post=41698"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_issue?post=41698"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_year?post=41698"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content_type?post=41698"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_languages?post=41698"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_list_years?post=41698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}