{"id":42109,"date":"2019-03-11T00:00:00","date_gmt":"2019-03-11T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/khaddour-2-3\/"},"modified":"2024-11-20T00:36:34","modified_gmt":"2024-11-20T05:36:34","slug":"khaddour","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/ar\/education-deplacement\/khaddour\/","title":{"rendered":"D\u00e9veloppement de la petite enfance et soutien psychosocial en Syrie"},"content":{"rendered":"<p><span><span><span lang=\"FR\">D\u00e8s le d\u00e9but de la crise syrienne, des personnes d\u00e9plac\u00e9es \u00e0 l\u2019int\u00e9rieur de leur propre pays (PDI) venues de l\u2019ensemble du territoire syrien ont cherch\u00e9 refuge dans le district de Salamieh dans l\u2019est du gouvernorat de Hama, ce qui a fait augmenter la population de 40&nbsp;% pour arriver au total actuel de 300&nbsp;000 personnes. Grand nombre de ceux qui ont \u00e9t\u00e9 d\u00e9plac\u00e9s \u2013 y compris des enfants \u2013 souffraient de traumatismes s\u00e9v\u00e8res. Les acteurs humanitaires dans la ville de Salamieh, et notamment le Croissant rouge arabe syrien (CRAS) et l\u2019Aga Khan Development Network (AKDN), ont d\u00e9ploy\u00e9 des \u00e9quipes de soutien psychosocial mais les intervenants sur place se sont rapidement rendu compte qu\u2019ils n\u2019\u00e9taient pas pr\u00e9par\u00e9s pour faire face \u00e0 l\u2019immensit\u00e9 des besoins en sant\u00e9 mentale. <\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">AKDN a donc d\u00e9velopp\u00e9 un plan strat\u00e9gique de mise en place d\u2019un soutien psychosocial complet dans le district de Salamieh par le biais d\u2019approches communautaires et durables de la sant\u00e9 mentale et du soutien psychosocial. Outre le plaidoyer et la sensibilisation autour de la sant\u00e9 mentale et du soutien psychosocial en situation de conflit et le renforcement des capacit\u00e9s de fonctionnement en ce qui concerne les comp\u00e9tences et le nombre de travailleurs en sant\u00e9 mentale, le plan int\u00e9grait \u00e9galement des \u00e9l\u00e9ments de protection sp\u00e9cifiquement con\u00e7us \u00e0 l\u2019intention des enfants, parmi lesquels&nbsp;:&nbsp;une mise \u00e0 disposition d\u2019espaces amis informels, un soutien pour aider les enfants \u00e0 d\u00e9velopper des m\u00e9canismes de survie associ\u00e9 \u00e0 des activit\u00e9s compl\u00e9mentaires pour aider les adultes \u00e0 comprendre le d\u00e9veloppement psychosocial, social, cognitif, moteur et linguistique de leurs enfants. <\/span><\/span><\/span><\/p>\n<p><span><span><strong><span lang=\"FR\">Moi et mon enfant en situation de crise<\/span><\/strong><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">Le programme <em>Moi et mon enfant en situation de crise<\/em> (Me and My Child in Crisis \u2013MMIC) qui int\u00e9grait un soutien psychosocial au programme bien \u00e9tabli de d\u00e9veloppement de la petite enfance d\u2019AKDN, a \u00e9t\u00e9 l\u2019un des \u00e9l\u00e9ments cl\u00e9s de ce plan strat\u00e9gique. Le Programme MMIC a \u00e9t\u00e9 invent\u00e9 initialement pour proposer des sessions d\u2019apprentissage du r\u00f4le parental et donner aux parents d\u00e9plac\u00e9s et aux parents au sein de la communaut\u00e9 d\u2019accueil des possibilit\u00e9s de se rencontrer dans un espace accueillant o\u00f9 ils pouvaient parler de leurs exp\u00e9riences traumatiques, comme la mort, la perte, le deuil, la douleur, le choc ainsi que les difficult\u00e9s auxquelles ils se trouvaient confront\u00e9s pour \u00e9lever leurs enfants dans des environnements stressants. Il est apparu \u00e9vident pendant ces sessions que les parents n\u2019\u00e9taient pas capables de g\u00e9rer les pressions associ\u00e9es aux traumatismes de leurs enfants en plus du stress auquel ils faisaient face eux-m\u00eames&nbsp;; en cons\u00e9quence, ce groupe d\u2019enfants devenait de plus en plus n\u00e9glig\u00e9 et par l\u00e0-m\u00eame de plus en plus vuln\u00e9rable. <\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">Le programme MMIC, en ciblant \u00e0 la fois les parents et leur enfants jusqu\u2019\u00e0 l\u2019\u00e2ge de huit ans, a cherch\u00e9 \u00e0 introduire des concepts de d\u00e9veloppement de la petite enfance et \u00e0 enseigner des m\u00e9thodes pour apporter un soutien psychosocial aux enfants. Le projet donnait \u00e9galement la possibilit\u00e9 d\u2019aider \u00e0 l\u2019instauration de meilleures relations entre les PDI et les communaut\u00e9s d\u2019accueil en leur permettant de s\u2019assoir ensemble pour discuter des difficult\u00e9s \u00e0 s\u2019adapter \u00e0 leur situation nouvelle, dans un espace s\u00fbr aupr\u00e8s de personnes qu\u2019ils comprenaient intuitivement. <\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">Les parents ont appris diff\u00e9rentes choses comme l\u2019importance de la croissance et du d\u00e9veloppement pr\u00e9coce de l\u2019enfant et se sont familiaris\u00e9s avec le d\u00e9veloppement c\u00e9r\u00e9bral, les m\u00e9thodes \u00ab&nbsp;d\u2019apprentissage actif&nbsp;\u00bb, les caract\u00e9ristiques de la petite enfance, les avantages d\u2019une implication parentale active, le soutien psychosocial aux parents et aux enfants, la communication effective des enfants, et la notion de discipline positive. Parall\u00e8lement, les enfants ont \u00e9t\u00e9 int\u00e9gr\u00e9s \u00e0 des activit\u00e9s connexes. Par exemple, il a \u00e9t\u00e9 demand\u00e9 aux enfants d\u2019inventer des histoires dont ils ont ensuite fait part \u00e0 leurs parents, comme moyen pour permettre aux enfants de s\u2019exprimer et aux parents de comprendre ce qui se passe dans l\u2019esprit de leur enfant. L\u2019<em>arbre de s\u00e9curit\u00e9<\/em> est un autre exercice dans lequel un enfant \u00e9crit en guise de branches les noms des membres de sa famille \u00e0 qui il fait confiance, ce qui permet aux parents de comprendre quelles sont les personnes aupr\u00e8s desquelles leur enfant se sent le plus en s\u00e9curit\u00e9.&nbsp; <\/span><\/span><\/span><\/p>\n<p><span><span><strong><span lang=\"FR\">S\u2019adapter en vue d\u2019une viabilit\u00e9 \u00e0 long terme <\/span><\/strong><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">Alors que le nombre des participants augmentait, il est devenu urgent de consid\u00e9rer la viabilit\u00e9 \u00e0 long terme du projet. Les responsables du projet ont consult\u00e9 les Normes minimales de l\u2019INEE<a href=\"#_edn1\" name=\"_ednref1\"><span><span><span lang=\"FR\"><span>[1]<\/span><\/span><\/span><\/span><\/a>, et deux d\u2019entre elles se sont av\u00e9r\u00e9es particuli\u00e8rement pertinentes au cas du programme MMIC, savoir&nbsp;: combiner l\u2019aide d\u2019urgence et le rel\u00e8vement pr\u00e9coce, et encourager les initiatives \u00e9ducatives conduites par la communaut\u00e9. En cons\u00e9quence, le projet a \u00e9volu\u00e9 pour se transformer au niveau du mode de fonctionnement en une s\u00e9rie d\u2019associations parents\/enseignants bas\u00e9es dans les \u00e9coles. Gr\u00e2ce \u00e0 cette \u00e9volution, le projet a touch\u00e9 un nombre encore plus \u00e9lev\u00e9 de parents et d\u2019enfants (\u00e0 la fois parmi les PDI et parmi la communaut\u00e9 d\u2019accueil) ce qui a contribu\u00e9 \u00e0 augmenter la sensibilisation au d\u00e9veloppement de la petite enfance ainsi que la contribution du soutien psychosocial dans la vie des enfants. Ce faisant, le projet s\u2019est tout de m\u00eame heurt\u00e9 \u00e0 plusieurs difficult\u00e9s.<\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">Premi\u00e8rement, certains parents n\u2019\u00e9taient pas suffisamment comp\u00e9tents pour transmettre les informations contenues dans le mat\u00e9riel de formation, plus particuli\u00e8rement en ce qui concerne des concepts sp\u00e9cifiques \u00e0 l\u2019\u00e9ducation. En outre, tous les animateurs n\u2019avaient pas suffisamment de motivation pour assurer b\u00e9n\u00e9volement la formation sans incitation financi\u00e8re. Deuxi\u00e8mement, les animateurs organisaient les sessions MMIC au sein des \u00e9coles, mais toutes ne disposaient pas de ressources suffisantes, projecteurs, \u00e9lectricit\u00e9, chauffage. Et troisi\u00e8mement, les mat\u00e9riaux didactiques donnaient une introduction aux caract\u00e9ristiques de chaque p\u00e9riode de la petite enfance jusqu\u2019\u00e0 l\u2019\u00e2ge de huit ans mais les parents d\u2019enfants d\u2019\u00e2ge scolaire (6 \u00e0 12 ans) ne trouvaient pas tr\u00e8s pertinentes les discussions sur le d\u00e9veloppement c\u00e9r\u00e9bral du b\u00e9b\u00e9.<\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">En cons\u00e9quence, le contenu du projet a \u00e9t\u00e9 simplifi\u00e9, et les animateurs du programme MMIC ont \u00e9t\u00e9 form\u00e9s \u00e0 la transmission des sujets concernant les enfants de 6 \u00e0 12 ans, alors que les besoins des plus jeunes enfants \u00e9taient cibl\u00e9s par le biais d\u2019autres initiatives d\u2019AKDN. Le projet a accord\u00e9 davantage d\u2019importance \u00e0 l\u2019utilisation d\u2019activit\u00e9s interactives afin d\u2019apporter un soutien psychosocial aux enfants et aux parents. Le projet a cherch\u00e9 \u00e0 aider les parents \u00e0 en savoir davantage sur le d\u00e9veloppement de la petite enfance, en se concentrant sur l\u2019importance du soutien psychosocial, sur la mise en pratique des concepts de d\u00e9veloppement de la petite enfance et du soutien psychosocial (comme, par exemple, de permettre aux enfants de pleurer lorsqu\u2019ils sont tristes), et sur la mise en place progressive de meilleurs canaux de communication avec leurs enfants (en utilisant par exemple des m\u00e9thodes de discipline positive).&nbsp; <\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">Depuis son instauration, le projet s\u2019est trouv\u00e9 confront\u00e9 \u00e0 un autre d\u00e9fi majeur&nbsp;: le manque de participation des p\u00e8res. Un sujet li\u00e9 \u00e0 diff\u00e9rents facteurs, notamment \u00e0 la conviction que les soins aux enfants sont la responsabilit\u00e9 de la m\u00e8re, \u00e0 l\u2019absence physique des p\u00e8res (alors que beaucoup sont au combat et que de nombreux autres ont \u00e9t\u00e9 tu\u00e9s), et \u00e0 la pression accrue sur les hommes de trouver un travail (\u00e9tant donn\u00e9 le d\u00e9clin de la situation \u00e9conomique). Les sessions du programme MMIC ont \u00e9t\u00e9 assur\u00e9es par des animateurs qui \u00e9taient eux-m\u00eames des couples mari\u00e9s de mani\u00e8re \u00e0 encourager les parents \u00e0 participer en couples, mais le manque de participation masculine a tout de m\u00eame persist\u00e9. Pendant la p\u00e9riode 2014 \u00e0 2018, 2216 parents ont particip\u00e9 au programme, sur lesquels seulement 131 hommes.&nbsp; <\/span><\/span><\/span><\/p>\n<p><span><span><strong><span lang=\"FR\">Vers une amorce de r\u00e9tablissement<\/span><\/strong><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">Alors que l\u2019intensit\u00e9 du conflit arm\u00e9 a diminu\u00e9 au cours de l\u2019ann\u00e9e 2018, le nom du projet \u2013 <em>Moi et mon enfant en situation de crise<\/em> \u2013 a fini par \u00eatre per\u00e7u comme associ\u00e9 \u00e0 une phase pass\u00e9e et particuli\u00e8rement difficile de la crise. Le contenu du projet MMIC a donc \u00e9t\u00e9 revisit\u00e9 pour s\u2019ajuster \u00e0 la phase de r\u00e9tablissement (m\u00eame s\u2019il ne faut pas oublier qu\u2019il reste des besoins tr\u00e8s s\u00e9rieux en soutien psychosocial parmi les PDI et les personnes de retour comme parmi les membres de la communaut\u00e9 d\u2019accueil) et a \u00e9t\u00e9 transform\u00e9 en un programme intitul\u00e9 <em>Lire avec les enfants<\/em> (Reading with Children \u2013 RWC).<\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">Le programme <em>Lire avec les enfants<\/em> a pour objectif de sensibiliser les parents au r\u00f4le de la lecture comme facteur de d\u00e9veloppement des comp\u00e9tences linguistiques de leurs enfants et \u00e0 l\u2019importance d\u2019\u00e9tablir des habitudes de lecture \u00e0 l\u2019int\u00e9rieur de la routine quotidienne des enfants. Il couvre \u00e9galement des sujets de soutien psychosocial \u00e0 destination des parents et des enfants (y compris la discipline positive). Le projet met \u00e0 disposition 15 recueils de contes que les parents peuvent emprunter et lire \u00e0 leurs enfants ou avec leurs enfants \u00e0 la maison. <\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">Le projet aide \u00e9galement les parents \u00e0 pr\u00e9parer psychologiquement leurs enfants \u00e0 l\u2019entr\u00e9e \u00e0 l\u2019\u00e9cole par le biais du calendrier <em>Je suis pr\u00eat(e) pour l\u2019\u00e9cole<\/em><\/span> <span>(I Am Ready for School)<\/span><span lang=\"FR\">, un projet qui immerge les parents, les enseignants et les enfants dans des activit\u00e9s interactives au cours des premi\u00e8res semaines d\u2019\u00e9cole de mani\u00e8re \u00e0 ce que les enfants se sentent en s\u00e9curit\u00e9 \u00e0 mesure qu\u2019ils\/elles se familiarisent avec leur nouvel environnement et avec les enseignants. De mars \u00e0 ao\u00fbt 2018, 375 enfants et 323 parents ont particip\u00e9 au projet <em>Je suis pr\u00eat(e) pour l\u2019\u00e9cole<\/em> (m\u00eame si la participation des p\u00e8res reste faible).<\/span><\/span><\/span><\/p>\n<p><span><span><strong><span lang=\"FR\">D\u00e9fis et options<\/span><\/strong><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">Assurer une participation constante s\u2019est av\u00e9r\u00e9 un d\u00e9fi notoire. Les taux de participation tant pour les parents que pour les animateurs au programme MMIC comme au programme RWC se sont av\u00e9r\u00e9s instables. Dans l\u2019optique d\u2019am\u00e9liorer la participation au programme dans des contextes o\u00f9 les ressources financi\u00e8res des personnes sont tr\u00e8s diminu\u00e9es le recours aux incitations est fortement recommand\u00e9s. Les incitations propos\u00e9es peuvent \u00eatre utilis\u00e9es en conjonction avec d\u2019autres programmes humanitaires et doivent r\u00e9pondre aux besoins et s\u2019adapter au contexte, qu\u2019il s\u2019agisse d\u2019esp\u00e8ces, de coupons, de nourriture, de produits non alimentaires (des kits WASH (eau, assainissement et hygi\u00e8ne) ou d\u2019hivernage) ou des paniers pour les enfants (comprenant des produits comme des livres de contes, des sous-v\u00eatements, des uniformes scolaires et des suppl\u00e9ments nutritionnels). Donner des incitations d\u00e8s le d\u00e9but d\u2019un projet (plut\u00f4t qu\u2019\u00e0 mi-parcours) contribuera \u00e0 faire en sorte que la mise \u00e0 disposition d\u2019un programme de soutien psychosocial et de d\u00e9veloppement de la petite enfance soit maintenue de la naissance \u00e0 l\u2019enfance et au-del\u00e0. M\u00eame si AKDN n\u2019a pas utilis\u00e9 en Syrie une approche fond\u00e9e sur l\u2019incitation, il semblerait, en examinant l\u2019exp\u00e9rience de diff\u00e9rents acteurs \u00e0 travers le monde, que l\u2019utilisation d\u2019incitatifs sous forme d\u2019esp\u00e8ces ou de nourriture soit une approche qui vaille la peine d\u2019\u00eatre consid\u00e9r\u00e9e.&nbsp; <\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>L\u2019utilisation de la technologie et des applications mobiles semble \u00eatre une autre option \u00e0 explorer afin de faciliter l\u2019acc\u00e8s des parents aux produits de soutien psychosocial. Comme nous l\u2019avons mentionn\u00e9 plus-haut, de nombreux parents, et plus particuli\u00e8rement les p\u00e8res, n\u2019\u00e9taient pas en mesure de participer aux sessions du fait de leurs obligations li\u00e9es au travail. Mettre \u00e0 disposition des plateformes mobiles ou utiliser celles qui sont couramment utilis\u00e9es (comme WhatsApp ou Facebook) pourrait am\u00e9liorer la couverture et l\u2019acc\u00e8s. Par exemple&nbsp;: une application gratuite pourrait proposer des vid\u00e9os d\u2019apprentissage, des messages de sensibilisation et des groupes de discussion interactive&nbsp;; les pages Facebook permettent aux employ\u00e9s du programme d\u2019afficher des sujets et aux lecteurs de les discuter et de soulever des questions&nbsp;; sur WhatsApp, des messages de sensibilisation peuvent \u00eatre envoy\u00e9s \u00e0 des groupes de participants qui peuvent les retransmettre \u00e0 leur tour&nbsp;; et des contrats peuvent \u00eatre \u00e9tablis avec les fournisseurs de services locaux pour envoyer des messages par SMS sur le soutien psychosocial de mani\u00e8re \u00e0 atteindre l\u2019ensemble d\u2019une population dans une zone particuli\u00e8re. (La Fondation Aga Khan utilise d\u00e9j\u00e0 la messagerie SMS dans le cadre de sa campagne de sensibilisation \u00e0 la sant\u00e9). De telles initiatives ont toutes les chances de bien fonctionner dans le contexte syrien, dans la mesure o\u00f9 de tr\u00e8s nombreux foyers poss\u00e8dent des t\u00e9l\u00e9phones portables. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>AKDN travaille actuellement avec le gouvernement et avec les acteurs non-gouvernementaux \u00e0 l\u2019\u00e9tablissement d\u2019un cadre de soutien psychosocial \u00e0 l\u2019\u00e9chelle nationale. Le succ\u00e8s du programme de soutien psychosocial destin\u00e9 aux enfants dans le district de Salamieh pendant la crise se doit en partie au fait que le programme de d\u00e9veloppement de la petite enfance \u00e9tait d\u00e9j\u00e0 bien \u00e9tabli dans cette zone avant la crise. Dans le cas de communaut\u00e9s vuln\u00e9rables aux conflits et aux probl\u00e8mes subs\u00e9quents de sant\u00e9 mentale, les programmes de d\u00e9veloppement de la petite enfance peuvent au moins assurer une infrastructure sur laquelle il sera par la suite possible d\u2019adosser des programmes de sant\u00e9 mentale et de soutien psychosocial, dans l\u2019optique d\u2019att\u00e9nuer et d\u2019apprendre \u00e0 g\u00e9rer les troubles mentaux, et notamment l\u2019apparition de traumatismes graves.&nbsp;&nbsp; <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">&nbsp;<\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\">Fatima Khaddour <span><span><em><a href=\"mailto:fatima.khaddour89@gmail.com\">fatima.khaddour89@gmail.com<\/a><\/em><\/span><\/span><br \/>\nResponsable de projet, Fondation Aga Khan, Syrie <span><span><em><a href=\"http:\/\/www.akdn.org\">www.akdn.org<\/a><\/em><\/span><\/span> <\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span><span><a href=\"#_ednref1\" name=\"_edn1\"><span><span lang=\"EN-CA\"><span><span><span lang=\"EN-CA\"><span>[1]<\/span><\/span><\/span><\/span><\/span><\/span><\/a> <span><span>Les Normes minimales de l\u2019INEE d\u00e9finissent des niveaux minimums en termes de qualit\u00e9 et d\u2019acc\u00e8s \u00e0 l\u2019\u00e9ducation de la situation d\u2019urgence \u00e0 la phase de rel\u00e8vement, et pr\u00e9sentent les pratiques optimales visant \u00e0 satisfaire les droits et les besoins \u00e9ducatifs des personnes touch\u00e9es par une catastrophe ou une situation de crise.<span lang=\"EN-CA\"><span><a href=\"http:\/\/www.ineesite.org\/en\/minimum-standards\/translations\"> www.ineesite.org\/en\/minimum-standards\/translations<\/a><\/span><\/span><\/span><\/span> <\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e8s le d\u00e9but de la crise syrienne, des personnes d\u00e9plac\u00e9es \u00e0 l\u2019int\u00e9rieur de leur propre pays (PDI) venues de l\u2019ensemble du territoire syrien ont cherch\u00e9 refuge dans le district de Salamieh dans l\u2019est du gouvernorat de Hama, ce qui a fait augmenter la population de 40&nbsp;% pour arriver au total actuel de 300&nbsp;000 personnes. Grand&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42362,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[108],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[568],"class_list":["post-42109","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-108","fmr_content_type-article","fmr_languages-french","fmr_list_years-568","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9veloppement de la petite enfance et soutien psychosocial en Syrie - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9veloppement de la petite enfance et soutien psychosocial en Syrie - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"D\u00e8s le d\u00e9but de la crise syrienne, des personnes d\u00e9plac\u00e9es \u00e0 l\u2019int\u00e9rieur de leur propre pays (PDI) venues de l\u2019ensemble du territoire syrien ont cherch\u00e9 refuge dans le district de Salamieh dans l\u2019est du gouvernorat de Hama, ce qui a fait augmenter la population de 40&nbsp;% pour arriver au total actuel de 300&nbsp;000 personnes. Grand&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-20T05:36:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/\",\"url\":\"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/\",\"name\":\"D\u00e9veloppement de la petite enfance et soutien psychosocial en Syrie - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2019-03-11T05:00:00+00:00\",\"dateModified\":\"2024-11-20T05:36:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FMR 60 &#8211; \u00c9ducation : besoins, droits et acc\u00e8s en d\u00e9placement\",\"item\":\"https:\/\/www.fmreview.org\/education-deplacement\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00e9veloppement de la petite enfance et soutien psychosocial en Syrie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9veloppement de la petite enfance et soutien psychosocial en Syrie - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/","og_locale":"ar_AR","og_type":"article","og_title":"D\u00e9veloppement de la petite enfance et soutien psychosocial en Syrie - Forced Migration Review","og_description":"D\u00e8s le d\u00e9but de la crise syrienne, des personnes d\u00e9plac\u00e9es \u00e0 l\u2019int\u00e9rieur de leur propre pays (PDI) venues de l\u2019ensemble du territoire syrien ont cherch\u00e9 refuge dans le district de Salamieh dans l\u2019est du gouvernorat de Hama, ce qui a fait augmenter la population de 40&nbsp;% pour arriver au total actuel de 300&nbsp;000 personnes. Grand&hellip;","og_url":"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/","og_site_name":"Forced Migration Review","article_modified_time":"2024-11-20T05:36:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/","url":"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/","name":"D\u00e9veloppement de la petite enfance et soutien psychosocial en Syrie - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2019-03-11T05:00:00+00:00","dateModified":"2024-11-20T05:36:34+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/education-deplacement\/khaddour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/ar\/"},{"@type":"ListItem","position":2,"name":"FMR 60 &#8211; \u00c9ducation : besoins, droits et acc\u00e8s en d\u00e9placement","item":"https:\/\/www.fmreview.org\/education-deplacement\/"},{"@type":"ListItem","position":3,"name":"D\u00e9veloppement de la petite enfance et soutien psychosocial en Syrie"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/42109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/42109\/revisions"}],"predecessor-version":[{"id":42866,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/42109\/revisions\/42866"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/42362"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/media?parent=42109"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_themes?post=42109"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_region?post=42109"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_issue?post=42109"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_year?post=42109"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content_type?post=42109"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_languages?post=42109"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_list_years?post=42109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}