{"id":42117,"date":"2019-03-11T00:00:00","date_gmt":"2019-03-11T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/hagan-2-3\/"},"modified":"2024-11-20T00:38:24","modified_gmt":"2024-11-20T05:38:24","slug":"hagan","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/ar\/education-deplacement\/hagan\/","title":{"rendered":"\u00c9coles de rue et Bus-\u00e9cole : des propositions d\u2019\u00e9ducation informelle en France"},"content":{"rendered":"<p><span><span><span><span lang=\"FR\"><span>C\u2019est suite \u00e0 la destruction de la Jungle de Calais en 2016 que le gouvernement fran\u00e7ais a mis en \u0153uvre sa politique de z\u00e9ro tol\u00e9rance \u00e0 l\u2019\u00e9gard des camps, une politique qui veut que tout site informel d\u2019installation soit maintenant syst\u00e9matiquement d\u00e9truit par la police et les \u00e9quipes de \u00ab&nbsp;nettoyage&nbsp;\u00bb. L\u2019argument est que la France dispose d\u2019institutions d\u2019accueil des migrants \u2013 \u00e0 condition qu\u2019ils acceptent de passer par le syst\u00e8me formel de l\u2019asile. Toutefois, pour ceux qui ne passent pas par ce syst\u00e8me, quel qu\u2019en soit le motif, cela se traduit par une exclusion bien plus compl\u00e8te&nbsp;; en poursuivant cette politique les autorit\u00e9s fran\u00e7aises remettent en cause non seulement l\u2019acc\u00e8s \u00e0 des conditions de vie minimales mais aussi l\u2019acc\u00e8s \u00e0 l\u2019\u00e9ducation et \u00e0 d\u2019autres services fondamentaux qui \u00e9taient pris en charge par des b\u00e9n\u00e9voles dans les sites informels d\u2019installation. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>En France, il n\u2019existe aucune disposition officielle pour l\u2019acquisition de la langue pour les demandeurs d\u2019asile jusqu\u2019\u00e0 ce que le statut de r\u00e9fugi\u00e9 leur soit accord\u00e9. Pourtant, d\u00e9buter les cours plus t\u00f4t au cours du processus d\u2019asile permettrait non seulement de faciliter l\u2019int\u00e9gration de ceux dont la demande est accept\u00e9e&nbsp;mais leur donnerait \u00e9galement la possibilit\u00e9 d\u2019acqu\u00e9rir des comp\u00e9tences indispensables tout en constituant une distraction bienvenue pendant les longs mois d\u2019attente anxieuse. Les demandeurs d\u2019asile consid\u00e8rent l\u2019\u00e9ducation comme un moteur de changement \u00e0 travers lequel ils peuvent am\u00e9liorer leur qualit\u00e9 de vie, participer de mani\u00e8re comp\u00e9titive sur le march\u00e9 de l\u2019emploi, et ainsi de suite&nbsp;: en d\u2019autres termes, comme un \u00e9l\u00e9ment essentiel d\u2019une nouvelle existence dans une nouvelle soci\u00e9t\u00e9. De nombreuses personnes plaident en faveur de la cr\u00e9ation de simples espaces d\u2019hospitalit\u00e9 en France, des espaces sans conditions ou obligations qui donneraient aux demandeurs d\u2019asile le temps de se reposer et de r\u00e9fl\u00e9chir \u00e0 leurs plans d\u2019avenir. Dispenser des services d\u2019\u00e9ducation pourrait \u00eatre un moyen id\u00e9al de faciliter cela. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><strong><span lang=\"FR\"><span>R\u00e9cup\u00e9rer la salle de classe<\/span><\/span><\/strong> <\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Malgr\u00e9 des conditions difficiles, de nombreuses initiatives communautaires offrent des services d\u2019\u00e9ducation de mani\u00e8re informelle. Chaque soir \u00e0 18h30, des migrants et des demandeurs d\u2019asile se r\u00e9unissent au Place de Stalingrad dans le nord-est de Paris. Ils se s\u00e9parent en trois groupes en fonction de leurs connaissances du fran\u00e7ais, et s\u2019assoient sur les marches qui m\u00e8nent au square public en dessous. Trois enseignants b\u00e9n\u00e9voles \u2013 un pour chaque niveau \u2013 de l\u2019organisation b\u00e9n\u00e9vole locale BAAM (Bureau d\u2019accueil et d\u2019accompagnement des migrants<a href=\"#_edn1\" name=\"_ednref1\"><span lang=\"FR\"><span><span>[1]<\/span><\/span><\/span><\/a>)<\/span><\/span><strong> <\/strong><span lang=\"FR\"><span>apportent des tableaux blancs et des stylos pour faciliter l\u2019apprentissage de l\u2019alphabet, de phrases \u00e9l\u00e9mentaires ainsi que du vocabulaire et des r\u00e8gles de grammaires pour les \u00e9tudiants les plus avanc\u00e9s. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Pendant ce temps, \u00e0 Calais, le School Bus Project<a href=\"#_edn2\" name=\"_ednref2\"><span lang=\"FR\"><span><span>[2]<\/span><\/span><\/span><\/a> (Projet Bus-\u00e9cole) cherche \u00e0 donner une \u00e9ducation \u00e9l\u00e9mentaire aux jeunes qui vivent de mani\u00e8re pr\u00e9caire. Chaque jour ce bus \u00e0 imp\u00e9riale jaune vif se rend dans un endroit de Calais ou de Grande-Synthe, \u00e0 une distance \u00e0 pied de l\u00e0 o\u00f9 vivent les gens dans les bois, en se cachant du mieux qu\u2019ils peuvent. L\u2019imp\u00e9riale du bus a \u00e9t\u00e9 transform\u00e9e en salle de classe, avec une salle plus petite dans laquelle des s\u00e9ances en groupes plus restreints peuvent avoir lieu. Le premier niveau est occup\u00e9 par une zone de r\u00e9cr\u00e9ation pour jouer et faire de la musique. Pour de nombreux usagers, cette \u00e9cole mobile est l\u2019un des seuls endroits o\u00f9 ils peuvent trouver s\u00e9curit\u00e9 et possibilit\u00e9 d\u2019apprendre. La plupart des jours le bus est bond\u00e9, remplis d\u2019\u00e9l\u00e8ves motiv\u00e9s, particuli\u00e8rement pendant les mois d\u2019hiver o\u00f9 c\u2019est \u00e9galement l\u2019un des seuls endroits offrant un abri. Au-del\u00e0 de la dispensation d\u2019une \u00e9ducation qui fait tant d\u00e9faut, le Bus-\u00e9cole est aussi la d\u00e9monstration publique de la volont\u00e9 d\u2019apprendre des nouveaux arrivants (et celle d\u2019enseigner des b\u00e9n\u00e9voles) dans un effort pour contrecarrer la criminalisation des personnes d\u00e9plac\u00e9es et faire la preuve qu\u2019il existe un mod\u00e8le d\u2019accueil \u00e0 visage humain. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span>&nbsp;<\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Maria Hagan <em><span><a href=\"mailto:mhh35@cam.ac.uk\"><span>mhh35@cam.ac.uk<\/span><\/a><\/span><\/em><br \/>\n<span>Doctorante, D\u00e9partement de g\u00e9ographie, Universit\u00e9 de Cambridge <em><span><a href=\"http:\/\/www.geog.cam.ac.uk\"><span>www.geog.cam.ac.uk<\/span><\/a><\/span> <\/em><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span><span><span><a href=\"#_ednref1\" name=\"_edn1\"><span><span><span>[1]<\/span><\/span><\/span><\/a> <span><span><a href=\"https:\/\/baamasso.org\/en\/\"><span>https:\/\/baamasso.org\/en\/<\/span><\/a><\/span><\/span> <\/span><\/span><\/span><\/p>\n<p><span><span><span><a href=\"#_ednref2\" name=\"_edn2\"><span><span><span>[2]<\/span><\/span><\/span><\/a> <span><span><a href=\"http:\/\/www.schoolbusproject.org\/\"><span>www.schoolbusproject.org\/<\/span><\/a><\/span><\/span> <\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est suite \u00e0 la destruction de la Jungle de Calais en 2016 que le gouvernement fran\u00e7ais a mis en \u0153uvre sa politique de z\u00e9ro tol\u00e9rance \u00e0 l\u2019\u00e9gard des camps, une politique qui veut que tout site informel d\u2019installation soit maintenant syst\u00e9matiquement d\u00e9truit par la police et les \u00e9quipes de \u00ab&nbsp;nettoyage&nbsp;\u00bb. L\u2019argument est que la France&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42362,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[108],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[568],"class_list":["post-42117","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-108","fmr_content_type-article","fmr_languages-french","fmr_list_years-568","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9coles de rue et Bus-\u00e9cole : des propositions d\u2019\u00e9ducation informelle en France - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9coles de rue et Bus-\u00e9cole : des propositions d\u2019\u00e9ducation informelle en France - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"C\u2019est suite \u00e0 la destruction de la Jungle de Calais en 2016 que le gouvernement fran\u00e7ais a mis en \u0153uvre sa politique de z\u00e9ro tol\u00e9rance \u00e0 l\u2019\u00e9gard des camps, une politique qui veut que tout site informel d\u2019installation soit maintenant syst\u00e9matiquement d\u00e9truit par la police et les \u00e9quipes de \u00ab&nbsp;nettoyage&nbsp;\u00bb. L\u2019argument est que la France&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-20T05:38:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/\",\"url\":\"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/\",\"name\":\"\u00c9coles de rue et Bus-\u00e9cole : des propositions d\u2019\u00e9ducation informelle en France - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2019-03-11T05:00:00+00:00\",\"dateModified\":\"2024-11-20T05:38:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FMR 60 &#8211; \u00c9ducation : besoins, droits et acc\u00e8s en d\u00e9placement\",\"item\":\"https:\/\/www.fmreview.org\/education-deplacement\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9coles de rue et Bus-\u00e9cole : des propositions d\u2019\u00e9ducation informelle en France\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9coles de rue et Bus-\u00e9cole : des propositions d\u2019\u00e9ducation informelle en France - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/","og_locale":"ar_AR","og_type":"article","og_title":"\u00c9coles de rue et Bus-\u00e9cole : des propositions d\u2019\u00e9ducation informelle en France - Forced Migration Review","og_description":"C\u2019est suite \u00e0 la destruction de la Jungle de Calais en 2016 que le gouvernement fran\u00e7ais a mis en \u0153uvre sa politique de z\u00e9ro tol\u00e9rance \u00e0 l\u2019\u00e9gard des camps, une politique qui veut que tout site informel d\u2019installation soit maintenant syst\u00e9matiquement d\u00e9truit par la police et les \u00e9quipes de \u00ab&nbsp;nettoyage&nbsp;\u00bb. L\u2019argument est que la France&hellip;","og_url":"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/","og_site_name":"Forced Migration Review","article_modified_time":"2024-11-20T05:38:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/","url":"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/","name":"\u00c9coles de rue et Bus-\u00e9cole : des propositions d\u2019\u00e9ducation informelle en France - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2019-03-11T05:00:00+00:00","dateModified":"2024-11-20T05:38:24+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/education-deplacement\/hagan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/education-deplacement\/hagan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/ar\/"},{"@type":"ListItem","position":2,"name":"FMR 60 &#8211; \u00c9ducation : besoins, droits et acc\u00e8s en d\u00e9placement","item":"https:\/\/www.fmreview.org\/education-deplacement\/"},{"@type":"ListItem","position":3,"name":"\u00c9coles de rue et Bus-\u00e9cole : des propositions d\u2019\u00e9ducation informelle en France"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/42117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/42117\/revisions"}],"predecessor-version":[{"id":42874,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/42117\/revisions\/42874"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content\/42362"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/media?parent=42117"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_themes?post=42117"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_region?post=42117"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_issue?post=42117"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_year?post=42117"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_content_type?post=42117"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_languages?post=42117"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/ar\/wp-json\/wp\/v2\/fmr_list_years?post=42117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}