{"id":41069,"date":"2019-03-11T00:00:00","date_gmt":"2019-03-11T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/mcevoy-2-2\/"},"modified":"2025-03-12T17:33:41","modified_gmt":"2025-03-12T22:33:41","slug":"mcevoy-2-2","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/es\/educacion-desplazamiento\/mcevoy-2-2\/","title":{"rendered":"Sentirse lo suficientemente seguro para aprender en una zona de conflicto"},"content":{"rendered":"<p><span><span><span><span>Con frecuencia, los programas psicosociales tradicionales se centran en incidentes que han ocurrido en el pasado y se implementan en espacios que ahora son f\u00edsicamente seguros. Sin embargo, en contextos de crisis prolongadas como el de Afganist\u00e1n, los ni\u00f1os no solo est\u00e1n lidiando con traumas pasados, sino tambi\u00e9n con estr\u00e9s y temor continuos. En estos contextos, la programaci\u00f3n psicosocial debe adoptar un enfoque diferente. El desarrollo de la sensaci\u00f3n de seguridad debe enfocarse en fortalecer la conciencia que tiene el ni\u00f1o acerca del riesgo y del estr\u00e9s, ense\u00f1ando competencias de resoluci\u00f3n de problemas individuales y creando una sensaci\u00f3n de seguridad a trav\u00e9s del juego, la expresi\u00f3n creativa y los ejercicios de confianza. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span>En Afganist\u00e1n, hay unos 767&nbsp;600 ni\u00f1os que han sido desplazados internamente por el conflicto<\/span><\/span><a href=\"#_edn1\" name=\"_ednref1\"><span><span><span><span><span><span>[1]<\/span><\/span><\/span><\/span><\/span><\/span><\/a><span><span>. Asegurar la continuidad de la educaci\u00f3n durante una crisis es vital para proporcionar rutinas y estructuras, permitir a los ni\u00f1os perseguir objetivos a m\u00e1s largo plazo y reducir el abandono de por vida de la educaci\u00f3n. El Consejo Noruego de Refugiados (NRC, por sus siglas en ingl\u00e9s) brinda educaci\u00f3n a miles de ni\u00f1os desplazados en Afganist\u00e1n, pero descubri\u00f3 que, con la mayor exposici\u00f3n en los \u00faltimos a\u00f1os a una violencia terrible, ahora es a\u00fan m\u00e1s dif\u00edcil que los ni\u00f1os se integren en su nuevo entorno y contin\u00faen motivados con su educaci\u00f3n<\/span><\/span><a href=\"#_edn2\" name=\"_ednref2\"><span><span><span><span><span><span>[2]<\/span><\/span><\/span><\/span><\/span><\/span><\/a><span><span>. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span>En respuesta, desde diciembre de 2017, el NRC de Afganist\u00e1n ha estado implementado un programa complementario en el aula dentro de las escuelas del pa\u00eds para abordar las necesidades psicosociales agudas de los ni\u00f1os afectados por traumas inducidos por el conflicto. Este programa \u2014the Better Learning Programme, BLP (Programa para un Mejor Aprendizaje)\u2014 fue desarrollado por el NRC y la Universidad de Troms\u00f8 en 2007 y fue probado primero en Uganda y despu\u00e9s en Palestina. El programa ayuda a los estudiantes a identificar sus reacciones al estr\u00e9s, aprender t\u00e9cnicas para calmarse y sentirse seguros, ser activos en su propia recuperaci\u00f3n y poder hablar con los maestros y sus familias acerca de sus problemas. Tambi\u00e9n busca desarrollar la resiliencia en la comunidad escolar, mediante el fortalecimiento de la colaboraci\u00f3n entre maestros y padres en el apoyo al bienestar de los alumnos.<\/span><\/span><\/span><\/span><\/p>\n<p><span><span><strong><span><span>Identificar el estr\u00e9s y sentirse seguro<\/span><\/span><\/strong><\/span><\/span><\/p>\n<p><span><span><span><span>Nuestra sensaci\u00f3n de seguridad generalmente se distorsiona despu\u00e9s de un evento posiblemente letal, y los sobrevivientes pueden sentirse aterrorizados ante el menor ruido o recordatorio sensorial. Los modelos para la recuperaci\u00f3n de traumas se enfocan en la necesidad de restablecer la sensaci\u00f3n de seguridad para recuperar el control sobre la respuesta psicol\u00f3gica del cuerpo ante eventos traum\u00e1ticos. A menudo, se alienta a los supervivientes a separar el pasado del presente, reconociendo que el evento potencialmente letal se encuentra en el pasado y que ahora, en el presente, est\u00e1n seguros. El programa BLP ense\u00f1a a los estudiantes a identificar las fuentes de estr\u00e9s, sus reacciones ante \u00e9l y su impacto f\u00edsico, y luego a aprender ejercicios pr\u00e1cticos tranquilizadores, como respiraci\u00f3n profunda, tensi\u00f3n y liberaci\u00f3n de los m\u00fasculos, equilibrios y varios estiramientos. Los ni\u00f1os practican estos ejercicios en cada sesi\u00f3n y se los alienta a practicarlos en el hogar y con sus padres. Estos ejercicios los ayudan a tomar el control de sus s\u00edntomas y a sentirse capaces de gestionar su propio estr\u00e9s. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span>Sin embargo, en Afganist\u00e1n, los riesgos relacionados con el conflicto contin\u00faan afectando a los ni\u00f1os, incluso cuando han sido desplazados a provincias m\u00e1s seguras. Es com\u00fan que en sus nuevas comunidades, los ni\u00f1os contin\u00faen escuchando salvas de cohetes o tiroteos, y alentar a los ni\u00f1os a que crean que ahora est\u00e1n seguros podr\u00eda, en realidad, ser perjudicial y dejarlos vulnerables a otros traumas si experimentaran otro incidente o si se vieran obligados a mudarse otra vez. Un ejercicio, llamado \u201cespacio seguro\u201d, ayuda a los ni\u00f1os a visualizar un lugar real o imaginario donde se sienten seguros, experimentando e interiorizando de esta manera una sensaci\u00f3n de seguridad. El objetivo de este tipo de ejercicios es ayudar a los estudiantes a lidiar no solo con las pesadillas o recuerdos intrusivos, sino tambi\u00e9n con sonidos angustiantes, rumores o experiencias con las que se topan en su vida cotidiana. Se alent\u00f3 a los ni\u00f1os a usar los ejercicios cuando los despertaba una explosi\u00f3n durante la noche (siempre y cuando no estuvieran en peligro inmediato) y al hacerlo, se sent\u00edan capaces de permanecer en calma cuando hab\u00eda combates en distritos cercanos.<\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span>\u201c<em>Amo el espacio seguro. Simplemente cerrar los ojos y pensar en alg\u00fan lugar calmo y seguro, alg\u00fan lugar lindo&#8230; Es incre\u00edble.\u201d<\/em> <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><strong><span><span>Mantener la seguridad f\u00edsica <\/span><\/span><\/strong><\/span><\/span><\/p>\n<p><span><span><span><span>En la fase piloto del BLP, se observ\u00f3 que los ni\u00f1os se sent\u00edan seguros durante la sesi\u00f3n, pero luego atravesar\u00edan situaciones aterradoras fuera del aula. En el camino a la escuela, los ni\u00f1os se enfrentan a la posibilidad de ser secuestrados o de encontrarse en enfrentamientos armados o explosiones, minas terrestres, acoso de miembros de la comunidad y accidentes de tr\u00e1nsito. Tambi\u00e9n hay altos niveles de maltrato en el hogar y trabajo infantil. Decirles a los ni\u00f1os que est\u00e1n seguros cuando habitualmente se enfrentan a numerosos riesgos puede desempoderarlos y tomarlos desprevenidos. En la segunda fase del desarrollo del BLP, por lo tanto, se a\u00f1adi\u00f3 una sesi\u00f3n nueva para ayudar a los ni\u00f1os a ser conscientes de los riesgos en sus comunidades y a identificar las medidas para mantenerse a salvo, tal como caminar en grupos a la escuela o identificar rutas alternativas. Se alienta a los ni\u00f1os a dibujar un mapa de su comunidad y a abordar los riesgos potenciales; con el apoyo del maestro, pueden explorar maneras de mantenerse a salvo. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span>La combinaci\u00f3n de soluciones pr\u00e1cticas a problemas reales y estrategias de resoluci\u00f3n de problemas para lidiar con el impacto emocional ha ayudado a aumentar la sensaci\u00f3n de seguridad de los estudiantes. Mientras tanto, los maestros tambi\u00e9n hallaron que la sesi\u00f3n era \u00fatil para ayudarlos a entender mejor los riesgos particulares que enfrentan los estudiantes individuales y las diferentes formas que tienen de apoyarlos. Los estudiantes tambi\u00e9n tuvieron m\u00e1s confianza para pedir apoyo a los adultos acerca de los riesgos en la comunidad. Sin embargo, la nueva sesi\u00f3n requiere de mayor evaluaci\u00f3n para determinar la efectividad de las estrategias de mitigaci\u00f3n de riesgos. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><strong><span><span>Crear seguridad a trav\u00e9s del juego <\/span><\/span><\/strong><\/span><\/span><\/p>\n<p><span><span><span><span>Para muchos ni\u00f1os en Afganist\u00e1n, es dif\u00edcil encontrar un lugar que sea f\u00edsicamente seguro del todo y\/o apto para ni\u00f1os. El BLP, por lo tanto, busc\u00f3 ayudar a los ni\u00f1os a experimentar una sensaci\u00f3n de seguridad que no dependiera del ambiente f\u00edsico. Cada sesi\u00f3n de BLP segu\u00eda el mismo patr\u00f3n todas las semanas para desarrollar familiaridad y previsibilidad, y los ejercicios creativos y juegos formaron una parte esencial de la rutina semanal. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span>Jugar es esencial para el desarrollo de los ni\u00f1os y tambi\u00e9n crea y fortalece la sensaci\u00f3n de seguridad. Jugar ayuda a los ni\u00f1os a procesar y a expresar las emociones en forma medida, y puede ayudar a elevar su autoestima. Aun as\u00ed, muchos ni\u00f1os de Afganist\u00e1n tienen pocas o ninguna oportunidad de jugar, incluso en la escuela. Los m\u00e9todos de ense\u00f1anza tienden a ser bastante tradicionales, los docentes transmiten conocimientos mientras los estudiantes toman notas. Al inicio de la implementaci\u00f3n del BLP, los maestros tend\u00edan a hablar mucho, explicar los conceptos del programa, lo cual reduc\u00eda el tiempo y el espacio disponible para que los ni\u00f1os se expresaran. A medida que se desarroll\u00f3 el programa, se introdujeron juegos en todas las sesiones. Esto tuvo dos objetivos. El primero era ayudar a los estudiantes y a los maestros a relajarse y a aumentar la sensaci\u00f3n de confianza y seguridad dentro del grupo. El segundo objetivo era asegurar que los ni\u00f1os salieran de la sesi\u00f3n sinti\u00e9ndose bien. A la luz de la falta de servicios y redes de apoyo en las comunidades de los ni\u00f1os \u2014incluyendo el acceso extremadamente limitado a cualquier forma de asesoramiento psicol\u00f3gico\u2014 fue importante asegurar que si durante las sesiones emerg\u00edan emociones o recuerdos dif\u00edciles, se pudiera usar un juego para ayudar a sacudir sentimientos inc\u00f3modos. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span>Desde la introducci\u00f3n de los juegos en cada sesi\u00f3n, hubo un cambio notorio entre estudiantes y maestros, en particular, en el nivel de risa y tranquilidad en el aula y el estrecho v\u00ednculo dentro del grupo. Los maestros expresaron cu\u00e1nto disfrutaban ver re\u00edr a sus estudiantes y c\u00f3mo hab\u00eda aumentado su confianza como maestros. Las observaciones demostraron que la sensaci\u00f3n de seguridad de los estudiantes aument\u00f3 y que pod\u00edan expresar sus sentimientos y recibir ayuda para gestionarlos; ni\u00f1os a los que se observ\u00f3 llorando en el medio de la sesi\u00f3n mientras compart\u00edan una historia terminaron la sesi\u00f3n riendo y sonriendo despu\u00e9s de participar en un juego grupal. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><strong><span><span>Impacto e implementaci\u00f3n<\/span><\/span><\/strong><\/span><\/span><span><span>&nbsp;<\/span><\/span><\/p>\n<p><span><span><span><span>El programa BLP se puede implementar casi en cualquier sitio e incluso cuando se deben reubicar las clases debido a problemas de seguridad, se puede desarrollar la sensaci\u00f3n de seguridad porque depende de la confianza del grupo y no del espacio f\u00edsico<\/span><\/span><a href=\"#_edn3\" name=\"_ednref3\"><span><span><span><span><span><span>[3]<\/span><\/span><\/span><\/span><\/span><\/span><\/a><span><span>. A la fecha, la evaluaci\u00f3n del programa indic\u00f3 una reducci\u00f3n de las pesadillas, emociones angustiantes y enfermedades f\u00edsicas, un incremento en el inter\u00e9s por asistir a la escuela y completar la tarea y, tal vez lo que es m\u00e1s importante, una mayor sensaci\u00f3n de seguridad. El 78&nbsp;% de los ni\u00f1os que hab\u00eda participado en el BLP dijo que se sent\u00eda menos asustado debido al grupo de BLP. Los estudiantes consideraron al BLP como un espacio donde se sent\u00edan c\u00f3modos, relajados y seguros y dijeron que pod\u00edan acceder a estos sentimientos en casa, en cualquier momento, al practicar los ejercicios del BLP, ya sea solos, o con amigos y familia. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span>Implementar el BLP en Afganist\u00e1n ha requerido de varias rondas de adaptaci\u00f3n y todav\u00eda estamos en proceso de desarrollar los planes de la sesi\u00f3n y capacitaci\u00f3n docente, como tambi\u00e9n considerar la manera de involucrar mejor a los padres y a la comunidad general. Continuar\u00e1 requiriendo mayor adaptaci\u00f3n y fortalecimiento a la luz de la seguridad en deterioro de Afganist\u00e1n. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"EN-US\"><span>Bethan McEvoy <em><span><a href=\"mailto:bethan.mcevoy@nrc.no\"><span>bethan.mcevoy@nrc.no<\/span><\/a><\/span> <\/em><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span>Asesora en educaci\u00f3n, Consejo Noruego para los Refugiados, Afganist\u00e1n <em><span><a href=\"http:\/\/www.nrc.no\"><span>www.nrc.no<\/span><\/a><\/span><\/em> <\/span><\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span><span><a href=\"#_ednref1\" name=\"_edn1\"><span><span><span lang=\"EN-US\"><span>[1]<\/span><\/span><\/span><\/span><\/a> <span lang=\"EN-US\"><span>Desde septiembre de 2018<\/span><\/span>.<\/span><\/span><\/p>\n<p><span><span><a href=\"#_ednref2\" name=\"_edn2\"><span><span lang=\"EN-US\"><span><span><span lang=\"EN-US\"><span>[2]<\/span><\/span><\/span><\/span><\/span><\/span><\/a><span lang=\"EN-US\"><span> NRC (2018) <em>Education in Emergencies; Children in Distress. A Child Protection Risk Analysis for NRC Afghanistan\u2019s Education Programme<\/em>.<\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span><span lang=\"EN-US\"><span><a href=\"http:\/\/www.nrc.no\/resources\/reports\/education-in-emer%20gencies-children-in-distressnew-page\/\">www.nrc.no\/resources\/reports\/education-in-emer gencies-children-in-distressnew-page\/<\/a><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><a href=\"#_ednref3\" name=\"_edn3\"><span><span lang=\"EN-US\"><span><span><span lang=\"EN-US\"><span>[3]<\/span><\/span><\/span><\/span><\/span><\/span><\/a><span lang=\"ES-MX\"><span> Para obtener m\u00e1s informaci\u00f3n sobre el BLP del NRC contacte con <span><a href=\"mailto:sonia.gomez@nrc.no\"><span>sonia.gomez@nrc.no<\/span><\/a><\/span>. <\/span><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con frecuencia, los programas psicosociales tradicionales se centran en incidentes que han ocurrido en el pasado y se implementan en espacios que ahora son f\u00edsicamente seguros. Sin embargo, en contextos de crisis prolongadas como el de Afganist\u00e1n, los ni\u00f1os no solo est\u00e1n lidiando con traumas pasados, sino tambi\u00e9n con estr\u00e9s y temor continuos. En estos&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42712,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[108],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[38],"fmr_list_years":[568],"class_list":["post-41069","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-108","fmr_content_type-article","fmr_languages-spanish","fmr_list_years-568","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sentirse lo suficientemente seguro para aprender en una zona de conflicto - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sentirse lo suficientemente seguro para aprender en una zona de conflicto - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"Con frecuencia, los programas psicosociales tradicionales se centran en incidentes que han ocurrido en el pasado y se implementan en espacios que ahora son f\u00edsicamente seguros. Sin embargo, en contextos de crisis prolongadas como el de Afganist\u00e1n, los ni\u00f1os no solo est\u00e1n lidiando con traumas pasados, sino tambi\u00e9n con estr\u00e9s y temor continuos. En estos&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T22:33:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/\",\"url\":\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/\",\"name\":\"Sentirse lo suficientemente seguro para aprender en una zona de conflicto - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2019-03-11T05:00:00+00:00\",\"dateModified\":\"2025-03-12T22:33:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RMF 60 &#8211; Educaci\u00f3n: necesidades, derechos y acceso en el desplazamiento\",\"item\":\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sentirse lo suficientemente seguro para aprender en una zona de conflicto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sentirse lo suficientemente seguro para aprender en una zona de conflicto - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/","og_locale":"es_ES","og_type":"article","og_title":"Sentirse lo suficientemente seguro para aprender en una zona de conflicto - Forced Migration Review","og_description":"Con frecuencia, los programas psicosociales tradicionales se centran en incidentes que han ocurrido en el pasado y se implementan en espacios que ahora son f\u00edsicamente seguros. Sin embargo, en contextos de crisis prolongadas como el de Afganist\u00e1n, los ni\u00f1os no solo est\u00e1n lidiando con traumas pasados, sino tambi\u00e9n con estr\u00e9s y temor continuos. En estos&hellip;","og_url":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-03-12T22:33:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/","url":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/","name":"Sentirse lo suficientemente seguro para aprender en una zona de conflicto - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2019-03-11T05:00:00+00:00","dateModified":"2025-03-12T22:33:41+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/mcevoy-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/es\/"},{"@type":"ListItem","position":2,"name":"RMF 60 &#8211; Educaci\u00f3n: necesidades, derechos y acceso en el desplazamiento","item":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/"},{"@type":"ListItem","position":3,"name":"Sentirse lo suficientemente seguro para aprender en una zona de conflicto"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41069\/revisions"}],"predecessor-version":[{"id":44645,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41069\/revisions\/44645"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/42712"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/media?parent=41069"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_themes?post=41069"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_region?post=41069"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_issue?post=41069"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_year?post=41069"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content_type?post=41069"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_languages?post=41069"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_list_years?post=41069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}