{"id":41070,"date":"2019-03-11T00:00:00","date_gmt":"2019-03-11T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/khaddour-2-2\/"},"modified":"2025-03-12T17:33:41","modified_gmt":"2025-03-12T22:33:41","slug":"khaddour-2-2","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/es\/educacion-desplazamiento\/khaddour-2-2\/","title":{"rendered":"El desarrollo de la primera infancia y el apoyo psicol\u00f3gico en Siria"},"content":{"rendered":"<p><span>Desde el comienzo de la crisis siria, los desplazados internos de toda Siria buscaron un refugio seguro en el distrito de Salam\u00ede, al este de la gobernaci\u00f3n de Hama, aumentando la poblaci\u00f3n en un 40&nbsp;% hasta su total actual de 300&nbsp;000. Muchos de los desplazados \u2014incluyendo ni\u00f1os\u2014 sufr\u00edan de traumas graves. Los actores humanitarios en la ciudad de Salam\u00ede, incluyendo la Media Luna Roja \u00c1rabe Siria (MLRAS) y la Red de Desarrollo Aga Khan (AKDN, por sus siglas en ingl\u00e9s), desplegaron equipos de apoyo psicosocial, pero los encargados pronto se dieron cuenta de que no estaban preparados para abordar la considerable amplitud de las necesidades de salud mental. <\/span><\/p>\n<p><span>&nbsp;La AKDN, por lo tanto, desarroll\u00f3 un plan estrat\u00e9gico para brindar apoyo psicosocial completo en el distrito de Salam\u00ede, usando enfoques comunitarios sostenibles a la salud mental y al apoyo psicosocial. Adem\u00e1s de la promoci\u00f3n y la generaci\u00f3n de conciencia acerca de la salud mental y el apoyo psicosocial en contextos de conflicto, y el fortalecimiento de las capacidades en t\u00e9rminos de competencias y cantidad de trabajadores de la salud mental, el plan tambi\u00e9n incorpor\u00f3 elementos de protecci\u00f3n espec\u00edficamente dise\u00f1ados para ni\u00f1os. Estos incluyeron la provisi\u00f3n de espacios y apoyo amigables no formales para ayudar a los ni\u00f1os a desarrollar mecanismos de resoluci\u00f3n de problemas, as\u00ed como actividades para ayudar a los adultos a entender el desarrollo psicol\u00f3gico, social, cognitivo, motor y ling\u00fc\u00edstico de sus hijos. <\/span><\/p>\n<p><span><span>&nbsp;<\/span><\/span><strong><span lang=\"EN-US\">Me and My Child in Crisis<\/span><\/strong><\/p>\n<p><span lang=\"EN-US\">&nbsp;<\/span><span>Uno de los elementos clave del plan estrat\u00e9gico fue el programa Me and My Child in Crisis (MMIC), que integr\u00f3 el apoyo psicosocial en la programaci\u00f3n bien establecida del desarrollo de la primera infancia (DPI) en la AKDN. En un principio, el programa MMIC se estableci\u00f3 con el objetivo de ofrecer sesiones para padres, donde los padres de desplazados internos y de la comunidad de acogida pudieran reunirse en un espacio seguro y amigable, donde pudieran hablar acerca de sus experiencias traum\u00e1ticas (como la muerte, p\u00e9rdida, dolor, conmoci\u00f3n y los desaf\u00edos que afrontan al criar a sus hijos en entornos estresantes). Durante las sesiones, se puso de manifiesto que los padres no pod\u00edan manejar la presi\u00f3n de lidiar con los traumas de sus hijos, adem\u00e1s del estr\u00e9s que ellos mismos enfrentaban; como consecuencia, este grupo de ni\u00f1os estaba cada vez m\u00e1s desatendido y, por lo tanto, m\u00e1s vulnerable. &nbsp;<\/span><\/p>\n<p><span>Dirigido a padres y sus hijos de hasta ocho a\u00f1os, el programa MMIC busc\u00f3 introducir los conceptos de DPI y ense\u00f1ar m\u00e9todos para brindar apoyo psicosocial a los ni\u00f1os. El proyecto tambi\u00e9n present\u00f3 una oportunidad para facilitar mejores relaciones entre los desplazados internos y las comunidades de acogida, permiti\u00e9ndoles sentarse a hablar sobre los desaf\u00edos de adaptarse a sus nuevas situaciones,<span> en un espacio seguro, junto a personas con las que pod\u00edan identificarse.<\/span><\/span><\/p>\n<p><span>&nbsp;Los padres aprendieron acerca de aspectos como la importancia del crecimiento y del desarrollo temprano del ni\u00f1o, el desarrollo del cerebro, m\u00e9todos de \u201caprendizaje activo\u201d, caracter\u00edsticas de la primera infancia, ventajas de la crianza comprometida, apoyo psicosocial para padres y ni\u00f1os, competencias de comunicaci\u00f3n efectivas para ni\u00f1os y la noci\u00f3n de disciplina positiva. En paralelo, se inscribi\u00f3 a los ni\u00f1os en actividades relacionadas. Por ejemplo, se les pidi\u00f3 a los ni\u00f1os que crearan historias que luego se compart\u00edan con sus padres, como una forma de que los ni\u00f1os se expresen y que los padres entiendan qu\u00e9 ocurre en la mente de sus hijos. Otro ejercicio fue el \u201c\u00e1rbol de la seguridad\u201d, donde los ni\u00f1os escrib\u00edan los nombres de los familiares de confianza como ramas de un \u00e1rbol, ayudando a sus padres a entender qui\u00e9n exactamente hace sentir a sus hijos m\u00e1s seguros. &nbsp;<\/span><\/p>\n<p><strong><span>Adaptaci\u00f3n para sostenibilidad a largo plazo<\/span><\/strong><span>&nbsp;<\/span><\/p>\n<p><span>A medida que aumentaba el n\u00famero de participantes, deb\u00eda considerarse la sostenibilidad del proyecto a largo plazo. Los administradores del proyecto consultaron las Normas M\u00ednimas de la Red Interagencial para la Educaci\u00f3n en Situaciones de Emergencia (INEE, por sus siglas en ingl\u00e9s)<\/span><a href=\"#_edn1\" name=\"_ednref1\"><span><span><span><!--[if !supportFootnotes]--><span><span>[1]<\/span><\/span><!--[endif]--><\/span><\/span><\/span><\/a><span>, dos de las cuales eran particularmente pertinentes al programa MMIC: la combinaci\u00f3n de la asistencia en situaci\u00f3n de emergencia con la recuperaci\u00f3n temprana, y la promoci\u00f3n de las iniciativas educativas comunitarias. Como resultado, el proyecto recurri\u00f3 a asociaciones de padres y docentes en las escuelas como medio de implementaci\u00f3n. Al hacerlo, el proyecto alcanz\u00f3 a m\u00e1s padres y ni\u00f1os (de desplazados internos y comunidades de acogida), lo que aument\u00f3 la conciencia del DPI y la contribuci\u00f3n del apoyo psicosocial en las vidas de los ni\u00f1os. Sin embargo, esto plante\u00f3 varios desaf\u00edos. &nbsp;<\/span><\/p>\n<p><span>En primer lugar, algunos padres no ten\u00edan las competencias correctas para entregar la informaci\u00f3n incluida en los materiales de capacitaci\u00f3n, especialmente conceptos espec\u00edficos de la educaci\u00f3n. Adem\u00e1s, no todos los facilitadores estaban comprometidos con la capacitaci\u00f3n voluntaria, sin incentivo econ\u00f3mico. En segundo lugar, los facilitadores conduc\u00edan las sesiones de MMIC en las escuelas, pero no todas ellas ten\u00edan los recursos necesarios, como proyectores, electricidad o calefacci\u00f3n. Y, en tercer lugar, los materiales de capacitaci\u00f3n introduc\u00edan caracter\u00edsticas de la primera infancia para todas las edades hasta los ocho a\u00f1os, pero a los padres de los ni\u00f1os en edad escolar (6\u201312) los debates sobre el desarrollo del cerebro de lactantes les result\u00f3 irrelevante.&nbsp;<\/span><\/p>\n<p><span>En consecuencia, se simplific\u00f3 el contenido del proyecto y se capacit\u00f3 a los facilitadores del MMIC en la ense\u00f1anza de temas relacionados a las edades 6\u201312, mientras que las necesidades de los ni\u00f1os m\u00e1s peque\u00f1os fueron abordadas a trav\u00e9s de otras iniciativas de la AKDN. Se puso un mayor \u00e9nfasis en el uso de actividades interactivas para brindar apoyo psicosocial a ni\u00f1os y padres. El proyecto ayud\u00f3 a los padres a mejorar su conocimiento del DPI y la importancia del apoyo psicosocial, puso los conceptos de DPI y apoyo psicosocial en pr\u00e1ctica (por ejemplo, permitir que un ni\u00f1o llore cuando est\u00e1 triste) y crear mejores canales de comunicaci\u00f3n con sus hijos (por ejemplo, usar m\u00e9todos de disciplina positivos).<span>&nbsp;<\/span><\/span><\/p>\n<p><span>Desde su establecimiento, el proyecto present\u00f3 otro desaf\u00edo importante: la falta de participaci\u00f3n de los padres varones. Esto se relaciona con una cantidad de factores, incluyendo la creencia de que la madre es la responsable del cuidado del ni\u00f1o, la ausencia f\u00edsica de los padres (muchos de los cuales est\u00e1n combatiendo en la guerra, en la cual muchos otros fueron asesinados) y la creciente presi\u00f3n sobre los hombres para trabajar (dada la situaci\u00f3n econ\u00f3mica decreciente). Las sesiones de MMIC fueron realizadas por facilitadores que en s\u00ed mismos eran parejas casadas, para alentar a los padres a participar como parejas, pero la falta de participaci\u00f3n de los hombres continu\u00f3. Entre 2014 y 2018, participaron 2216 padres, de los cuales solo 131 eran hombres.<\/span><\/p>\n<p><span>&nbsp;<\/span><strong><span>Avanzar hacia la recuperaci\u00f3n<\/span><\/strong><span>&nbsp;<\/span><\/p>\n<p><span>Cuando disminuy\u00f3 la intensidad del conflicto armado en 2018, el nombre del proyecto \u2014<span>Me and My Child in Crisis<\/span>\u2014 empez\u00f3 a percibirse como asociado con una fase de la crisis anterior, particularmente dif\u00edcil. Por lo tanto, se revis\u00f3 el contenido de MMIC para ajustarse a la fase de recuperaci\u00f3n (aunque no debe olvidarse que contin\u00faa habiendo necesidades de apoyo psicosocial muy serias para desplazados internos, repatriados y comunidades de acogida) y se transform\u00f3 en el programa <span>Reading with Children<\/span> (RWC, por sus siglas en ingl\u00e9s).<\/span><\/p>\n<p><span>&nbsp;El objetivo de RWC es sensibilizar a los padres acerca del papel de la lectura en el desarrollo de las competencias ling\u00fc\u00edsticas de sus hijos y la importancia de establecer h\u00e1bitos de lectura como parte de la rutina diaria de los ni\u00f1os. Tambi\u00e9n abarca temas de apoyo psicosocial para padres y ni\u00f1os (como la disciplina positiva). El proyecto presta 15 libros de cuentos a los padres para que los lean con sus hijos en el hogar. &nbsp;<\/span><\/p>\n<p><span>El proyecto tambi\u00e9n ayuda a los padres a preparar psicol\u00f3gicamente a sus hijos para la escuela a trav\u00e9s del calendario del proyecto <span>I Am Ready for School<\/span> y sumerge a los padres, maestros y ni\u00f1os en actividades interactivas durante la primera semana de escuela, para que los ni\u00f1os se sientan seguros durante su familiarizaci\u00f3n con los nuevos entornos y con los maestros. Entre marzo y agosto de 2018, 375 ni\u00f1os y 323 padres participaron del programa RWC (aunque la participaci\u00f3n de los hombr<span>es<\/span> contin\u00faa siendo baja).&nbsp;<\/span><\/p>\n<p><strong><span>Desaf\u00edos y opciones<\/span><\/strong><span>&nbsp;<\/span><\/p>\n<p><span>Un desaf\u00edo notable fue asegurar la asistencia continua. Los \u00edndices de asistencia para padres y facilitadores en MMIC y RWC fueron inestables. Para mejorar la participaci\u00f3n en el programa en contextos donde los recursos econ\u00f3micos de las personas fueron decreciendo, se recomienda fervorosamente ofrecer incentivos. El tipo de incentivo ofrecido puede ser <span>usado en conjunto con otros programas humanitarios<\/span> y pueden estar basados en la necesidad y adecuados al contexto, ya sea dinero en efectivo, cupones o alimentos, art\u00edculos no alimentarios (equipos de agua,&nbsp;saneamiento&nbsp;e higiene, o de invierno) o cestas para ni\u00f1os (que incluyan art\u00edculos como libros de cuentos, ropa interior, uniforme escolar y suplementos nutritivos). <span>Brindar incentivos desde el comienzo de un proyecto (en vez de en la mitad) ayudar\u00e1 a asegurar que la entrega de apoyo psicosocial y DPI se mantenga desde el nacimiento hasta la ni\u00f1ez, y en adelante. Aunque la AKDN en Siria realmente no aplic\u00f3 un enfoque basado en incentivos, a partir de la observaci\u00f3n de las experiencias de los actores de todo el mundo que usan dinero en efectivo o incentivos alimentarios, parece ser un abordaje que vale la pena considerar.<\/span><\/span><\/p>\n<p><span>&nbsp;Otra opci\u00f3n que se podr\u00eda explorar es el uso de tecnolog\u00eda m\u00f3vil y aplicaciones para facilitar el acceso parental a los productos de DPI. Como se mencion\u00f3 anteriormente, muchos padres, especialmente los hombres, no pudieron asistir a las sesiones debido a compromisos laborales. Proporcionar plataformas m\u00f3viles o utilizar aquellas que se usan com\u00fanmente (como WhatsApp o Facebook) podr\u00eda mejorar la cobertura y el acceso. Por ejemplo: una aplicaci\u00f3n gratuita podr\u00eda ofrecer videos de aprendizaje, mensajes de sensibilizaci\u00f3n y discusiones grupales interactivas; las p\u00e1ginas de Facebook permiten al personal del programa publicar temas y los lectores pueden debatirlos y formular preguntas; en WhatsApp, se pueden enviar mensajes de sensibilizaci\u00f3n a los grupos de participantes que pueden, a su vez, reenviarlos; y se puede contratar a proveedores locales de servicios m\u00f3viles para enviar mensajes SMS acerca de DPI para alcanzar a todos aquellos que viven en ciertas zonas. (La Fundaci\u00f3n Aga Khan ya utiliza los mensajes SMS como parte de su campa\u00f1a de sensibilizaci\u00f3n sobre la salud). Dichas iniciativas podr\u00edan funcionar bien en el contexto sirio, dada la gran cantidad de hogares que cuentan con dispositivos m\u00f3viles.&nbsp;<\/span><\/p>\n<p><span>En la actualidad, la AKDN trabaja con actores gubernamentales y no gubernamentales para establecer un marco de DPI nacional. El \u00e9xito de la programaci\u00f3n del apoyo psicosocial para ni\u00f1os en el distrito de Salam\u00ede durante la crisis se debi\u00f3, en parte, al hecho de que la programaci\u00f3n de DPI estaba bien establecida en esta zona antes de la crisis. Para las comunidades vulnerables al conflicto y los desaf\u00edos de salud mental posteriores, la programaci\u00f3n de DPI puede, al menos, proporcionar la infraestructura a partir de la cual construir la programaci\u00f3n en materia de <\/span><span>salud mental y apoyo psicosocial<span>, a fin de ayudar a mitigar y lidiar con las condiciones de salud mental, incluyendo el inicio de traumas graves. <\/span><\/span><\/p>\n<p><span><span>&nbsp;<\/span><\/span><\/p>\n<p><span lang=\"EN-US\">Fatima Khaddour <em><span><a href=\"mailto:fatima.khaddour89@gmail.com\"><span>fatima.khaddour89@gmail.com<\/span><\/a><\/span> <\/em><\/span><\/p>\n<p><span>Oficial de proyectos, Fundaci\u00f3n Aga Khan en Siria <em><span><a href=\"http:\/\/www.akdn.org\"><span>www.akdn.org<\/span><\/a><\/span><\/em> <\/span><\/p>\n<p><!--[if !supportEndnotes]--><!--[endif]--><\/p>\n<p><a href=\"#_ednref1\" name=\"_edn1\"><span><span lang=\"EN-CA\"><span><!--[if !supportFootnotes]--><span><span lang=\"EN-CA\">[1]<\/span><\/span><!--[endif]--><\/span><\/span><\/span><\/a><span lang=\"ES-MX\"> Las Normas M\u00ednimas de la INEE articulan el nivel m\u00ednimo de calidad y acceso educativo en emergencias hacia la recuperaci\u00f3n, presentando mejores pr\u00e1cticas para satisfacer los derechos educativos y las necesidades de las personas afectadas por las cat\u00e1strofes y las crisis. <\/span><\/p>\n<p><span lang=\"ES-MX\"><a href=\"http:\/\/www.ineesite.org\/en\/minimum-standards\/translations\"><span>www.ineesite.org\/en\/minimum-standards\/translations<\/span><\/a><\/span><span lang=\"ES-MX\"> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el comienzo de la crisis siria, los desplazados internos de toda Siria buscaron un refugio seguro en el distrito de Salam\u00ede, al este de la gobernaci\u00f3n de Hama, aumentando la poblaci\u00f3n en un 40&nbsp;% hasta su total actual de 300&nbsp;000. Muchos de los desplazados \u2014incluyendo ni\u00f1os\u2014 sufr\u00edan de traumas graves. Los actores humanitarios en&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42712,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[108],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[38],"fmr_list_years":[568],"class_list":["post-41070","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-108","fmr_content_type-article","fmr_languages-spanish","fmr_list_years-568","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El desarrollo de la primera infancia y el apoyo psicol\u00f3gico en Siria - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El desarrollo de la primera infancia y el apoyo psicol\u00f3gico en Siria - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"Desde el comienzo de la crisis siria, los desplazados internos de toda Siria buscaron un refugio seguro en el distrito de Salam\u00ede, al este de la gobernaci\u00f3n de Hama, aumentando la poblaci\u00f3n en un 40&nbsp;% hasta su total actual de 300&nbsp;000. Muchos de los desplazados \u2014incluyendo ni\u00f1os\u2014 sufr\u00edan de traumas graves. Los actores humanitarios en&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T22:33:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/\",\"url\":\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/\",\"name\":\"El desarrollo de la primera infancia y el apoyo psicol\u00f3gico en Siria - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2019-03-11T05:00:00+00:00\",\"dateModified\":\"2025-03-12T22:33:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RMF 60 &#8211; Educaci\u00f3n: necesidades, derechos y acceso en el desplazamiento\",\"item\":\"https:\/\/www.fmreview.org\/educacion-desplazamiento\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El desarrollo de la primera infancia y el apoyo psicol\u00f3gico en Siria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El desarrollo de la primera infancia y el apoyo psicol\u00f3gico en Siria - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/","og_locale":"es_ES","og_type":"article","og_title":"El desarrollo de la primera infancia y el apoyo psicol\u00f3gico en Siria - Forced Migration Review","og_description":"Desde el comienzo de la crisis siria, los desplazados internos de toda Siria buscaron un refugio seguro en el distrito de Salam\u00ede, al este de la gobernaci\u00f3n de Hama, aumentando la poblaci\u00f3n en un 40&nbsp;% hasta su total actual de 300&nbsp;000. Muchos de los desplazados \u2014incluyendo ni\u00f1os\u2014 sufr\u00edan de traumas graves. Los actores humanitarios en&hellip;","og_url":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-03-12T22:33:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/","url":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/","name":"El desarrollo de la primera infancia y el apoyo psicol\u00f3gico en Siria - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2019-03-11T05:00:00+00:00","dateModified":"2025-03-12T22:33:41+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/khaddour-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/es\/"},{"@type":"ListItem","position":2,"name":"RMF 60 &#8211; Educaci\u00f3n: necesidades, derechos y acceso en el desplazamiento","item":"https:\/\/www.fmreview.org\/educacion-desplazamiento\/"},{"@type":"ListItem","position":3,"name":"El desarrollo de la primera infancia y el apoyo psicol\u00f3gico en Siria"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41070\/revisions"}],"predecessor-version":[{"id":44646,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41070\/revisions\/44646"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/42712"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/media?parent=41070"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_themes?post=41070"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_region?post=41070"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_issue?post=41070"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_year?post=41070"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content_type?post=41070"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_languages?post=41070"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_list_years?post=41070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}