{"id":41696,"date":"2015-12-15T00:00:00","date_gmt":"2015-12-15T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/montenegro-2-3\/"},"modified":"2025-04-01T07:27:40","modified_gmt":"2025-04-01T12:27:40","slug":"montenegro-2-3","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/es\/destination-europe-fr\/montenegro-2-3\/","title":{"rendered":"La protection sociale : une quatri\u00e8me solution durable ?"},"content":{"rendered":"<p>Un projet pilote intitul&eacute; &laquo;&nbsp;Mobilit&eacute; r&eacute;gionale et int&eacute;gration socio-&eacute;conomique des r&eacute;fugi&eacute;s&nbsp;&raquo; a &eacute;t&eacute; propos&eacute; en 2014 dans le cadre de la D&eacute;claration et du Plan d&rsquo;action du Br&eacute;sil.<a href=\"#_edn1\" name=\"_ednref1\" title=\"\"><sup><sup>[1]<\/sup><\/sup><\/a> Dans la pratique, ce projet vise &agrave; faire venir au Br&eacute;sil des r&eacute;fugi&eacute;s colombiens actuellement en &Eacute;quateur. Sur une p&eacute;riode de deux ans, 200 personnes se rendraient &agrave; Paran&aacute;, dans le sud du Br&eacute;sil, pour y travailler, selon des modalit&eacute;s d&rsquo;emploi garanties par les autorit&eacute;s br&eacute;siliennes. En plus de leur salaire, une assistance financi&egrave;re suppl&eacute;mentaire serait apport&eacute;e par l&rsquo;UNHCR, sur une courte p&eacute;riode de trois mois, aux familles colombiennes (compos&eacute;es d&rsquo;une &agrave; cinq personnes) &eacute;tablies en &Eacute;quateur et dont au moins l&rsquo;un des membres est en &acirc;ge de travailler (entre 18 et 45 ans). Via des partenariats avec des acteurs priv&eacute;s locaux, des emplois ont &eacute;t&eacute; identifi&eacute;s dans le secteur des services, la construction, l&rsquo;agroalimentaire, le textile et les supermarch&eacute;s.<\/p>\n<p>Les autorit&eacute;s br&eacute;siliennes reconna&icirc;traient ces familles comme des r&eacute;fugi&eacute;s, dont la protection serait assur&eacute;e et qui auraient &eacute;galement la possibilit&eacute; de d&eacute;poser une demande de r&eacute;sidence dans le pays. Une telle solution est possible car, depuis 2013, le Br&eacute;sil et l&rsquo;&Eacute;quateur sont parties &agrave; l&rsquo;accord de visa du Mercosur, selon lequel les r&eacute;sidents des pays membres du bloc r&eacute;gional<a href=\"#_edn2\" name=\"_ednref2\" title=\"\">[2]<\/a> ont le droit de r&eacute;sider dans n&rsquo;importe lequel des pays signataires, sans aucune r&eacute;f&eacute;rence &agrave; leur statut migratoire.<\/p>\n<p>Ce projet pilote porte int&eacute;gralement sur la mobilit&eacute; du travail et &eacute;largit clairement la protection des r&eacute;fugi&eacute;s au-del&agrave; du niveau juridique, jusqu&rsquo;au niveau de la protection sociale. Au d&eacute;part, ce projet pilote &eacute;tait pr&eacute;sent&eacute; comme une quatri&egrave;me solution mais, ult&eacute;rieurement, il a plut&ocirc;t &eacute;t&eacute; consid&eacute;r&eacute; comme une modalit&eacute; sp&eacute;ciale de r&eacute;installation. Il se distingue en effet des activit&eacute;s traditionnelles de r&eacute;installation dans la mesure o&ugrave; les b&eacute;n&eacute;ficiaires seraient des entrepreneurs ou des personnes pouvant int&eacute;grer le march&eacute; de l&rsquo;emploi, et non pas des groupes vuln&eacute;rables ou des personnes dont la s&eacute;curit&eacute; est menac&eacute;e.<\/p>\n<p>Toutefois, il peut &eacute;galement montrer une direction &agrave; suivre en tant que suppl&eacute;ment innovant aux trois solutions durables traditionnelles, &agrave; savoir l&rsquo;int&eacute;gration locale, le rapatriement et la r&eacute;installation. Les critiques envers ces trois solutions se sont intensifi&eacute;es en raison du nombre &eacute;lev&eacute; et sans pr&eacute;c&eacute;dent de nouvelles crises et de crises prolong&eacute;es de r&eacute;fugi&eacute;s. Le niveau des rapatriements n&rsquo;a jamais &eacute;t&eacute; aussi bas, les crises financi&egrave;res entravent les efforts d&rsquo;int&eacute;gration tandis que la r&eacute;installation ne b&eacute;n&eacute;ficie toujours que de l&rsquo;appui d&rsquo;un groupe restreint de pays d&rsquo;accueil.<\/p>\n<p>&Agrave; l&rsquo;origine, ce sont les autorit&eacute;s br&eacute;siliennes qui ont propos&eacute; ce projet pilote, avant qu&rsquo;un accord bilat&eacute;ral soit pr&eacute;sent&eacute; aux autorit&eacute;s d&rsquo;&Eacute;quateur en d&eacute;cembre 2014. Il &eacute;tait initialement pr&eacute;vu que le programme soit mis en &oelig;uvre d&rsquo;ici octobre 2015 mais l&rsquo;&Eacute;quateur n&rsquo;a toujours pas confirm&eacute; son acceptation. Le d&eacute;bat fait toujours rage au sujet de la possibilit&eacute;, pour les r&eacute;fugi&eacute;s colombiens &eacute;tablis en &Eacute;quateur, de conserver leur statut de r&eacute;fugi&eacute; aussi bien au Br&eacute;sil qu&rsquo;en &Eacute;quateur au cours des trois premiers mois d&rsquo;adaptation, les arguments se concentrant sur la garantie de protection au cas o&ugrave; les r&eacute;fugi&eacute;s ne s&rsquo;adapteraient pas &agrave; la vie au Br&eacute;sil et souhaiteraient retourner en &Eacute;quateur.<\/p>\n<p>La reproduction dans d&rsquo;autres r&eacute;gions du monde d&rsquo;un pilote sur la mobilit&eacute; du travail tel que celui-ci impliquerait n&eacute;cessairement de s&rsquo;adapter aux r&eacute;alit&eacute;s de chacune des r&eacute;gions, mais cette initiative n&rsquo;en sugg&egrave;re pas moins comment am&eacute;liorer la coordination des m&eacute;canismes r&eacute;gionaux d&rsquo;asile via la protection sociale. Alors que traditionnellement, la protection des r&eacute;fugi&eacute;s s&rsquo;est centr&eacute;e sur une compr&eacute;hension des aspects juridiques, cette question est aussi de plus en plus souvent abord&eacute;e sous l&rsquo;angle de la protection sociale,<a href=\"#_edn3\" name=\"_ednref3\" title=\"\">[3]<\/a> y compris les politiques relatives aux interventions sur le march&eacute; du travail, l&rsquo;assurance sociale et l&rsquo;assistance sociale. Cette d&eacute;marche implique une reconnaissance pragmatique du fait que les r&eacute;fugi&eacute;s fuyant les pers&eacute;cutions ont besoin de la protection apport&eacute;e non seulement par les papiers et les droits, mais aussi par l&rsquo;acc&egrave;s au march&eacute; du travail, &agrave; l&rsquo;alimentation et aux services sociaux. Ce type de projet sur la mobilit&eacute; du travail peut aider &agrave; r&eacute;partir les r&eacute;percussions d&rsquo;un influx r&eacute;gional de r&eacute;fugi&eacute;s, en particulier dans les contextes o&ugrave; des pays pauvres ou de petite taille sont les premiers et les plus touch&eacute;s&nbsp;; on pense ici &agrave; l&rsquo;Italie et &agrave; la Gr&egrave;ce.<\/p>\n<p>&nbsp;<\/p>\n<p>Carolina Montenegro <a href=\"mailto:carolmontcastro@gmail.com\"><em>carolmontcastro@gmail.com<\/em><\/a><\/p>\n<p>Journaliste sp&eacute;cialis&eacute;e sur les questions des droits humains et humanitaires.<\/p>\n<div>\n\t<br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[1]<\/a> <a href=\"http:\/\/www.acnur.org\/cartagena30\/en\/brazil-declaration-and-plan-of-action\/\">www.acnur.org\/cartagena30\/en\/brazil-declaration-and-plan-of-action\/<\/a><\/p>\n<\/p><\/div>\n<div id=\"edn2\">\n<p><a href=\"#_ednref2\" name=\"_edn2\" title=\"\">[2]<\/a> Argentine, Bolivie, Br&eacute;sil, Chili, Colombie, &Eacute;quateur, Guyane, Paraguay, P&eacute;rou, Suriname, Uruguay et Venezuela.<\/p>\n<\/p><\/div>\n<div id=\"edn3\">\n<p><a href=\"#_ednref3\" name=\"_edn3\" title=\"\">[3]<\/a> Reportez-vous &agrave; la d&eacute;finition de la Banque mondiale&nbsp;: politiques et programmes visant &agrave; r&eacute;duire la pauvret&eacute; et la vuln&eacute;rabilit&eacute; en promouvant des march&eacute;s de l&rsquo;emploi efficaces, en r&eacute;duisant l&#39;exposition des personnes aux risques et en renfor&ccedil;ant leurs capacit&eacute;s &agrave; g&eacute;rer les risques &eacute;conomiques et sociaux tels que le ch&ocirc;mage, l&#39;exclusion, la maladie, le handicap et la vieillesse. Banque mondiale (2001) <em>Social protection sector strategy: from safety net to springboard<\/em> Washington, D.C.<\/p>\n<p><a href=\"http:\/\/documents.worldbank.org\/curated\/en\/2001\/01\/828354\/social-protection-sector-strategy-safety-net-springboard\">http:\/\/documents.worldbank.org\/curated\/en\/2001\/01\/828354\/social-protection-sector-strategy-safety-net-springboard<\/a><\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un projet pilote intitul&eacute; &laquo;&nbsp;Mobilit&eacute; r&eacute;gionale et int&eacute;gration socio-&eacute;conomique des r&eacute;fugi&eacute;s&nbsp;&raquo; a &eacute;t&eacute; propos&eacute; en 2014 dans le cadre de la D&eacute;claration et du Plan d&rsquo;action du Br&eacute;sil.[1] Dans la pratique, ce projet vise &agrave; faire venir au Br&eacute;sil des r&eacute;fugi&eacute;s colombiens actuellement en &Eacute;quateur. Sur une p&eacute;riode de deux ans, 200 personnes se rendraient&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42645,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[99],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[565],"class_list":["post-41696","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-99","fmr_content_type-article","fmr_languages-french","fmr_list_years-565","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La protection sociale : une quatri\u00e8me solution durable ? - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La protection sociale : une quatri\u00e8me solution durable ? - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"Un projet pilote intitul&eacute; &laquo;&nbsp;Mobilit&eacute; r&eacute;gionale et int&eacute;gration socio-&eacute;conomique des r&eacute;fugi&eacute;s&nbsp;&raquo; a &eacute;t&eacute; propos&eacute; en 2014 dans le cadre de la D&eacute;claration et du Plan d&rsquo;action du Br&eacute;sil.[1] Dans la pratique, ce projet vise &agrave; faire venir au Br&eacute;sil des r&eacute;fugi&eacute;s colombiens actuellement en &Eacute;quateur. Sur une p&eacute;riode de deux ans, 200 personnes se rendraient&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T12:27:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/\",\"url\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/\",\"name\":\"La protection sociale : une quatri\u00e8me solution durable ? - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2015-12-15T05:00:00+00:00\",\"dateModified\":\"2025-04-01T12:27:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FMR 51 &#8211; Destination : Europe\",\"item\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La protection sociale : une quatri\u00e8me solution durable ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La protection sociale : une quatri\u00e8me solution durable ? - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/","og_locale":"es_ES","og_type":"article","og_title":"La protection sociale : une quatri\u00e8me solution durable ? - Forced Migration Review","og_description":"Un projet pilote intitul&eacute; &laquo;&nbsp;Mobilit&eacute; r&eacute;gionale et int&eacute;gration socio-&eacute;conomique des r&eacute;fugi&eacute;s&nbsp;&raquo; a &eacute;t&eacute; propos&eacute; en 2014 dans le cadre de la D&eacute;claration et du Plan d&rsquo;action du Br&eacute;sil.[1] Dans la pratique, ce projet vise &agrave; faire venir au Br&eacute;sil des r&eacute;fugi&eacute;s colombiens actuellement en &Eacute;quateur. Sur une p&eacute;riode de deux ans, 200 personnes se rendraient&hellip;","og_url":"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-04-01T12:27:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/","url":"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/","name":"La protection sociale : une quatri\u00e8me solution durable ? - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2015-12-15T05:00:00+00:00","dateModified":"2025-04-01T12:27:40+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/montenegro-2-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/es\/"},{"@type":"ListItem","position":2,"name":"FMR 51 &#8211; Destination : Europe","item":"https:\/\/www.fmreview.org\/destination-europe-fr\/"},{"@type":"ListItem","position":3,"name":"La protection sociale : une quatri\u00e8me solution durable ?"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41696\/revisions"}],"predecessor-version":[{"id":46166,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41696\/revisions\/46166"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/42645"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/media?parent=41696"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_themes?post=41696"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_region?post=41696"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_issue?post=41696"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_year?post=41696"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content_type?post=41696"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_languages?post=41696"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_list_years?post=41696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}