{"id":41700,"date":"2015-12-15T00:00:00","date_gmt":"2015-12-15T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/pace-severance-2-3\/"},"modified":"2025-04-01T07:27:41","modified_gmt":"2025-04-01T12:27:41","slug":"pace-severance-2-3","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/es\/destination-europe-fr\/pace-severance-2-3\/","title":{"rendered":"L\u2019importance de la terminologie migratoire"},"content":{"rendered":"<p>Les efforts actuels pour d&eacute;battre de la &laquo; crise migratoire &raquo; et y r&eacute;agir en Europe sont de nature pol&eacute;mique, une pol&eacute;mique aliment&eacute;e en partie par la terminologie impr&eacute;cise et parfois incendiaire utilis&eacute;e pour d&eacute;crire les migrants. Cette situation risque &eacute;galement de contribuer &agrave; l&rsquo;&eacute;rosion des droits des migrants.<\/p>\n<p>Le terme de &laquo;&nbsp;crise&nbsp;&raquo;, utilis&eacute; de mani&egrave;re routini&egrave;re pour d&eacute;crire la migration &agrave; destination de l&rsquo;Europe au cours de l&rsquo;ann&eacute;e 2015, doit lui-m&ecirc;me &ecirc;tre examin&eacute; de plus pr&egrave;s. D&rsquo;autres pays, dont un grand nombre disposent de ressources beaucoup moins importantes que l&rsquo;Europe, connaissent depuis quelques temps une version aigu&euml; de ce flux migratoire. &Agrave; la mi-novembre 2015, la Turquie, dont la population est de 76&nbsp;millions d&rsquo;habitants, accueillait 2&nbsp;181&nbsp;293 Syriens, soit un ratio de 1 syrien pour 35 Turcs. En Jordanie, le ratio entre Syriens et Jordaniens est d&rsquo;environ 1 sur 10 tandis qu&rsquo;au Liban ce ratio atteint le niveau impressionnant de 1 sur 5. Il est donc important de mettre en perspective l&rsquo;&eacute;chelle de cette &laquo;&nbsp;crise&nbsp;&raquo; en Europe.<\/p>\n<p>L&eacute;gal et ill&eacute;gal<\/p>\n<p>Le d&eacute;bat concernant la terminologie n&rsquo;est pas une question &laquo;&nbsp;politiquement correcte&nbsp;&raquo;, comme on essaie parfois de le d&eacute;peindre. Il a de r&eacute;elles implications pour les migrants. De nombreuses personnes, y compris certains membres du grand public, journalistes et repr&eacute;sentants gouvernementaux, r&eacute;duisent la totalit&eacute; des migrants &agrave; seulement deux cat&eacute;gories&nbsp;: les migrants &laquo;&nbsp;l&eacute;gaux&nbsp;&raquo; et les migrants &laquo;&nbsp;ill&eacute;gaux&nbsp;&raquo;. Cette dichotomie est toutefois erron&eacute;e, et &agrave; plus d&rsquo;un titre.<\/p>\n<p>Les personnes ne peuvent pas &ecirc;tre ill&eacute;gales, seuls les actes peuvent l&rsquo;&ecirc;tre. En outre, le terme &laquo;&nbsp;ill&eacute;gal&nbsp;&raquo; implique une d&eacute;cision juridique, alors m&ecirc;me que le migrant n&rsquo;a pas eu l&rsquo;occasion de d&eacute;fendre son cas. Dans le domaine du droit criminel, lorsqu&rsquo;un individu est accus&eacute; d&rsquo;une action ill&eacute;gale, il est inacceptable qu&rsquo;une autre personne (y compris, et peut-&ecirc;tre plus particuli&egrave;rement, les journalistes et les politiciens s&rsquo;exprimant en public) parle de cet individu comme d&rsquo;un &laquo;&nbsp;criminel&nbsp;&raquo; avant que sa culpabilit&eacute; n&rsquo;ait &eacute;t&eacute; d&eacute;montr&eacute;e. En effet, la r&egrave;gle de pr&eacute;somption d&rsquo;innocence doit ici s&rsquo;appliquer. Et pourtant, dans le contexte de la migration, des personnalit&eacute;s publiques emploient r&eacute;guli&egrave;rement le terme &laquo;&nbsp;ill&eacute;gal&nbsp;&raquo;, que l&rsquo;on retrouve dans des journaux r&eacute;put&eacute;s et dans des d&eacute;cisions juridiques.<\/p>\n<p>Le terme &laquo; ill&eacute;gal &raquo;, qui fait r&eacute;f&eacute;rence &agrave; une absence de statut valide, est souvent utilis&eacute; pour d&eacute;crire les migrants qui p&eacute;n&egrave;trent de mani&egrave;re clandestine sur un territoire. Toutefois, cette utilisation oriente un volume disproportionn&eacute; de critiques &agrave; l&rsquo;encontre d&rsquo;un groupe qui repr&eacute;sente seulement une partie des migrants sans statut valide. &Agrave; l&rsquo;&eacute;chelle mondiale, la plus grande cat&eacute;gorie de migrants sans statut valide est celle des personnes &eacute;tant entr&eacute;es l&eacute;galement dans un pays mais y ayant s&eacute;journ&eacute; plus longtemps qu&rsquo;elles n&rsquo;y &eacute;taient autoris&eacute;es. Ces personnes exc&eacute;dant la dur&eacute;e de validit&eacute; de leur droit de s&eacute;jour repr&eacute;sentent la majorit&eacute; de la&nbsp; population dite de migrants &laquo;&nbsp;ill&eacute;gaux&nbsp;&raquo;.<\/p>\n<p>Le Rapporteur sp&eacute;cial des Nations Unies sur les droits de l&#39;homme des migrants a plusieurs fois r&eacute;p&eacute;t&eacute; que l&rsquo;entr&eacute;e clandestine sur un territoire devrait constituer une offense uniquement administrative et non pas criminelle. L&rsquo;Organisation internationale pour les migrations et d&rsquo;autres organisations internationales pr&eacute;conisent depuis longtemps l&rsquo;utilisation du terme &laquo;&nbsp;irr&eacute;gulier&nbsp;&raquo; plut&ocirc;t que du terme &laquo;&nbsp;ill&eacute;gal&nbsp;&raquo;, suite &agrave; la recommandation &eacute;mise en 1975 par l&rsquo;Assembl&eacute;e g&eacute;n&eacute;rale de l&rsquo;ONU.<a href=\"#_edn1\" name=\"_ednref1\" title=\"\">[1]<\/a><\/p>\n<p><strong>Traite des &ecirc;tres humains et trafic des migrants<\/strong><\/p>\n<p>Il est important de mieux comprendre la traite et le trafic comme deux crimes distincts. Leur diff&eacute;renciation continue de poser probl&egrave;me aux journalistes comme aux politiciens. Cependant, cette distinction est importante car les victimes de la traite ont droit &agrave; un ensemble particulier de mesures de protection, conform&eacute;ment au droit international et europ&eacute;en. Si elles ne sont pas correctement identifi&eacute;es, elles ne pourront pas b&eacute;n&eacute;ficier de ces protections. La traite implique l&rsquo;intention d&rsquo;exploiter une victime par diff&eacute;rents moyens tels que la force, d&rsquo;autres formes de coercition, la fraude ou la tromperie, et n&rsquo;implique pas n&eacute;cessairement le franchissement l&eacute;gal ou ill&eacute;gal d&rsquo;une fronti&egrave;re.<a href=\"#_edn2\" name=\"_ednref2\" title=\"\">[2]<\/a><\/p>\n<p>En revanche, le trafic est un crime qui implique la facilitation de l&rsquo;entr&eacute;e d&rsquo;une personne de mani&egrave;re ill&eacute;gale, contre un b&eacute;n&eacute;fice financier ou tout autre b&eacute;n&eacute;fice mat&eacute;riel, dans un &Eacute;tat dont cette personne n&rsquo;est ni ressortissante ni r&eacute;sidente. En d&rsquo;autres mots, le trafic implique toujours le franchissement ill&eacute;gal d&rsquo;une fronti&egrave;re.<a href=\"#_edn3\" name=\"_ednref3\" title=\"\">[3]<\/a><\/p>\n<p>Le seul moyen d&rsquo;efficace d&rsquo;identifier correctement les mesures de protection ou des services auxquels un migrant a le droit est de mener une &eacute;valuation individuelle de la situation du migrant pour d&eacute;terminer s&rsquo;il a &eacute;t&eacute; victime de traite ou de trafic. Dans un cas comme dans l&rsquo;autre, ce sont les malfaiteurs qui commettent le crime et non pas les migrants.<\/p>\n<p><strong>R&eacute;fugi&eacute;s, demandeurs d&rsquo;asile et autres migrants<\/strong><\/p>\n<p>Les politiciens ne sont pas toujours d&rsquo;accord sur les aspects logistiques de la protection des r&eacute;fugi&eacute;s, mais ils contestent rarement le fait que les r&eacute;fugi&eacute;s ont le droit &agrave; une protection. En d&rsquo;autres mots, ces derniers sont consid&eacute;r&eacute;s comme des &laquo;&nbsp;bons&nbsp;&raquo; migrants, dont le droit &agrave; la protection est clairement d&eacute;fini par la Convention de l&rsquo;ONU relative au statut des r&eacute;fugi&eacute;s. En revanche, les politiciens, la presse et le grand public ont plut&ocirc;t tendance &agrave; appr&eacute;hender les demandeurs d&rsquo;asile avec scepticisme, une situation en partie due &agrave; une mauvaise compr&eacute;hension du terme &laquo;&nbsp;demandeur d&rsquo;asile&nbsp;&raquo;. L&rsquo;asile correspond &agrave; une d&eacute;finition juridique sp&eacute;cifique et les migrants qui le sollicitent ne r&eacute;pondent pas tous aux crit&egrave;res d&rsquo;acceptation. Toutefois, la d&eacute;cision d&rsquo;octroyer l&rsquo;asile &agrave; un demandeur est distincte du droit d&rsquo;un migrant &agrave; d&eacute;poser une demande d&rsquo;asile. Ce droit existe, indiff&eacute;remment du fait que l&rsquo;asile soit finalement octroy&eacute; ou non.<\/p>\n<p>Il existe une tendance &agrave; cat&eacute;goriser tous les autres migrants en tant que &laquo;&nbsp;migrants &eacute;conomiques&nbsp;&raquo; et de les d&eacute;peindre comme des &laquo;&nbsp;mauvais&nbsp;&raquo; migrants, motiv&eacute;s uniquement par leurs propres int&eacute;r&ecirc;ts. Toutefois, d&rsquo;un point de vue juridique, le terme &laquo;&nbsp;migrant &eacute;conomique&nbsp;&raquo; n&rsquo;existe pas. Les termes qui existent en revanche dans les trait&eacute;s internationaux, par exemple &laquo;&nbsp;travailleur migrant&nbsp;&raquo;, sont mieux adapt&eacute;s car la cat&eacute;gorisation trop large et impr&eacute;cise de &laquo;&nbsp;migrant &eacute;conomique&nbsp;&raquo; ne tient pas compte des circonstances individuelles de chaque migrant, qui peuvent se composer de plusieurs motivations. Il est dangereux d&rsquo;utiliser ce terme car il risque d&rsquo;impliquer, &agrave; tort, que ces migrants n&rsquo;auront jamais le droit de r&eacute;gulariser leur statut, si bien qu&rsquo;il est possible de refuser sommairement leur entr&eacute;e sur le territoire ou de les expulser. Dans certains cas, un migrant qui n&rsquo;est ni un r&eacute;fugi&eacute; ni un demandeur d&rsquo;asile peut tout de m&ecirc;me avoir le droit, sur le plan juridique, de r&eacute;gulariser son s&eacute;jour dans un pays r&eacute;cepteur. Et quel que soit le cas, tous les migrants ont des droits qui doivent &ecirc;tre respect&eacute;s.<\/p>\n<p>Il est important que les d&eacute;bats publics tiennent compte des distinctions susmentionn&eacute;es afin de faciliter la recherche de solutions raisonnables et respectueuses. La terminologie peut jouer un r&ocirc;le important pour fa&ccedil;onner le d&eacute;bat sur une gouvernance efficace de la migration.<\/p>\n<p>&nbsp;<\/p>\n<p>Paola Pace <a href=\"mailto:ppace@iom.int\"><em>ppace@iom.int<\/em><\/a><\/p>\n<p>Coordinatrice de la promotion de la sant&eacute; des migrants pour l&#39;Afrique de l&#39;Est, Organisation internationale pour les migrations, Kenya <a href=\"http:\/\/www.iom.int\"><em>www.iom.int<\/em><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Kristi Severance <a href=\"mailto:migratitude@gmail.com\"><em>migratitude@gmail.com<\/em><\/a><\/p>\n<p>Consultante ind&eacute;pendante<\/p>\n<div>\n\t<br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[1]<\/a> Assembl&eacute;e g&eacute;n&eacute;rale, Mesures pour garantir les droits humains et la dignit&eacute; de tous les travailleurs migrants, 3449, 2433<sup>&egrave;me<\/sup> r&eacute;union pl&eacute;ni&egrave;re, 9 d&eacute;cembre 1975. <a href=\"http:\/\/www.worldlii.org\/int\/other\/UNGARsn\/1975\/87.pdf\">www.worldlii.org\/int\/other\/UNGARsn\/1975\/87.pdf<\/a><\/p>\n<\/p><\/div>\n<div id=\"edn2\">\n<p><a href=\"#_ednref2\" name=\"_edn2\" title=\"\">[2]<\/a> Protocole additionnel &agrave; la Convention des Nations Unies contre la criminalit&eacute; transnationale organis&eacute;e visant &agrave; pr&eacute;venir, r&eacute;primer et punir la traite des personnes, en particulier des femmes et des enfants <a href=\"http:\/\/www.unodc.org\/documents\/treaties\/UNTOC\/Publications\/TOC%20Convention\/TOCebook-e.pdf\">www.unodc.org\/documents\/treaties\/UNTOC\/Publications\/TOC%20Convention\/TOCebook-e.pdf<\/a> <a href=\"http:\/\/tinyurl.com\/UNTOC\"><strong>http:\/\/tinyurl.com\/UNTOC<\/strong><\/a><\/p>\n<\/p><\/div>\n<div id=\"edn3\">\n<p><a href=\"#_ednref3\" name=\"_edn3\" title=\"\">[3]<\/a> Protocole contre le trafic illicite de migrants par terre, air et mer, additionnel &agrave; la Convention des Nations Unies contre la criminalit&eacute; transnationale organis&eacute;e<\/p>\n<p><a href=\"http:\/\/www.refworld.org\/cgi-bin\/texis\/vtx\/rwmain\/opendocpdf.pdf?reldoc=y&amp;docid=4891c27e2\">www.refworld.org\/cgi-bin\/texis\/vtx\/rwmain\/opendocpdf.pdf?reldoc=y&amp;docid=4891c27e2<\/a><\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les efforts actuels pour d&eacute;battre de la &laquo; crise migratoire &raquo; et y r&eacute;agir en Europe sont de nature pol&eacute;mique, une pol&eacute;mique aliment&eacute;e en partie par la terminologie impr&eacute;cise et parfois incendiaire utilis&eacute;e pour d&eacute;crire les migrants. Cette situation risque &eacute;galement de contribuer &agrave; l&rsquo;&eacute;rosion des droits des migrants. Le terme de &laquo;&nbsp;crise&nbsp;&raquo;, utilis&eacute; de&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42645,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[99],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[565],"class_list":["post-41700","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-99","fmr_content_type-article","fmr_languages-french","fmr_list_years-565","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019importance de la terminologie migratoire - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019importance de la terminologie migratoire - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"Les efforts actuels pour d&eacute;battre de la &laquo; crise migratoire &raquo; et y r&eacute;agir en Europe sont de nature pol&eacute;mique, une pol&eacute;mique aliment&eacute;e en partie par la terminologie impr&eacute;cise et parfois incendiaire utilis&eacute;e pour d&eacute;crire les migrants. Cette situation risque &eacute;galement de contribuer &agrave; l&rsquo;&eacute;rosion des droits des migrants. Le terme de &laquo;&nbsp;crise&nbsp;&raquo;, utilis&eacute; de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T12:27:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/\",\"url\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/\",\"name\":\"L\u2019importance de la terminologie migratoire - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2015-12-15T05:00:00+00:00\",\"dateModified\":\"2025-04-01T12:27:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FMR 51 &#8211; Destination : Europe\",\"item\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u2019importance de la terminologie migratoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019importance de la terminologie migratoire - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/","og_locale":"es_ES","og_type":"article","og_title":"L\u2019importance de la terminologie migratoire - Forced Migration Review","og_description":"Les efforts actuels pour d&eacute;battre de la &laquo; crise migratoire &raquo; et y r&eacute;agir en Europe sont de nature pol&eacute;mique, une pol&eacute;mique aliment&eacute;e en partie par la terminologie impr&eacute;cise et parfois incendiaire utilis&eacute;e pour d&eacute;crire les migrants. Cette situation risque &eacute;galement de contribuer &agrave; l&rsquo;&eacute;rosion des droits des migrants. Le terme de &laquo;&nbsp;crise&nbsp;&raquo;, utilis&eacute; de&hellip;","og_url":"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-04-01T12:27:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/","url":"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/","name":"L\u2019importance de la terminologie migratoire - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2015-12-15T05:00:00+00:00","dateModified":"2025-04-01T12:27:41+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/pace-severance-2-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/es\/"},{"@type":"ListItem","position":2,"name":"FMR 51 &#8211; Destination : Europe","item":"https:\/\/www.fmreview.org\/destination-europe-fr\/"},{"@type":"ListItem","position":3,"name":"L\u2019importance de la terminologie migratoire"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41700\/revisions"}],"predecessor-version":[{"id":46170,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41700\/revisions\/46170"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/42645"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/media?parent=41700"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_themes?post=41700"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_region?post=41700"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_issue?post=41700"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_year?post=41700"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content_type?post=41700"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_languages?post=41700"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_list_years?post=41700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}