{"id":41701,"date":"2015-12-15T00:00:00","date_gmt":"2015-12-15T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/szczepanik-tylec-2-3\/"},"modified":"2025-04-01T07:27:41","modified_gmt":"2025-04-01T12:27:41","slug":"szczepanik-tylec-2-3","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/es\/destination-europe-fr\/szczepanik-tylec-2-3\/","title":{"rendered":"Le paradoxe de l\u2019immigration polonaise vis-\u00e0-vis des demandeurs d\u2019asile ukrainiens"},"content":{"rendered":"<p>En 2014 le nombre total de demandes d&rsquo;asile d&eacute;pos&eacute;es en Pologne par des ressortissants de tous les pays atteignaient &agrave; peine un plus de 8000.<a href=\"#_edn1\" name=\"_ednref1\" title=\"\">[1]<\/a> Face &agrave; 428&nbsp;000 en Hongrie ou 646&nbsp;000 en Italie (deux autres &Eacute;tats situ&eacute;s sur la fronti&egrave;re ext&eacute;rieure de l&rsquo;UE), les statistiques polonaises sont &eacute;tonnamment faibles, d&rsquo;autant plus qu&rsquo;elles incluent la p&eacute;riode qui a suivi le d&eacute;clenchement du conflit en Ukraine.<\/p>\n<p>Alors que la majorit&eacute; des r&eacute;fugi&eacute;s qui fuient le conflit en Ukraine ont cherch&eacute; refuge en Russie, un nombre moins important d&rsquo;entre eux ont d&eacute;pos&eacute; des demandes de protection internationale aupr&egrave;s de l&rsquo;UE, et notamment aupr&egrave;s de la Pologne. Le nombre des demandeurs d&rsquo;asile ukrainiens en Pologne a connu une augmentation substantielle compar&eacute; &agrave; celui des ann&eacute;es pr&eacute;c&eacute;dentes mais il est rest&eacute; faible en chiffres absolus: 46 demandes en 2013, 2253 en 2014 et 2061 &agrave; mi-novembre 2015.<a href=\"#_edn2\" name=\"_ednref2\" title=\"\">[2]<\/a> Toutefois, le taux d&rsquo;obtention du statut de r&eacute;fugi&eacute; reste extr&ecirc;mement faible, comme il l&rsquo;&eacute;tait en 2014 dans la plupart des autres principaux pays dans lesquels les Ukrainiens cherchaient asile: &nbsp;l&rsquo;Allemagne avait accord&eacute; le statut de r&eacute;fugi&eacute; ou de protection subsidiaire &agrave; 20 personnes sur 2705 demandes d&eacute;pos&eacute;es; l&rsquo;Italie &agrave; 45 personnes sur 2080 demandes d&eacute;pos&eacute;es; la Su&egrave;de avait accord&eacute; 10 statuts de r&eacute;fugi&eacute; sur 1320 demandes; &nbsp;et la France 30 sur 1425 demandes. Il est int&eacute;ressant de noter que la R&eacute;publique Tch&egrave;que qui avait re&ccedil;u 515 demandes avait accord&eacute; le statut de r&eacute;fugi&eacute; ou celui de protection subsidiaire &agrave; 145 de ces personnes.<\/p>\n<p>En Pologne, au 15 novembre 2015 deux personnes seulement ont obtenu le statut de r&eacute;fugi&eacute; et 24 celui de protection subsidiaire, une situation qui peut avoir pour effet de dissuader certains Ukrainiens de demander l&rsquo;asile en Pologne. Au cours de la m&ecirc;me p&eacute;riode, le nombre des Ukrainiens ayant entrepris une proc&eacute;dure de r&eacute;gularisation de leur permis de r&eacute;sidence en Pologne a pratiquement doubl&eacute;, et ce tant en ce qui concerne le nombre des demandes que celui des r&eacute;ponses positives.<\/p>\n<p>Ce qui pose probl&egrave;me c&rsquo;est que la Pologne tout en acceptant les Ukrainiens comme &eacute;tudiants ou comme migrants &eacute;conomiques, ne leur accorde pas le statut de r&eacute;fugi&eacute; m&ecirc;me s&rsquo;ils viennent de la partie Est de l&rsquo;Ukraine encore d&eacute;chir&eacute;e par la guerre. Lorsque le conflit a d&eacute;but&eacute; en Ukraine, l&rsquo;&eacute;lite politique polonaise a publiquement exprim&eacute; son soutien &agrave; l&rsquo;&eacute;gard des demandeurs d&rsquo;asile potentiels venus d&rsquo;Ukraine qui arriveraient sur le territoire polonais. Mais l&rsquo;approche actuelle de la Pologne semble vouloir limiter l&rsquo;afflux des demandeurs d&rsquo;asile tout en rendant la proc&eacute;dure de r&eacute;gularisation du permis de r&eacute;sidence tr&egrave;s accessible. N&eacute;anmoins, de nombreux Ukrainiens n&rsquo;ont pas cette information et continuent de d&eacute;poser des demandes d&rsquo;asile. Ce qui les place bien souvent dans une situation juridique compliqu&eacute;e; ils ne peuvent pas travailler en Pologne et si leur demande est rejet&eacute;e ils sont oblig&eacute;s de quitter le pays.<\/p>\n<p>Le paradoxe juridique<\/p>\n<p>La raison qui explique ce faible taux d&rsquo;obtention du statut de r&eacute;fugi&eacute; des Ukrainiens est l&rsquo;application par les autorit&eacute;s polonaises du concept de la &laquo;&nbsp;possibilit&eacute; de fuite et de r&eacute;installation interne&nbsp;&raquo;. Alors que ni la Convention de 1951, ni son Protocole de 1967 ne mentionnent express&eacute;ment ce concept, celui-ci s&rsquo;est vu d&eacute;velopp&eacute; dans la l&eacute;gislation et la pratique de certains &Eacute;tats. Il figure, par exemple, &agrave; l&rsquo;Article 8 de la nouvelle version de la Directive Qualification de l&rsquo;Union Europ&eacute;enne de 2011 qui introduit la possibilit&eacute; d&rsquo;avoir acc&egrave;s &agrave; une protection dans une autre partie du pays d&rsquo;origine comme faisant partie de l&rsquo;&eacute;valuation pour d&eacute;terminer le fondement d&rsquo;une demande de protection internationale. On observe &agrave; cet &eacute;gard des divergences importantes dans la pratique adopt&eacute;e par les diff&eacute;rents &Eacute;tats membres de l&rsquo;UE.<\/p>\n<p>En vertu de la l&eacute;gislation polonaise,<a href=\"#_edn3\" name=\"_ednref3\" title=\"\">[3]<\/a> un demandeur d&rsquo;asile doit prouver qu&rsquo;il n&rsquo;est pas en mesure de se r&eacute;installer en s&eacute;curit&eacute; dans aucune autre partie de son pays d&rsquo;origine. Du fait de l&rsquo;application de ce concept aux demandeurs d&rsquo;asile ukrainiens qui, dans leur majorit&eacute; viennent des zones de l&rsquo;Est contr&ocirc;l&eacute;es par les rebelles et ont une possibilit&eacute; (au moins th&eacute;oriquement) de se r&eacute;installer dans la partie occidentale du pays, on aboutit &agrave; une situation dans laquelle il est pratiquement impossible aux demandeurs d&rsquo;asile ukrainiens d&rsquo;obtenir le statut de protection en Pologne. &nbsp;<\/p>\n<p>Comme le stipulent les Principes directeurs sur la protection internationale du Haut-commissariat des Nations Unies pour les r&eacute;fugi&eacute;s,<a href=\"#_edn4\" name=\"_ednref4\" title=\"\"><sup><sup>[4]<\/sup><\/sup><\/a> le concept de la &laquo;&nbsp;possibilit&eacute; de fuite interne&nbsp;&raquo; n&rsquo;est ni un principe isol&eacute;, ni un test ind&eacute;pendant permettant de fonder la d&eacute;termination du statut de r&eacute;fugi&eacute;. Ce concept devrait donc n&rsquo;&ecirc;tre qu&rsquo;un &eacute;l&eacute;ment d&rsquo;une approche globale contribuant &agrave; d&eacute;terminer l&rsquo;octroi de la protection internationale. Toutefois, en Pologne, la possibilit&eacute; de fuite interne semble &ecirc;tre devenue un d&eacute;terminant fondamental dans la d&eacute;cision d&rsquo;octroyer la protection internationale aux demandeurs d&rsquo;asile ukrainiens.<\/p>\n<p>Selon la Cour europ&eacute;enne des droits de l&rsquo;homme,<a href=\"#_edn5\" name=\"_ednref5\" title=\"\"><em><strong>[5]<\/strong><\/em><\/a> en vue d&rsquo;appliquer le concept de la possibilit&eacute; de fuite interne, des garanties sp&eacute;cifiques doivent &ecirc;tre r&eacute;unies: notamment, la personne doit &ecirc;tre capable de se rendre dans la zone concern&eacute;e, y p&eacute;n&eacute;trer et s&rsquo;y installer. De m&ecirc;me, la politique appliqu&eacute;e par un &Eacute;tat d&rsquo;accueil ne devrait pas avoir pour cons&eacute;quence l&rsquo;expulsion de la personne vers une partie de son pays d&rsquo;origine o&ugrave; elle risque de subir des atteintes graves. Diff&eacute;rents rapports internationaux et comptes-rendus locaux signalent qu&rsquo;avec plus de 1,4 millions de personnes d&eacute;plac&eacute;es &agrave; l&rsquo;int&eacute;rieur du pays (PDI) et des ressources insuffisantes, la situation des PDI en Ukraine est extr&ecirc;mement difficile. Ils y rencontrent des probl&egrave;mes de proc&eacute;dures d&rsquo;enregistrement, d&rsquo;obtention d&rsquo;un logement ad&eacute;quat, d&rsquo;acc&egrave;s &agrave; l&rsquo;assistance m&eacute;dicale, &agrave; l&rsquo;emploi et au versement d&rsquo;allocations. En outre, les tensions augmentent entre les PDI et les communaut&eacute;s h&ocirc;tes qui rejettent la faute des probl&egrave;mes sociaux actuels et du conflit lui-m&ecirc;me sur les d&eacute;plac&eacute;s.<\/p>\n<p>Outre la possibilit&eacute; de demander la protection internationale, les Ukrainiens ont pour option de l&eacute;galiser leur s&eacute;jour sur le territoire polonais on obtenant un permis de r&eacute;sidence temporaire ou permanent. La r&egrave;glementation polonaise &agrave; cet &eacute;gard est tr&egrave;s lib&eacute;rale. En moyenne 80&nbsp;% des demandes de r&eacute;gularisation de s&eacute;jour sont accept&eacute;es, ce qui constitue une possibilit&eacute; non n&eacute;gligeable d&rsquo;obtenir un statut juridique. En cons&eacute;quence compar&eacute; &agrave; 2013, en 2014 le nombre de demandes de permis de r&eacute;sidence temporaire a augment&eacute; de 60&nbsp;% et de 104&nbsp;% pour les permis de r&eacute;sidence permanente. N&eacute;anmoins, l&rsquo;absence d&rsquo;informations claires sur la r&eacute;gularisation de la r&eacute;sidence comme sur les proc&eacute;dures d&rsquo;obtention de la protection internationale a entrain&eacute; une situation dans laquelle de nombreux Ukrainiens ont tout de m&ecirc;me d&eacute;cid&eacute; de d&eacute;poser des demandes d&rsquo;asile alors qu&rsquo;ils auraient rempli les conditions requises pour une r&eacute;gularisation de leur r&eacute;sidence.<\/p>\n<p>De nombreux Ukrainiens ignorent les cons&eacute;quences juridiques auxquelles ils s&rsquo;exposent en entamant cette proc&eacute;dure, comme par exemple l&rsquo;interdiction g&eacute;n&eacute;rale de travailler pendant les six premiers mois du processus. Tout cela parce que ni les autorit&eacute;s ukrainiennes ni les autorit&eacute;s polonaises ne leur fournissent &agrave; temps des informations fiables. Cette politique a tout particuli&egrave;rement touch&eacute; les migrants venus de l&rsquo;Est de l&rsquo;Ukraine qui r&eacute;sidaient et travaillaient d&eacute;j&agrave; en Pologne et auxquels on a conseill&eacute; de demander la protection internationale lorsque le conflit s&rsquo;est d&eacute;clar&eacute;. Dans la mesure o&ugrave; le permis de travail est automatiquement annul&eacute; lorsqu&rsquo;une personne d&eacute;pose une demande d&rsquo;asile, ces personnes n&rsquo;ont pas pu continuer &agrave; travailler. De plus, le refus d&rsquo;octroyer la protection &ndash; puisque tel a &eacute;t&eacute; le r&eacute;sultat de la grande majorit&eacute; des demandes, a signifi&eacute; qu&rsquo;elles ont d&ucirc; quitter la Pologne et dans de nombreux cas, qu&rsquo;elles se sont vues soumises &agrave; une interdiction de r&eacute;admission. De m&ecirc;me, les &eacute;tudiants ukrainiens de la r&eacute;gion du Donbass qui &eacute;tudiaient dans des universit&eacute;s polonaises et qui dans l&rsquo;espoir d&rsquo;obtenir la protection internationale avaient d&eacute;pos&eacute; une demande d&rsquo;asile plut&ocirc;t que de prolonger leur permis de r&eacute;sidence ont &eacute;galement perdu leur droit de s&eacute;journer dans le pays. Ces deux groupes de migrants n&rsquo;ont cons&eacute;cutivement pas d&rsquo;autre choix que de retourner en Ukraine ou de rester en Pologne mais de mani&egrave;re irr&eacute;guli&egrave;re.<\/p>\n<p>Le conflit en cours dans l&rsquo;Est de l&rsquo;Ukraine a suscit&eacute; de nombreuses attentes parmi les Ukrainiens de cette r&eacute;gion qui esp&eacute;raient obtenir la protection internationale en Pologne. Mais la d&eacute;cision des autorit&eacute;s polonaises de faire du concept de la &laquo;&nbsp;possibilit&eacute; de fuite interne&nbsp;&raquo; un test ind&eacute;pendant pour d&eacute;terminer le droit &agrave; l&rsquo;asile a plac&eacute; les demandeurs d&rsquo;asile ukrainiens dans une position tr&egrave;s vuln&eacute;rable. Tant qu&rsquo;il n&rsquo;y a pas de v&eacute;ritable possibilit&eacute; de r&eacute;installation des demandeurs d&rsquo;asile ukrainien &agrave; l&rsquo;int&eacute;rieur de l&rsquo;Ukraine l&rsquo;application r&eacute;it&eacute;r&eacute;e de ce concept par les autorit&eacute;s polonaises doit &ecirc;tre assouplie.<\/p>\n<p>&nbsp;<\/p>\n<p>Marta Szczepanik <a href=\"mailto:m.szczepanik@hfhr.org.pl\"><em>m.szczepanik@hfhr.org.pl<\/em><\/a><\/p>\n<p>Chercheuse, Programme d&rsquo;assistance juridique aux r&eacute;fugi&eacute;s et aux migrants, Fondation Helsinki pour les droits de l&rsquo;homme de Varsovie <a href=\"http:\/\/www.hfhr.org.pl\"><em>www.hfhr.org.pl<\/em><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Ewelina Tylec <a href=\"mailto:ewelina.tylec@gmail.com\"><em>ewelina.tylec@gmail.com<\/em><\/a><\/p>\n<p>Sp&eacute;cialiste des Droits de l&rsquo;homme, Institut de Droit et Soci&eacute;t&eacute; (INPRIS) <a href=\"http:\/\/www.inpris.pl\"><em>www.inpris.pl<\/em><\/a><\/p>\n<div>\n\t<br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[1]<\/a> Eurostat <a href=\"http:\/\/ec.europa.eu\/eurostat\/statistics-explained\/index.php\/File:Number_of_%28non-EU%29_asylum_applicants_in_the_EU_and_EFTA_Member_States,_by_age_distribution,_2014_%28%C2%B9%29_YB15_III.png\">http:\/\/ec.europa.eu\/eurostat\/statistics-explained\/index.php\/File:Number_of_%28non-EU%29_asylum_applicants_in_the_EU_and_EFTA_Member_States,_by_age_distribution,_2014_%28%C2%B9%29_YB15_III.png<\/a><\/p>\n<p><a href=\"http:\/\/tinyurl.com\/Eurostat-asylum2014\"><strong>http:\/\/tinyurl.com\/Eurostat-asylum2014<\/strong><\/a><\/p>\n<\/p><\/div>\n<div id=\"edn2\">\n<p><a href=\"#_ednref2\" name=\"_edn2\" title=\"\">[2]<\/a> Bureau des &eacute;trangers: <a href=\"http:\/\/udsc.gov.pl\/statystyki\">http:\/\/udsc.gov.pl\/statystyki<\/a><\/p>\n<\/p><\/div>\n<div id=\"edn3\">\n<p><a href=\"#_ednref3\" name=\"_edn3\" title=\"\">[3]<\/a> Article 18.1, <em>Loi de 2003 sur l&rsquo;octroi de la protection aux &eacute;trangers sur le territoire de la R&eacute;publique de Pologne <\/em><a href=\"http:\/\/www.refworld.org\/docid\/44a134a44.html\">www.refworld.org\/docid\/44a134a44.html<\/a><\/p>\n<\/p><\/div>\n<div id=\"edn4\">\n<p><a href=\"#_ednref4\" name=\"_edn4\" title=\"\">[4]<\/a> UNHCR (2003) <em>Principes directeurs sur la protection internationale: &nbsp;&laquo;&nbsp;Possibilit&eacute; de fuite ou de r&eacute;installation interne&nbsp;&raquo; dans le cadre de l&rsquo;application de l&rsquo;Article 1A(2) de la Convention de 1951 et\/ou du Protocole de 1967 relatifs au statut des r&eacute;fugi&eacute;s. <\/em><a href=\"http:\/\/www.noas.no\/wp-content\/uploads\/2002\/09\/UNHCR-Guidelines-Internal-Flight-or-Relocation-Alternative.doc\">www.noas.no\/wp-content\/uploads\/2002\/09\/UNHCR-Guidelines-Internal-Flight-or-Relocation-Alternative.doc<\/a><\/p>\n<\/p><\/div>\n<div id=\"edn5\">\n<p><a href=\"#_ednref5\" name=\"_edn5\" title=\"\">[5]<\/a> Cour europ&eacute;enne des droits de l&rsquo;homme, <em>Salah Sheekh c. les Pays-Bas <\/em>(Application no.&nbsp;1948\/04), 11.01.2007 <a href=\"http:\/\/www.refworld.org\/docid\/45cb3dfd2.html\">www.refworld.org\/docid\/45cb3dfd2.html<\/a><\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2014 le nombre total de demandes d&rsquo;asile d&eacute;pos&eacute;es en Pologne par des ressortissants de tous les pays atteignaient &agrave; peine un plus de 8000.[1] Face &agrave; 428&nbsp;000 en Hongrie ou 646&nbsp;000 en Italie (deux autres &Eacute;tats situ&eacute;s sur la fronti&egrave;re ext&eacute;rieure de l&rsquo;UE), les statistiques polonaises sont &eacute;tonnamment faibles, d&rsquo;autant plus qu&rsquo;elles incluent la&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42645,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[99],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[565],"class_list":["post-41701","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-99","fmr_content_type-article","fmr_languages-french","fmr_list_years-565","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le paradoxe de l\u2019immigration polonaise vis-\u00e0-vis des demandeurs d\u2019asile ukrainiens - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le paradoxe de l\u2019immigration polonaise vis-\u00e0-vis des demandeurs d\u2019asile ukrainiens - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"En 2014 le nombre total de demandes d&rsquo;asile d&eacute;pos&eacute;es en Pologne par des ressortissants de tous les pays atteignaient &agrave; peine un plus de 8000.[1] Face &agrave; 428&nbsp;000 en Hongrie ou 646&nbsp;000 en Italie (deux autres &Eacute;tats situ&eacute;s sur la fronti&egrave;re ext&eacute;rieure de l&rsquo;UE), les statistiques polonaises sont &eacute;tonnamment faibles, d&rsquo;autant plus qu&rsquo;elles incluent la&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T12:27:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/\",\"url\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/\",\"name\":\"Le paradoxe de l\u2019immigration polonaise vis-\u00e0-vis des demandeurs d\u2019asile ukrainiens - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2015-12-15T05:00:00+00:00\",\"dateModified\":\"2025-04-01T12:27:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FMR 51 &#8211; Destination : Europe\",\"item\":\"https:\/\/www.fmreview.org\/destination-europe-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le paradoxe de l\u2019immigration polonaise vis-\u00e0-vis des demandeurs d\u2019asile ukrainiens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le paradoxe de l\u2019immigration polonaise vis-\u00e0-vis des demandeurs d\u2019asile ukrainiens - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/","og_locale":"es_ES","og_type":"article","og_title":"Le paradoxe de l\u2019immigration polonaise vis-\u00e0-vis des demandeurs d\u2019asile ukrainiens - Forced Migration Review","og_description":"En 2014 le nombre total de demandes d&rsquo;asile d&eacute;pos&eacute;es en Pologne par des ressortissants de tous les pays atteignaient &agrave; peine un plus de 8000.[1] Face &agrave; 428&nbsp;000 en Hongrie ou 646&nbsp;000 en Italie (deux autres &Eacute;tats situ&eacute;s sur la fronti&egrave;re ext&eacute;rieure de l&rsquo;UE), les statistiques polonaises sont &eacute;tonnamment faibles, d&rsquo;autant plus qu&rsquo;elles incluent la&hellip;","og_url":"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-04-01T12:27:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/","url":"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/","name":"Le paradoxe de l\u2019immigration polonaise vis-\u00e0-vis des demandeurs d\u2019asile ukrainiens - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2015-12-15T05:00:00+00:00","dateModified":"2025-04-01T12:27:41+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/destination-europe-fr\/szczepanik-tylec-2-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/es\/"},{"@type":"ListItem","position":2,"name":"FMR 51 &#8211; Destination : Europe","item":"https:\/\/www.fmreview.org\/destination-europe-fr\/"},{"@type":"ListItem","position":3,"name":"Le paradoxe de l\u2019immigration polonaise vis-\u00e0-vis des demandeurs d\u2019asile ukrainiens"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41701\/revisions"}],"predecessor-version":[{"id":46171,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/41701\/revisions\/46171"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/42645"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/media?parent=41701"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_themes?post=41701"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_region?post=41701"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_issue?post=41701"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_year?post=41701"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content_type?post=41701"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_languages?post=41701"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_list_years?post=41701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}