{"id":42158,"date":"2020-06-16T00:00:00","date_gmt":"2020-06-16T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/ndikintum-agmalha-2-3\/"},"modified":"2024-11-20T00:34:40","modified_gmt":"2024-11-20T05:34:40","slug":"ndikintum-agmalha","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/es\/numero64\/ndikintum-agmalha\/","title":{"rendered":"R\u00e9silience, adaptation et apprentissage : les r\u00e9fugi\u00e9s maliens et leurs h\u00f4tes mauritaniens"},"content":{"rendered":"<p><span><span><span><span><span lang=\"FR\">La Mauritanie accueille actuellement 60&nbsp;511 r\u00e9fugi\u00e9s ayant fui le Mali en 2012. Originaires du nord du Mali, ils vivent aujourd\u2019hui dans le camp de Mbera et en p\u00e9riph\u00e9rie, dans le sud-est de la Mauritanie.<\/span><a href=\"#_edn1\" name=\"_ednref1\"><span><span><span><span><span><span>[1]<\/span><\/span><\/span><\/span><\/span><\/span><\/a><span lang=\"FR\"> C\u2019est l\u2019ins\u00e9curit\u00e9 croissante qui les a pouss\u00e9s \u00e0 quitter leur r\u00e9gion d\u2019origine. Toutefois, avant de fuir, la plupart d\u2019entre eux subissaient d\u00e9j\u00e0 les cons\u00e9quences n\u00e9gatives du changement climatique durant plusieurs d\u00e9cennies, voire davantage. Par exemple, depuis 1973, la s\u00e9cheresse frappe le nord du Mali tous les 10 ans environ.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Comme ces r\u00e9fugi\u00e9s maliens sont principalement des \u00e9leveurs, ils sont souvent partis en exil avec leur b\u00e9tail. La demande en ressources naturelles dans leur communaut\u00e9 d\u2019accueil, telles que l\u2019eau et les p\u00e2turages pour le b\u00e9tail, exerce une pression accrue qui est encore davantage exacerb\u00e9e par le changement climatique. L\u2019environnement naturel souffre \u00e9galement d\u2019autres activit\u00e9s telles que la collecte de bois de chauffe et l\u2019utilisation d\u2019eau \u00e0 des fins domestiques et agricoles. Heureusement, les r\u00e9fugi\u00e9s n\u2019ont pas seulement apport\u00e9 leurs besoins, mais aussi des solutions avec eux. Apr\u00e8s avoir d\u00fb affronter eux-m\u00eames les cons\u00e9quences n\u00e9fastes du changement climatique dans leur pays d\u2019origine, ils sont mieux arm\u00e9s pour affronter ces d\u00e9fis et att\u00e9nuer certains d\u2019entre eux dans leur communaut\u00e9 d\u2019accueil. Les r\u00e9fugi\u00e9s reconnaissent leur disposition \u00e0 apprendre de leur nouvelle situation s\u2019est d\u00e9velopp\u00e9e alors qu\u2019ils cherchaient eux-m\u00eames des solutions aux graves cons\u00e9quences du changement climatique dans leur pays.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><strong><span lang=\"FR\"><span>D\u00e9cider de partir&nbsp;: points de basculement <\/span><\/span><\/strong><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Plusieurs r\u00e9fugi\u00e9s maliens \u00e9tablis aujourd\u2019hui dans le camp de Mbera avaient auparavant d\u00e9j\u00e0 \u00e9t\u00e9 forc\u00e9s d\u2019abandonner leur lieu de vie \u00e0 cause du changement climatique, m\u00eame s\u2019ils \u00e9taient rest\u00e9s dans leur pays. Face aux impacts n\u00e9gatifs du changement climatique, leur r\u00e9ponse imm\u00e9diate a \u00e9t\u00e9 et demeure le recours \u00e0 des innovations autochtones pour tenter de renforcer leur r\u00e9silience, par exemple, en utilisant diff\u00e9rents types de paillis pour conserver l\u2019eau du sol ou en entourant les jarres avec des peaux d\u2019animaux pour que l\u2019eau reste fra\u00eeche. Le sentiment de communaut\u00e9 joue \u00e9galement un r\u00f4le central dans la survie, les membres les plus r\u00e9silients tendant une main g\u00e9n\u00e9reuse aux plus vuln\u00e9rables.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Toutefois, quand les strat\u00e9gies d\u2019adaptation innovantes d\u2019une communaut\u00e9 arrivent \u00e0 la limite de leurs possibilit\u00e9s, les populations commencent \u00e0 envisager de partir. Le point de basculement survient lorsque, en plus de l\u2019\u00e9chec des strat\u00e9gies d\u2019adaptation, les relations commencent \u00e0 souffrir et que la sauvegarde des int\u00e9r\u00eats individuels et familiaux prend le dessus sur la g\u00e9n\u00e9rosit\u00e9 envers les autres. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>La d\u00e9cision de partir est g\u00e9n\u00e9ralement prise apr\u00e8s consultation, et il peut alors s\u2019ensuivre un vaste exode de la plupart des membres de la communaut\u00e9. Les d\u00e9cisions peuvent \u00e9galement \u00eatre prises individuellement, par exemple par des jeunes ayant atteint l\u2019\u00e2ge de la maturit\u00e9 qui s\u2019estiment oblig\u00e9s de subvenir \u00e0 leurs propres besoins. Aux antipodes, certains pr\u00e9f\u00e9reraient mourir sur leurs terres plut\u00f4t que d\u2019aller vivre ailleurs. Enfin, d\u2019autres envisageraient de chercher refuge dans un pays voisin, mais \u00e0 la seule condition que la religion principale soit la m\u00eame que la leur. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><strong><span lang=\"FR\"><span>Faciliter l\u2019int\u00e9gration<\/span><\/span><\/strong><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Gr\u00e2ce \u00e0 l\u2019existence d\u2019une culture d\u00e9mocratique, d\u2019affinit\u00e9s nationales, d\u2019une ethnicit\u00e9 commune et de liens familiaux des deux c\u00f4t\u00e9s de la fronti\u00e8re, les communaut\u00e9s d\u2019accueil sont pr\u00e9dispos\u00e9es \u00e0 accueillir \u00e0 bras ouverts les personnes forc\u00e9es de se d\u00e9placer. Les autorit\u00e9s mauritaniennes adoptent depuis plusieurs d\u00e9cennies une politique de porte ouverte \u00e0 l\u2019\u00e9gard des r\u00e9fugi\u00e9s maliens et ont m\u00eame demand\u00e9 aux Mauritaniens d\u2019accueillir les r\u00e9fugi\u00e9s et de les consid\u00e9rer comme leurs fr\u00e8res et s\u0153urs. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>L\u2019\u00e9levage de b\u00e9tail et, dans une moindre mesure, de petits ruminants est l\u2019activit\u00e9 la plus importante entreprise par la majorit\u00e9 des r\u00e9fugi\u00e9s maliens. En outre, le troupeau de b\u00e9tail est une indication de la richesse (des \u00e9conomies pouvant \u00eatre transform\u00e9es en liquidit\u00e9s) et du statut de son propri\u00e9taire. Pour s\u2019int\u00e9grer facilement dans le pays d\u2019accueil, les r\u00e9fugi\u00e9s maliens recourent \u00e0 diverses strat\u00e9gies, notamment en r\u00e9tablissant, en reconstruisant ou en adaptant leurs moyens d\u2019existence. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>En ce qui concerne le r\u00e9tablissement, deux options se pr\u00e9sentent aux personnes d\u00e9plac\u00e9es qui sont parties \u00e0 la h\u00e2te. Elles peuvent demander \u00e0 un guide fiable de conduire leur troupeau jusqu\u2019\u00e0 un lieu s\u00fbr et accessible, probablement avec l\u2019aide d\u2019amis de confiance ou d\u2019autorit\u00e9s administratives ou traditionnelles qui garantiraient la travers\u00e9e. Sinon, elles peuvent prendre le risque de retourner chercher elles-m\u00eames leurs animaux. Par ailleurs, la reconstruction des moyens d\u2019existence est parfois possible gr\u00e2ce \u00e0 une s\u00e9lection intelligente des animaux qui donnent le plus de lait, qui ont le plus grand nombre de petits ou qui produisent le plus de viande, et qui servent alors de capital de d\u00e9part pour commencer \u00e0 se reconstituer un troupeau dans le pays d\u2019asile. S\u2019il n\u2019est pas possible de reconstruire ainsi leurs moyens d\u2019existence, les r\u00e9fugi\u00e9s choisiront alors de s\u2019adapter en embrassant l\u2019une des options disponibles dans le pays d\u2019asile, parfois par l\u2019interm\u00e9diaire de partenaires financ\u00e9s par des donateurs, et en l\u2019utilisant comme un tremplin pour reprendre progressivement la production de petits ruminants puis de b\u00e9tail. Il est \u00e9galement possible de poursuivre ces strat\u00e9gies simultan\u00e9ment. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><strong><span lang=\"FR\"><span>Strat\u00e9gies d\u2019adaptation <\/span><\/span><\/strong><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Les r\u00e9fugi\u00e9s maliens de Mbera sont parvenus \u00e0 reproduire plusieurs innovations \u00e9labor\u00e9es au Mali en r\u00e9ponse au changement climatique, notamment le jardinage (\u00e0 des fins de consommation domestique) et le travail en association pour r\u00e9duire les pressions sur les ressources naturelles et la d\u00e9gradation environnementale. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Seuls 1,3&nbsp;% des m\u00e9nages r\u00e9fugi\u00e9s \u00e9tablis \u00e0 Mbera avaient des connaissances agricoles lorsqu\u2019ils sont arriv\u00e9s au camp&nbsp;; toutefois, au 31 d\u00e9cembre 2019, les statistiques dont dispose le HCR indiquent qu\u2019environ 10&nbsp;% des m\u00e9nages dans la communaut\u00e9 totale des r\u00e9fugi\u00e9s pratiquaient le <strong>jardinage<\/strong>, soit de mani\u00e8re ind\u00e9pendante soit avec l\u2019assistance des partenaires du HCR dans le camp. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Les r\u00e9fugi\u00e9s reproduisent plusieurs techniques qu\u2019ils utilisaient d\u00e9j\u00e0 pour contourner les impacts n\u00e9gatifs du changement climatique lorsqu\u2019ils vivaient au Mali. Premi\u00e8rement, ils ont amen\u00e9 avec eux des vari\u00e9t\u00e9s r\u00e9sistantes \u00e0 la chaleur, inconnues de la communaut\u00e9 d\u2019accueil, notamment des oignons rouges et des graines de tomates. Deuxi\u00e8mement, ils ont adopt\u00e9 des pratiques respectueuses de l\u2019environnement, telles que la production de compost pour favoriser la fertilit\u00e9 des sols, alors que la norme au sein de la communaut\u00e9 d\u2019accueil consistait \u00e0 utiliser du fumier non-ferment\u00e9, ce qui a pour cons\u00e9quence n\u00e9gative de favoriser les invasions de fourmis soldats. Enfin, elles ont commenc\u00e9 \u00e0 utiliser des techniques autochtones de conservation de l\u2019eau, notamment l\u2019utilisation de lits de semences enfouis circulaires, au lieu des lits plats ou des lits enfouis rectangulaires g\u00e9n\u00e9ralement utilis\u00e9s par les Mauritaniens. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>L\u2019usage conjugu\u00e9 de ces techniques a donn\u00e9 des rendements impressionnants lors de la saison agricole 2019 et ces bons r\u00e9sultats obtenus par les r\u00e9fugi\u00e9s ont stimul\u00e9 l\u2019int\u00e9r\u00eat de la communaut\u00e9 d\u2019accueil pour ces activit\u00e9s. R\u00e9cemment, une visite d\u2019\u00e9change conjointe organis\u00e9e dans le camp de Mbera par les diff\u00e9rents partenaires et le HCR a donn\u00e9 aux r\u00e9fugi\u00e9es maliennes pratiquant le jardinage l\u2019occasion de partager leurs exp\u00e9riences avec des femmes de la communaut\u00e9 d\u2019accueil en mati\u00e8re de gestion de l\u2019eau, d\u2019am\u00e9lioration de la fertilit\u00e9 des sols et de techniques naturelles de contr\u00f4le des nuisibles. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span><span><span lang=\"FR\"><span>La Mauritanie a vot\u00e9 plusieurs lois visant \u00e0 prot\u00e9ger ses ressources naturelles contre la surexploitation, dont l\u2019application est confi\u00e9e au minist\u00e8re de l\u2019Environnement et du D\u00e9veloppement durable. Lorsque ce minist\u00e8re n\u2019a aucune pr\u00e9sence v\u00e9ritable dans une r\u00e9gion du pays, comme c\u2019est le cas dans le district de Bassikounou o\u00f9 le camp de Mbera est situ\u00e9, des Associations pour la gestion des ressources naturelles (AGRN) sont \u00e9tablies pour r\u00e9guler l\u2019acc\u00e8s aux ressources naturelles et la r\u00e9habilitation de ces derni\u00e8res. Toutefois, dans le camp de Mbera, o\u00f9 les AGRN n\u2019existent pas, les r\u00e9fugi\u00e9s se sont inspir\u00e9s de leurs propres exp\u00e9riences dans leur pays d\u2019origine pour \u00e9tablir plusieurs <strong>associations<\/strong> visant \u00e0 combattre la d\u00e9gradation environnementale. Par exemple, un groupe appel\u00e9 Volontaires R\u00e9fugi\u00e9s pour la Propri\u00e9t\u00e9 du Camp organise r\u00e9guli\u00e8rement des campagnes de nettoyage au sein du camp, qu\u2019ils \u00e9largissent parfois pour inclure la communaut\u00e9 d\u2019accueil. <\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span><span><span lang=\"FR\"><span>Parall\u00e8lement, au cours des cinq derni\u00e8res ann\u00e9es, des associations de reboisement ont plant\u00e9 plus de 60&nbsp;000 esp\u00e8ces d\u2019arbre adapt\u00e9es aux conditions locales distribu\u00e9es par SOS D\u00e9sert. Ces campagnes sont g\u00e9n\u00e9ralement organis\u00e9es lors des c\u00e9l\u00e9brations de la Journ\u00e9e mondiale de l\u2019environnement (5 juin) et de la Journ\u00e9e nationale de l\u2019arbre (premi\u00e8re semaine d\u2019ao\u00fbt). Ces actions, conduites par les r\u00e9fugi\u00e9s, ont contribu\u00e9 \u00e0 r\u00e9cuser l\u2019id\u00e9e que les r\u00e9fugi\u00e9s \u00e9taient les principaux responsables de la d\u00e9t\u00e9rioration de l\u2019environnement. Au contraire, ils sont aujourd\u2019hui per\u00e7us comme des partenaires du changement. <\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>De la m\u00eame mani\u00e8re, les r\u00e9fugi\u00e9s ont appris au contact de la communaut\u00e9 d\u2019accueil et adopt\u00e9 les pratiques locales respectueuses de l\u2019environnement. Par exemple, les feux de brousse comptent parmi les pires d\u00e9gradations environnementales en Mauritanie. Suite \u00e0 des campagnes de sensibilisation et \u00e0 des directives expliquant comment sonner l\u2019alarme en cas de feu de brousse, le nombre de nouveaux incendies de ce type et de catastrophes connexes a \u00e9t\u00e9 r\u00e9duit \u00e0 quatre seulement en 2019. Les r\u00e9fugi\u00e9s maliens, qui avaient peu de connaissances en mati\u00e8re de contr\u00f4le des incendies, disposent aujourd\u2019hui d\u2019une brigade de pompiers et interviennent aux c\u00f4t\u00e9s des brigades de la communaut\u00e9 d\u2019accueil et des gendarmes pour lutter contre les incendies. Ils ont \u00e9galement particip\u00e9 aux mesures pr\u00e9ventives, par exemple \u00e0 l\u2019\u00e9tablissement de plus de 100&nbsp;km de pare-feux. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Gr\u00e2ce \u00e0 leur disposition \u00e0 <strong>apprendre<\/strong>, les r\u00e9fugi\u00e9s ont \u00e9galement adopt\u00e9 des techniques d\u2019engraissage des petits ruminants, qui permettent \u00e0 ces animaux de prendre davantage de poids en consommant le m\u00eame volume de p\u00e2ture, ce qui permet de r\u00e9duire la pression sur les p\u00e2turages sur le long terme. En outre, les r\u00e9fugi\u00e9s maliens ont, par exemple, \u00e9galement commenc\u00e9 \u00e0 faire appel \u00e0 des services para-v\u00e9t\u00e9rinaires, qui n\u2019existaient pas dans leur communaut\u00e9 d\u2019origine mais qui sont pr\u00e9sents dans la communaut\u00e9 d\u2019accueil. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Les \u00e9changes de connaissances locales se font par le biais de canaux formels et informels. Parmi les canaux informels, on peut citer les interactions entre les membres des communaut\u00e9s lorsqu\u2019ils se rencontrent aux points d\u2019eau, sur les p\u00e2turages, sur les march\u00e9s hebdomadaires ou lors de c\u00e9r\u00e9monies festives. Quant aux plates-formes d\u2019interaction formelles, elles sont souvent \u00e9tablies par les agences de l\u2019ONU et les autres partenaires intervenant sur les sites d\u2019accueil lors d\u2019\u00e9v\u00e9nements marquant des journ\u00e9es internationales d\u2019observance et de militantisme, \u00e0 l\u2019instar de la Journ\u00e9e mondiale des r\u00e9fugi\u00e9s et de la Journ\u00e9e internationale pour l\u2019\u00e9limination de la violence \u00e0 l\u2019\u00e9gard des femmes. Par ailleurs, une agence partenaire a facilit\u00e9 l\u2019\u00e9tablissement de comit\u00e9s communautaires mixtes (communaut\u00e9s d\u2019accueil et de r\u00e9fugi\u00e9s) dans les villages du district de Bassikounou. Ils sont charg\u00e9s de la gestion des conflits, notamment en mati\u00e8re d\u2019acc\u00e8s aux ressources naturelles.&nbsp; <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><strong><span lang=\"FR\"><span>Remettre en question les id\u00e9es re\u00e7ues<\/span><\/span><\/strong><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Il faut remettre en question cette perception courante selon laquelle un influx de r\u00e9fugi\u00e9s ou de personnes cherchant \u00e0 se r\u00e9installer ailleurs \u00e0 cause d\u2019une crise climatique, d\u2019un conflit ou des deux, est forc\u00e9ment toujours n\u00e9gatif. Les r\u00e9fugi\u00e9s apportent une multitude de nouvelles ressources, y compris des ressources humaines acquises en r\u00e9ponse \u00e0 des crises climatiques dans leur pays d\u2019origine. Ces exp\u00e9riences leur permettent souvent de s\u2019attaquer \u00e0 des difficult\u00e9s semblables dans leur pays d\u2019asile et d\u2019inspirer les citoyens de ce pays \u00e0 en faire de m\u00eame. Sur le long terme, la mobilisation du potentiel et de l\u2019inventivit\u00e9 des communaut\u00e9s de r\u00e9fugi\u00e9s et d\u2019accueil peuvent fa\u00e7onner la r\u00e9ponse des pays face \u00e0 la crise climatique, contribuer \u00e0 la promotion de la s\u00e9curit\u00e9 alimentaire et de pratiques favorisant la protection des ressources naturelles et, parall\u00e8lement, garantir la protection des r\u00e9fugi\u00e9s.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span><span><span><span lang=\"FR\"><span>Fouda Ndikintum <\/span><\/span><a href=\"mailto:ndiki@unhcr.org\"><em><span><span>ndiki@unhcr.org<\/span><\/span><\/em><\/a><em> <\/em><\/span><\/span><\/span><br \/>\n<span><span><span><span lang=\"FR\"><span>Charg\u00e9 des moyens d\u2019existence au sous-bureau du HCR de Bassikounou, Mauritanie <\/span><\/span><a href=\"https:\/\/data2.unhcr.org\/en\/country\/mrt\"><em><span><span>https:\/\/data2.unhcr.org\/en\/country\/mrt<\/span><\/span><\/em><\/a><em> <\/em><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>Mohamed Ag Malha <\/span><\/span><a href=\"mailto:jnasat2811@gmail.com\"><span><span>jnasat2811@gmail.com<\/span><\/span><\/a><br \/>\n<span lang=\"FR\"><span>Pr\u00e9sident du conseil des r\u00e9fugi\u00e9s du camp de Mbera, Mauritanie<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span>Cet article est l\u2019expression d\u2019opinions personnelles et ne repr\u00e9sente pas n\u00e9cessairement les perspectives des organisations cit\u00e9es.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span><span><a href=\"#_ednref1\" name=\"_edn1\"><span><span lang=\"FR\"><span><span><span lang=\"FR\"><span><span>[1]<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/a><span lang=\"FR\"><span> 61,3&nbsp;% de Touaregs, 37,2&nbsp;% d\u2019Arabes et 1,5&nbsp;% d\u2019autres tribus minoritaires<\/span><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Mauritanie accueille actuellement 60&nbsp;511 r\u00e9fugi\u00e9s ayant fui le Mali en 2012. Originaires du nord du Mali, ils vivent aujourd\u2019hui dans le camp de Mbera et en p\u00e9riph\u00e9rie, dans le sud-est de la Mauritanie.[1] C\u2019est l\u2019ins\u00e9curit\u00e9 croissante qui les a pouss\u00e9s \u00e0 quitter leur r\u00e9gion d\u2019origine. Toutefois, avant de fuir, la plupart d\u2019entre eux subissaient&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42359,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[112],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[569],"class_list":["post-42158","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-112","fmr_content_type-article","fmr_languages-french","fmr_list_years-569","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e9silience, adaptation et apprentissage : les r\u00e9fugi\u00e9s maliens et leurs h\u00f4tes mauritaniens - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9silience, adaptation et apprentissage : les r\u00e9fugi\u00e9s maliens et leurs h\u00f4tes mauritaniens - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"La Mauritanie accueille actuellement 60&nbsp;511 r\u00e9fugi\u00e9s ayant fui le Mali en 2012. Originaires du nord du Mali, ils vivent aujourd\u2019hui dans le camp de Mbera et en p\u00e9riph\u00e9rie, dans le sud-est de la Mauritanie.[1] C\u2019est l\u2019ins\u00e9curit\u00e9 croissante qui les a pouss\u00e9s \u00e0 quitter leur r\u00e9gion d\u2019origine. Toutefois, avant de fuir, la plupart d\u2019entre eux subissaient&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-20T05:34:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/\",\"url\":\"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/\",\"name\":\"R\u00e9silience, adaptation et apprentissage : les r\u00e9fugi\u00e9s maliens et leurs h\u00f4tes mauritaniens - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2020-06-16T05:00:00+00:00\",\"dateModified\":\"2024-11-20T05:34:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FMR 64 &#8211; Crise climatique et communaut\u00e9s locales\",\"item\":\"https:\/\/www.fmreview.org\/numero64\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"R\u00e9silience, adaptation et apprentissage : les r\u00e9fugi\u00e9s maliens et leurs h\u00f4tes mauritaniens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9silience, adaptation et apprentissage : les r\u00e9fugi\u00e9s maliens et leurs h\u00f4tes mauritaniens - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/","og_locale":"es_ES","og_type":"article","og_title":"R\u00e9silience, adaptation et apprentissage : les r\u00e9fugi\u00e9s maliens et leurs h\u00f4tes mauritaniens - Forced Migration Review","og_description":"La Mauritanie accueille actuellement 60&nbsp;511 r\u00e9fugi\u00e9s ayant fui le Mali en 2012. Originaires du nord du Mali, ils vivent aujourd\u2019hui dans le camp de Mbera et en p\u00e9riph\u00e9rie, dans le sud-est de la Mauritanie.[1] C\u2019est l\u2019ins\u00e9curit\u00e9 croissante qui les a pouss\u00e9s \u00e0 quitter leur r\u00e9gion d\u2019origine. Toutefois, avant de fuir, la plupart d\u2019entre eux subissaient&hellip;","og_url":"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/","og_site_name":"Forced Migration Review","article_modified_time":"2024-11-20T05:34:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/","url":"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/","name":"R\u00e9silience, adaptation et apprentissage : les r\u00e9fugi\u00e9s maliens et leurs h\u00f4tes mauritaniens - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2020-06-16T05:00:00+00:00","dateModified":"2024-11-20T05:34:40+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/numero64\/ndikintum-agmalha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/es\/"},{"@type":"ListItem","position":2,"name":"FMR 64 &#8211; Crise climatique et communaut\u00e9s locales","item":"https:\/\/www.fmreview.org\/numero64\/"},{"@type":"ListItem","position":3,"name":"R\u00e9silience, adaptation et apprentissage : les r\u00e9fugi\u00e9s maliens et leurs h\u00f4tes mauritaniens"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/42158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/42158\/revisions"}],"predecessor-version":[{"id":42861,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/42158\/revisions\/42861"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content\/42359"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/media?parent=42158"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_themes?post=42158"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_region?post=42158"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_issue?post=42158"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_year?post=42158"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_content_type?post=42158"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_languages?post=42158"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/es\/wp-json\/wp\/v2\/fmr_list_years?post=42158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}