{"id":40598,"date":"2015-09-02T00:00:00","date_gmt":"2015-09-02T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/"},"modified":"2025-04-01T07:32:16","modified_gmt":"2025-04-01T12:32:16","slug":"mlinarevic-isakovic-rees-2-2","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/fr\/mlinarevic-isakovic-rees-2-2\/","title":{"rendered":"Si se deja a las mujeres fuera de las conversaciones de paz"},"content":{"rendered":"<p>La narrativa sobre la guerra suele retratar a las mujeres &uacute;nicamente como v&iacute;ctimas, despoj&aacute;ndolas de su voluntad y dej&aacute;ndolas sin voz ni voto en la reconstrucci&oacute;n de su pa&iacute;s. Sin embargo, que las mujeres hayan sido v&iacute;ctimas de la violencia y que participen activamente en el establecimiento y en la consolidaci&oacute;n de la paz no es incompatible, y ambos aspectos deben ser reconocidos durante las negociaciones de paz.<\/p>\n<p><span style=\"line-height: 1.5em;\">Durante el proceso de paz que precedi&oacute; a la firma del Acuerdo de Paz de <\/span>Dayton<span style=\"line-height: 1.5em;\"> en 1995 no particip&oacute; ni una sola mujer, ni como mediadora, ni como testigo, ni como miembro del equipo de negociaciones o signataria<\/span><a href=\"#_edn1\" name=\"_ednref1\" style=\"line-height: 1.5em;\" title=\"\">[1]<\/a><span style=\"line-height: 1.5em;\">. Su ausencia en este proceso oficial ha tenido ciertas consecuencias para la sociedad en su conjunto y tambi&eacute;n para las mujeres como colectivo dentro ella, y sobre la posibilidad de ser reconocidas como agentes del cambio en posteriores procesos.<\/span><\/p>\n<p><span style=\"line-height: 1.5em;\">La mesa de negociaci&oacute;n de <\/span>Dayton<span style=\"line-height: 1.5em;\"> s&oacute;lo ten&iacute;a sillas para hombres que ven&iacute;an respaldados por el poder de las fuerzas armadas. Bajo la pretensi&oacute;n de garantizar los derechos humanos, estas <\/span>&eacute;lites<span style=\"line-height: 1.5em;\"> masculinas consiguieron llegar a un acuerdo acerca de la f&oacute;rmula para dividir el territorio. <\/span>Bosnia-Herzegovina<span style=\"line-height: 1.5em;\"> se encuentra a d&iacute;a de hoy paralizada por la falta de funcionalidad del aparato estatal central y las pol&iacute;ticas nacionalistas basadas en cuestiones &eacute;tnicas que son los detonantes comunes de las dos entidades creadas por el Acuerdo de <\/span>Dayton<a href=\"#_edn2\" name=\"_ednref2\" style=\"line-height: 1.5em;\" title=\"\">[2]<\/a><span style=\"line-height: 1.5em;\">. La <\/span>&eacute;lite<span style=\"line-height: 1.5em;\"> pol&iacute;tica nacional no ha intentado de verdad incluir las perspectivas de las mujeres en los debates sobre reformas constitucionales. Y tampoco se consigui&oacute; el respaldo de la comunidad internacional implicada en las acciones para facilitar estos debates. El argumento <\/span>\u2012o<span style=\"line-height: 1.5em;\"> la <\/span>excusa\u2012<span style=\"line-height: 1.5em;\"> es que las mujeres ya est&aacute;n incluidas <\/span><em style=\"line-height: 1.5em;\">de facto<\/em><span style=\"line-height: 1.5em;\"> por su participaci&oacute;n en la vida pol&iacute;tica e institucional de <\/span>Bosnia-Herzegovina<span style=\"line-height: 1.5em;\">, entre otras cosas, a trav&eacute;s de su militancia en partidos. Pero la realidad es bien diferente y es que la representaci&oacute;n femenina es insuficiente o inadecuada.<\/span><\/p>\n<p>La ausencia de mujeres durante las negociaciones de paz no es exclusiva de Bosnia-Herzegovina. ONU Mujeres public&oacute; en 2012 un an&aacute;lisis de 31 procesos de paz en el que se demostraba que s&oacute;lo en el 4% de ellos participaron mujeres en calidad de signatarias. M&aacute;s recientemente, en las conversaciones de paz para Siria de Ginebra II, a pesar del apoyo de los Estados y de las ONG internacionales y de la existencia de la Resoluci&oacute;n 1325 del Consejo de Seguridad de las Naciones Unidas (RCSONU 1325) sobre mujeres, paz y seguridad<a href=\"#_edn3\" name=\"_ednref3\" title=\"\">[3]<\/a>, se dej&oacute; a las sirias fuera de las conversaciones de paz. Esto no solo es una afrenta patente a las obligaciones jur&iacute;dicas internacionales sino tambi&eacute;n un gran desperdicio. Cuando prominentes organizaciones internacionales y locales de mujeres sirias pidieron a las Naciones Unidas que garantizaran su inclusi&oacute;n en las negociaciones de paz de su pa&iacute;s en 2014, se les respondi&oacute; que &ldquo;la situaci&oacute;n pol&iacute;tica era complicada&rdquo;. Eso ya lo sab&iacute;amos. Pero la soluci&oacute;n no consiste en perpetuar la divisi&oacute;n que, en primera instancia, llev&oacute; al pa&iacute;s a la guerra. Los estudios muestran claramente que los &uacute;nicos tratados que han conseguido una situaci&oacute;n de paz sostenible son aquellos que han sido redactados con la participaci&oacute;n de las mujeres y con la clara inclusi&oacute;n de un an&aacute;lisis de g&eacute;nero a la hora de redactar el marco para la conclusi&oacute;n del conflicto, para la transici&oacute;n y para el futuro curso de la naci&oacute;n<a href=\"#_edn4\" name=\"_ednref4\" title=\"\">[4]<\/a>.<\/p>\n<p><strong>Crear un espacio para la inclusi&oacute;n y la participaci&oacute;n<\/strong><\/p>\n<p>Compartir las experiencias de las mujeres en las negociaciones de paz y en la vida de la posguerra se ha convertido en un imperativo para las activistas feministas por la paz con el fin de crear espacios para una inclusi&oacute;n significativa de las mujeres y su participaci&oacute;n activa en el establecimiento de la paz. Desde 2013 numerosas organizaciones de mujeres y activistas en Bosnia-Herzegovina, ayudadas por la Liga Internacional de Mujeres por la Paz y la Libertad, empezaron a trabajar para contrarrestar la mentalidad excluyente de las &eacute;lites pol&iacute;ticas mediante una iniciativa llamada &ldquo;Las Mujeres se Organizan para el Cambio en Siria y Bosnia-Herzegovina&rdquo;. La idea inicial era que las duras lecciones aprendidas por las bosnias \u2012durante y despu&eacute;s de la guerra\u2012 fuesen analizadas y utilizadas para desarrollar nuevas y mejores estrategias para que las mujeres tuvieran una participaci&oacute;n activa y significativa en los procesos de paz. Este conocimiento se podr&iacute;a compartir con otras cong&eacute;neres en situaciones similares para evitar errores y para que se tuvieran en consideraci&oacute;n y se contextualizaran las buenas pr&aacute;cticas. Al mismo tiempo, es una oportunidad para trazar caminos hacia la creaci&oacute;n de un movimiento femenino basado en principios feministas en Bosnia-Herzegovina que podr&aacute; actuar m&aacute;s all&aacute; de las pol&iacute;ticas nacionalistas basadas en divisoras cuestiones &eacute;tnicas<a href=\"#_edn5\" name=\"_ednref5\" title=\"\">[5]<\/a>.<\/p>\n<p><span style=\"line-height: 1.5em;\">Las <\/span>activistas<span style=\"line-height: 1.5em;\"> de <\/span>Bosnia-Herzegovina<span style=\"line-height: 1.5em;\"> se encontraron con casos de &eacute;xito pero tambi&eacute;n con muchos fracasos a lo largo de los &uacute;ltimos veinte a&ntilde;os. La mayor&iacute;a se pod&iacute;an achacar a dos factores: en primer lugar, a un acuerdo de paz fallido cuyo prop&oacute;sito era acabar con el conflicto armado pero que no conten&iacute;a los elementos necesarios para establecer una paz <\/span>sostenible<span style=\"line-height: 1.5em;\">. Y, en segundo lugar, el hecho de que las mujeres y la sociedad civil no tomaran parte en las negociaciones de paz.<\/span><\/p>\n<p><span style=\"line-height: 1.5em;\">Durante la guerra, las mujeres participaron activamente en distintas tareas para paliar las consecuencias de la violencia y en actividades de vital importancia para la supervivencia de las comunidades; asist&iacute;an a las personas desplazadas internas y a las v&iacute;ctimas de la violencia sexual; iban a trabajar \u2012desafiando a los francotiradores y los bombardeos\u2012 para mantener las f&aacute;bricas en funcionamiento; y algunas promov&iacute;an el di&aacute;logo entre comunidades en medio de la guerra. Sin embargo, no exist&iacute;a ning&uacute;n mecanismo que permitiera trasladar esas experiencias a las negociaciones de paz oficiales. La Resoluci&oacute;n 1325, que ped&iacute;a la participaci&oacute;n activa y significativa de las mujeres en todas las fases de establecimiento y consolidaci&oacute;n de la paz, se adopt&oacute; cinco a&ntilde;os despu&eacute;s de que finalizara la guerra de Bosnia.<\/span><\/p>\n<p><span style=\"line-height: 1.5em;\">Las mujeres siguieron organiz&aacute;ndose tras la guerra, algunas para exigir la verdad acerca de los familiares desaparecidos, otras para pedir que se las incluyera en las pol&iacute;ticas oficiales. Tambi&eacute;n las hubo que lideraron el dif&iacute;cil proceso de repatriaci&oacute;n, a menudo a lugares en los que muchas de ellas hab&iacute;an perdido a parientes cercanos o en los que ellas mismas hab&iacute;an sido convertidas en v&iacute;ctimas. Eran las que ten&iacute;an pr&aacute;ctica y experiencia en saber el tiempo que se tardar&iacute;a en hacer que el retorno fuera sostenible, no s&oacute;lo el de la propiedad (que era el principal foco de la comunidad internacional) sino tambi&eacute;n el acceso a derechos econ&oacute;micos, sociales y pol&iacute;ticos.<\/span><\/p>\n<p><strong style=\"line-height: 1.5em;\">El fracaso en el compromiso con cuestiones de g&eacute;nero<\/strong><\/p>\n<p>Muchos de los problemas que surgieron tras la guerra se podr&iacute;an haber evitado si hubiese habido un compromiso pol&iacute;tico m&aacute;s firme durante las conversaciones de paz y se hubiera contado con la participaci&oacute;n de representantes femeninas de la sociedad civil y asesores especializados en cuestiones de g&eacute;nero. La violencia dom&eacute;stica, la trata, la sanidad, la educaci&oacute;n, el empleo&#8230; todo esto est&aacute; relacionado con cuestiones de g&eacute;nero y deber&iacute;an haberse incluido como factores en la transici&oacute;n cuidadosamente planificada en la Bosnia-Herzegovina de posguerra. En su lugar, cuestiones reconocidas como &ldquo;graves&rdquo; o de inter&eacute;s &eacute;tnico y nacional (como la educaci&oacute;n) o de especial importancia para la econom&iacute;a pol&iacute;tica (como el empleo y la salud) se utilizaron para consolidar tanto las posturas nacionalistas basadas en cuestiones &eacute;tnicas como las neoliberales. La jurisdicci&oacute;n sobre estas cuestiones ya se hab&iacute;a dividido entre las diferentes &eacute;lites &ldquo;etnonacionalistas&rdquo; en Dayton, sin abordar ninguno de sus aspectos discriminatorios o de g&eacute;nero.<\/p>\n<p><span style=\"line-height: 1.5em;\">Las cuestiones reconocidas exclusivamente como &ldquo;de mujeres&rdquo; \u2012y por tanto, no de especial importancia para la redistribuci&oacute;n de los poderes y recursos\u2012 se ignoraron en Dayton y se dej&oacute; a las organizaciones de mujeres para que lidiaran con ellas. El cl&aacute;sico ejemplo es la violencia dom&eacute;stica, la cuesti&oacute;n que menos tiene que ver con la pol&iacute;tica &eacute;tnica. A las mujeres de Bosnia-Herzegovina se les concedi&oacute; un espacio para abordar estas cuestiones, y la &eacute;lite pol&iacute;tica masculina no interfiri&oacute; de manera sustancial dado que este tipo de violencia refleja a las mujeres como v&iacute;ctimas y no como personas con poder o con capacidad de tomar decisiones. Aunque las causas de la violencia dom&eacute;stica no se abordaron adecuadamente, se aprobaron nuevas leyes mejoradas a este respecto que fueron creadas por las ONG de mujeres y llevadas al Parlamento por parlamentarias.<\/span><\/p>\n<p><span style=\"line-height: 1.5em;\">No obstante, la cuesti&oacute;n de la violencia sexual en tiempos de guerra sigue estando muy politizada. Los nacionalismos pretenden aprovecharse del relato de las atrocidades cometidas por los otros con respecto a &ldquo;sus mujeres&rdquo;. Esta cosificaci&oacute;n y conversi&oacute;n de la mujer en un bien se reflejaba en el modo en que evolucion&oacute; el proceso de paz, en especial en lo que respecta al acceso a la justicia. En lugar de adoptar un enfoque para tratar y mejorar la situaci&oacute;n de las supervivientes que tambi&eacute;n tuviera unas repercusiones m&aacute;s amplias y transformadoras sobre la sociedad, la reacci&oacute;n de las &eacute;lites de una y otra parte han sido, en el mejor de los casos, ambivalentes y, en el peor, capciosas. Algunas de las cuestiones elevadas por los colectivos de mujeres ten&iacute;an que ver con la reparaci&oacute;n transformadora. Sin embargo, la respuesta fue &ldquo;conceder&rdquo; una especie de compensaci&oacute;n que era m&aacute;s una ayuda social que una reparaci&oacute;n de los abusos sufridos durante la guerra, lo que al final obligaba a las mujeres a depender de la asistencia social. Y ni siquiera esta especie de compensaci&oacute;n se concedi&oacute; a todas las supervivientes sino solo a aquellas que viv&iacute;an en la Federaci&oacute;n o que reun&iacute;an una serie de (problem&aacute;ticos) requisitos.<\/span><\/p>\n<p><span style=\"line-height: 1.5em;\">En los &uacute;ltimos m&aacute;s de 20 a&ntilde;os las ONG bosnias han tenido que adquirir una experiencia considerable en lo que respecta a la provisi&oacute;n de servicios como asistencia m&eacute;dica y apoyo psicosocial. Mientras tanto, las instituciones oficiales como los centros para el cuidado de la salud mental y los de bienestar social han hecho poco o nada para mejorar su capacidad de provisi&oacute;n de ayuda y servicios. Los supervivientes reciben hoy en d&iacute;a asistencia s&oacute;lo a trav&eacute;s de las ONG, que siguen dependiendo del apoyo de donantes extranjeros para poder seguir con su vital trabajo.<\/span><\/p>\n<p><span style=\"line-height: 1.5em;\">Existe un v&iacute;nculo inherente entre el modo en que dichos servicios han sido &ldquo;externalizados&rdquo; y la consecuci&oacute;n de una justicia real. Los aspectos jur&iacute;dicos formales de la Bosnia-Herzegovina de posguerra creados (el Tribunal Penal Internacional para la antigua Yugoslavia, el Tribunal de Bosnia-Herzegovina, etc.) ofrecen un marco para la rendici&oacute;n de cuentas por acciones delictivas pero han fracasado a la hora de proporcionar una justicia global. La noci&oacute;n de justicia ha sido demasiado limitada y ha quedado reducida a procesar y condenar a los que perpetraron los delitos (al principio &eacute;stas eran tambi&eacute;n las exigencias de las propias v&iacute;ctimas).<\/span><\/p>\n<p><span style=\"line-height: 1.5em;\">Se deber&iacute;a haber complementado el establecimiento de estos mecanismos de justicia oficiales, prestando atenci&oacute;n seriamente a los derechos sociales y econ&oacute;micos, de forma que la reconstrucci&oacute;n de Bosnia-Herzegovina tras la guerra hubiera estado respaldada por un proceso de transici&oacute;n transformador. S&oacute;lo mediante un proceso inclusivo se podr&iacute;an haber detectado las necesidades, por lo que la ausencia de las mujeres hizo que el fracaso fuera inevitable. Esto sigue siendo un reto, dado que &nbsp;la &ldquo;silla&rdquo; en la mesa de negociaci&oacute;n ha demostrado ser irrecuperable.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Gorana Mlinarevi\u0107 <em><a href=\"mailto:g.mlinarevic@gold.ac.uk\">g.mlinarevic@gold.ac.uk<\/a><\/em><\/p>\n<p>Investigadora, Proyecto Justicia de G&eacute;nero, Goldsmiths, Universidad de Londres. <em><a href=\"http:\/\/www.gold.ac.uk\/genderofjustice\">www.gold.ac.uk\/genderofjustice<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Nela Porobi\u0107 Isakovi\u0107 <em><a href=\"mailto:nporobic@wilpf.ch\">nporobic@wilpf.ch<\/a><\/em><\/p>\n<p>Coordinadora de proyectos, Mujeres organizadas para el cambio en Siria y Bosnia-Herzegovina, Liga Internacional de Mujeres por la Paz y la Libertad. <em><a href=\"http:\/\/womenorganizingforchange.org\/en\">http:\/\/womenorganizingforchange.org\/en<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Madeleine Rees <em><a href=\"mailto:mrees@wilfp.ch\">mrees@wilfp.ch<\/a><\/em><\/p>\n<p>Secretaria General, Liga Internacional de Mujeres por la Paz y la Libertad. <em><a href=\"http:\/\/www.wilpfinternational.org\/\">www.wilpfinternational.org<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<div>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[1]<\/a> ONU Mujeres (2012) <em>Participaci&oacute;n de las mujeres en las negociaciones de paz: relaciones entre presencia e influencia,<\/em> p. 4 http:\/\/tinyurl.com\/ONUmujeres-negocpaz-2012<\/p>\n<\/p><\/div>\n<div id=\"edn2\">\n<p><a href=\"#_ednref2\" name=\"_edn2\" title=\"\">[2]<\/a> El Acuerdo de Paz de Dayton cre&oacute; una Bosnia-Herzegovina descentralizada y dividi&oacute; el pa&iacute;s en dos entidades, la Federaci&oacute;n de Bosnia-Herzegovina y la Rep&uacute;blica Srpska, con un d&eacute;bil Gobierno central.<\/p>\n<\/p><\/div>\n<div id=\"edn3\">\n<p><a href=\"#_ednref3\" name=\"_edn3\" title=\"\">[3]<\/a> <a href=\"http:\/\/www.refworld.org\/docid\/3b00f4672e.html\">www.refworld.org\/docid\/3b00f4672e.html<\/a><\/p>\n[Disponible en &aacute;rabe, espa&ntilde;ol y franc&eacute;s en el mismo enlace]\n<\/p><\/div>\n<div id=\"edn4\">\n<p><a href=\"#_ednref4\" name=\"_edn4\" title=\"\">[4]<\/a> V&eacute;ase, por ejemplo, Paffenholz T. (2014) <em>Civil Society and Peace Negotiations: Beyond the Inclusion<\/em>&ndash;<em>Exclusion<\/em><em> Dichotomy<\/em> [Sociedad Civil y Negociaciones de Paz: m&aacute;s all&aacute; de la dicotom&iacute;a entre la inclusi&oacute;n y la exclusi&oacute;n], <em>Negotiation Journal, <\/em>Vol. 30, N&ordm; 1, p&aacute;ginas 69-91.&nbsp;<\/p>\n<\/p><\/div>\n<div id=\"edn5\">\n<p><a href=\"#_ednref5\" name=\"_edn5\" title=\"\">[5]<\/a> Puede consultar los informes de todos los debates en la web <a href=\"http:\/\/womenorganizingforchange.org\/en\/events\/retrospective-exercise\/\">http:\/\/womenorganizingforchange.org\/en\/events\/retrospective-exercise\/<\/a><\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La narrativa sobre la guerra suele retratar a las mujeres &uacute;nicamente como v&iacute;ctimas, despoj&aacute;ndolas de su voluntad y dej&aacute;ndolas sin voz ni voto en la reconstrucci&oacute;n de su pa&iacute;s. Sin embargo, que las mujeres hayan sido v&iacute;ctimas de la violencia y que participen activamente en el establecimiento y en la consolidaci&oacute;n de la paz no&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[98],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[38],"fmr_list_years":[564],"class_list":["post-40598","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-98","fmr_content_type-article","fmr_languages-spanish","fmr_list_years-564","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Si se deja a las mujeres fuera de las conversaciones de paz - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Si se deja a las mujeres fuera de las conversaciones de paz - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"La narrativa sobre la guerra suele retratar a las mujeres &uacute;nicamente como v&iacute;ctimas, despoj&aacute;ndolas de su voluntad y dej&aacute;ndolas sin voz ni voto en la reconstrucci&oacute;n de su pa&iacute;s. Sin embargo, que las mujeres hayan sido v&iacute;ctimas de la violencia y que participen activamente en el establecimiento y en la consolidaci&oacute;n de la paz no&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T12:32:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/\",\"url\":\"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/\",\"name\":\"Si se deja a las mujeres fuera de las conversaciones de paz - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2015-09-02T05:00:00+00:00\",\"dateModified\":\"2025-04-01T12:32:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Si se deja a las mujeres fuera de las conversaciones de paz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Si se deja a las mujeres fuera de las conversaciones de paz - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Si se deja a las mujeres fuera de las conversaciones de paz - Forced Migration Review","og_description":"La narrativa sobre la guerra suele retratar a las mujeres &uacute;nicamente como v&iacute;ctimas, despoj&aacute;ndolas de su voluntad y dej&aacute;ndolas sin voz ni voto en la reconstrucci&oacute;n de su pa&iacute;s. Sin embargo, que las mujeres hayan sido v&iacute;ctimas de la violencia y que participen activamente en el establecimiento y en la consolidaci&oacute;n de la paz no&hellip;","og_url":"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-04-01T12:32:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/","url":"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/","name":"Si se deja a las mujeres fuera de las conversaciones de paz - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2015-09-02T05:00:00+00:00","dateModified":"2025-04-01T12:32:16+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/mlinarevic-isakovic-rees-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Si se deja a las mujeres fuera de las conversaciones de paz"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/40598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/40598\/revisions"}],"predecessor-version":[{"id":46244,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/40598\/revisions\/46244"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/media?parent=40598"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_themes?post=40598"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_region?post=40598"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_issue?post=40598"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_year?post=40598"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content_type?post=40598"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_languages?post=40598"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_list_years?post=40598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}