{"id":40599,"date":"2015-09-02T00:00:00","date_gmt":"2015-09-02T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/munro-2-2\/"},"modified":"2025-04-01T07:32:16","modified_gmt":"2025-04-01T12:32:16","slug":"munro-2-2","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/fr\/munro-2-2\/","title":{"rendered":"Las interpretaciones del Anexo 7: evaluaci\u00f3n del impacto sobre los no retornados en el Reino Unido"},"content":{"rendered":"<p>La mayor&iacute;a de las personas de Bosnia-Herzegovina que actualmente residen en el Reino Unido (RU) tomaron la decisi&oacute;n de abandonar su pa&iacute;s de origen y crear un nuevo hogar temporal o permanente all&iacute; como consecuencia directa de la guerra que tuvo lugar entre 1992 y 1995. Todos aquellos que llegaron al Reino Unido en la d&eacute;cada de los noventa formaban parte de uno de estos tres colectivos: los que llegaron como parte del Proyecto Bosnia promovido por el Gobierno del Reino Unido (compuesto por hasta 1 000 personas censadas por el Alto Comisionado de las Naciones Unidas para los Refugiados o por la Cruz Roja y clasificadas como un &nbsp;miembros de un grupo especialmente vulnerable, muchas de las cuales se encontraban retenidas en antiguos campos de concentraci&oacute;n); los que hicieron el viaje de forma independiente; o los evacuados por razones m&eacute;dicas.<\/p>\n<p>La falta de fiabilidad de los datos cuantitativos sobre migraci&oacute;n al Reino Unido imposibilita cualquier c&aacute;lculo certero del n&uacute;mero de personas procedentes de Bosnia-Herzegovina que todav&iacute;a residen en el Reino Unido, aunque los representantes de la comunidad estiman una cifra aproximada de 10 000. Muchos de los que se exiliaron durante el conflicto han regresado desde entonces y est&aacute; claro que es totalmente apropiado que quienes deseen regresar &ldquo;a casa&rdquo; despu&eacute;s de un conflicto violento puedan ejercer su derecho a hacerlo. Sin embargo, ser&iacute;a muy interesante investigar sobre la elecci&oacute;n o voluntad de aquellas personas a las que tanto se les ha quitado ya, sobre todo dada la amplia ret&oacute;rica sobre la migraci&oacute;n y el asilo en el contexto Europeo (y en otros m&aacute;s amplios)<a href=\"#_edn1\" name=\"_ednref1\" title=\"\">[1]<\/a>.<\/p>\n<p><strong>La insistencia acerca del retorno<\/strong><\/p>\n<p>Muchos argumentan que el &ldquo;&eacute;xito&rdquo; de Dayton recae sobre la implementaci&oacute;n del Anexo 7 y en el regreso de los refugiados, y de hecho la comunidad internacional est&aacute; interesada en enfatizar la importancia del retorno de los desplazados internos y de los refugiados. Pero ser&iacute;a interesante que tuvi&eacute;ramos en consideraci&oacute;n las motivaciones potenciales que se hallan detr&aacute;s de la insistencia en la importancia del retorno de los refugiados.<\/p>\n<p>&iquest;Busca esta insistencia, como algunos han se&ntilde;alado, subrayar que la pr&aacute;ctica de la &ldquo;depuraci&oacute;n &eacute;tnica&rdquo; no va a ser recompensada con beneficios territoriales?<a href=\"#_edn2\" name=\"_ednref2\" title=\"\">[2]<\/a> &iquest;Es posible que parte del deseo de un retorno &ldquo;exitoso&rdquo; de los refugiados se deba a un intento de atenuar cualquier tipo de culpa residual que pueda quedar a tenor del fracaso colectivo de la comunidad internacional a la hora de intervenir positivamente en Bosnia durante la primera etapa de la guerra?<\/p>\n<p>Los Gobiernos europeos son cada vez m&aacute;s reticentes a ofrecer refugio permanente a las personas que se exilian en situaciones de conflicto y la pr&aacute;ctica durante la guerra de la d&eacute;cada de los noventa consisti&oacute; en ofrecer &ldquo;protecci&oacute;n provisional&rdquo; a los refugiados de la guerra de Bosnia (dos ejemplos ser&iacute;an Alemania y Reino Unido). La comunidad internacional suele presentar el retorno como algo vital no s&oacute;lo para el &eacute;xito a largo plazo del tratado de paz sino tambi&eacute;n para el bienestar emocional de las personas desplazadas. En ese caso, &iquest;es posible que las leyes sobre inmigraci&oacute;n cada vez menos piadosas de algunos Gobiernos europeos est&eacute;n alineadas con el discurso sobre la importancia del retorno de los refugiados?&nbsp;<\/p>\n<p>Es inevitable que las discusiones sobre la reconciliaci&oacute;n lleven aparejadas, como poco, una gran carga pol&iacute;tica y emocional, en un pa&iacute;s donde tantos de los responsables de haber causado tanto da&ntilde;o no han sido llevados ante la justicia. En ese sentido, la insistencia en que el retorno de los refugiados constituir&iacute;a el pilar fundamental del &eacute;xito del Acuerdo de Dayton<a href=\"#_edn3\" name=\"_ednref3\" title=\"\">[3]<\/a>, aunque est&eacute; evidentemente destinado a garantizar la protecci&oacute;n de los refugiados retornados, podr&iacute;a interpretarse como que tiene un subtexto m&aacute;s sutil e insidioso. En la Bosnia-Herzegovina post conflicto y en sus inmediaciones, donde los gestos de reconciliaci&oacute;n significativos por parte de los perpetradores son pocos y espaciados en el tiempo, el Anexo 7 pone el foco sobre la v&iacute;ctima. Ellos est&aacute;n ya muy familiarizados con el s&iacute;ndrome del superviviente. Al poner tanto &eacute;nfasis en su retorno y en el de otros en su situaci&oacute;n, se corre el peligro de aumentar la carga emocional de aquellos cuya resiliencia ya se ha puesto a prueba no s&oacute;lo por el horror de la guerra en s&iacute; sino tambi&eacute;n por el considerable estr&eacute;s que a veces produce la experiencia de migrar.<\/p>\n<p>Entre los refugiados de Bosnia-Herzegovina a los que entrevist&eacute; en el transcurso de mi estudio,<a href=\"#_edn4\" name=\"_ednref4\" title=\"\">[4]<\/a> el tiempo medio para tomar una decisi&oacute;n sobre su estatus migratorio era de siete a&ntilde;os; los que m&aacute;s tiempo hab&iacute;an esperado lo hab&iacute;an hecho durante trece a&ntilde;os<a href=\"#_edn5\" name=\"_ednref5\" title=\"\">[5]<\/a>. Los entrevistados hablaron acerca del intenso sentimiento de desplazamiento f&iacute;sico y emocional al darse cuenta de que, despu&eacute;s de haber tenido que dejar sus hogares y que &eacute;stos fueran totalmente bombardeados o incendiados o de haberse visto obligados a renunciar a cualquier derecho sobre su propiedad, lo que les ofrec&iacute;an en el pa&iacute;s de &ldquo;refugio&rdquo; era temporalidad e incertidumbre. Estas personas se enfrentaban a a&ntilde;os de estar en el limbo sin derecho al trabajo o sin la documentaci&oacute;n necesaria para facilitarles el retorno provisional sin hacer que peligren sus solicitudes de asilo.&nbsp;<\/p>\n<p>Se podr&iacute;a argumentar que al considerar el retorno de los refugiados como esencial para el futuro de Bosnia-Herzegovina parad&oacute;jicamente se corre el riesgo de pasar por alto los derechos de aquellos refugiados m&aacute;s vulnerables. Despu&eacute;s de todo ser&iacute;a dif&iacute;cil subestimar el efecto acumulativo y corrosivo que tendr&iacute;a sobre la salud mental y emocional de un refugiado que, tras sobrevivir a la guerra y a sus r&eacute;plicas y al sistema de inmigraci&oacute;n del Reino Unido, se ve luego culpable emocionalmente por el argumento de que &ldquo;el retorno de los refugiados es vital para Bosnia&rdquo;.<\/p>\n<p>Aunque la implementaci&oacute;n del Anexo 7 resulta crucial para la protecci&oacute;n de los derechos de aquellos refugiados y desplazados internos que s&iacute; desean regresar, es importante que se reconozcan los derechos de los que han decido establecer su hogar en otro sitio. Aceptar la decisi&oacute;n de estos refugiados de no regresar supondr&iacute;a un avance en el reconocimiento y respeto de la &ldquo;voluntad&rdquo; de los refugiados; algo que, lamentablemente, tan a menudo suele faltar en los estudios sobre migraciones forzadas<a href=\"#_edn6\" name=\"_ednref6\" title=\"\">[6]<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Gayle Munro <a href=\"mailto:gayle.munro@salvationarmy.org.uk\">gayle.munro@salvationarmy.org.uk<\/a><\/p>\n<p>Director de investigaci&oacute;n, el Ej&eacute;rcito de Salvaci&oacute;n. <a href=\"http:\/\/www.salvationarmy.org.uk\/\">www.salvationarmy.org.uk<\/a><\/p>\n<p>El contenido del presente art&iacute;culo no refleja necesariamente la postura del Ej&eacute;rcito de la Salvaci&oacute;n.<\/p>\n<div>\n\t<br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[1]<\/a> V&eacute;ase el n&uacute;mero 51 de <em>Revista Migraciones Forzadas<\/em> (que se publicar&aacute; en diciembre de 2015) sobre &ldquo;Destino: Europa&rdquo;. www.fmreview.org\/destination-europe<\/p>\n<\/p><\/div>\n<div id=\"edn2\">\n<p><a href=\"#_ednref2\" name=\"_edn2\" title=\"\">[2]<\/a> Dahlman C. and Tuathail G. &Oacute;. (2005) &lsquo;The legacy of ethnic cleansing: The international community and the returns process in post-Dayton Bosnia-Herzegovina&rsquo; [El legado de la depuraci&oacute;n &eacute;tnica: la comunidad internacional y el proceso de retorno tras el Acuerdo de Dayton sobre Bosnia-Herzegovina], <em>Political Geography<\/em> (Geograf&iacute;a pol&iacute;tica) 24(5): 569-599. <a href=\"http:\/\/www.sciencedirect.com\/science\/article\/pii\/S0962629805000223\">www.sciencedirect.com\/science\/article\/pii\/S0962629805000223<\/a><\/p>\n<\/p><\/div>\n<div id=\"edn3\">\n<p><a href=\"#_ednref3\" name=\"_edn3\" title=\"\">[3]<\/a> V&eacute;ase por ejemplo &lsquo;Albright urges Bosnian refugee return&rsquo; [Albright urge al retorno de los refugiados bosnios], BBC News, 31 de agosto1998 <a href=\"http:\/\/news.bbc.co.uk\/1\/hi\/world\/europe\/161970.stm\">http:\/\/news.bbc.co.uk\/1\/hi\/world\/europe\/161970.stm<\/a> y &lsquo;Bosnia: Dayton will collapse unless refugees return&rsquo; [Bosnia: Dayton caer&aacute; a menos que los refugiados regresen], noviembre de 1997 <a href=\"http:\/\/refugeenews.tripod.com\/nov97bosnia.htm\">http:\/\/refugeenews.tripod.com\/nov97bosnia.htm<\/a><\/p>\n<\/p><\/div>\n<div id=\"edn4\">\n<p><a href=\"#_ednref4\" name=\"_edn4\" title=\"\">[4]<\/a> El estudio en el que se basa el presente art&iacute;culo fue llevado a cabo en 2008-13 mientras el autor era doctorando en el Departamento de Geograf&iacute;a del University College London. Los participantes en el estudio llevaban viviendo en Reino Unido una media de 15 a&ntilde;os en el momento del proyecto; la inmensa mayor&iacute;a hab&iacute;an llegado entre 1990 y 1995.<\/p>\n<\/p><\/div>\n<div id=\"edn5\">\n<p><a href=\"#_ednref5\" name=\"_edn5\" title=\"\">[5]<\/a> A algunos se les conced&iacute;a la condici&oacute;n de refugiados mientras que a otros se les ampliaba la protecci&oacute;n provisional y finalmente se les conced&iacute;a permiso para quedarse permanentemente.<\/p>\n<\/p><\/div>\n<div id=\"edn6\">\n<p><a href=\"#_ednref6\" name=\"_edn6\" title=\"\">[6]<\/a> Turton D. (2003) &lsquo;Conceptualising Forced Migration&rsquo; [La conceptualizaci&oacute;n de la migraci&oacute;n forzada], RSC Working Paper No 12, Centro de Estudios para los Refugiados, Universidad de Oxford. <a href=\"http:\/\/www.rsc.ox.ac.uk\/publications\/conceptualising-forced-migration\">www.rsc.ox.ac.uk\/publications\/conceptualising-forced-migration<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mayor&iacute;a de las personas de Bosnia-Herzegovina que actualmente residen en el Reino Unido (RU) tomaron la decisi&oacute;n de abandonar su pa&iacute;s de origen y crear un nuevo hogar temporal o permanente all&iacute; como consecuencia directa de la guerra que tuvo lugar entre 1992 y 1995. Todos aquellos que llegaron al Reino Unido en la&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[98],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[38],"fmr_list_years":[564],"class_list":["post-40599","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-98","fmr_content_type-article","fmr_languages-spanish","fmr_list_years-564","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las interpretaciones del Anexo 7: evaluaci\u00f3n del impacto sobre los no retornados en el Reino Unido - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/munro-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las interpretaciones del Anexo 7: evaluaci\u00f3n del impacto sobre los no retornados en el Reino Unido - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"La mayor&iacute;a de las personas de Bosnia-Herzegovina que actualmente residen en el Reino Unido (RU) tomaron la decisi&oacute;n de abandonar su pa&iacute;s de origen y crear un nuevo hogar temporal o permanente all&iacute; como consecuencia directa de la guerra que tuvo lugar entre 1992 y 1995. Todos aquellos que llegaron al Reino Unido en la&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/munro-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T12:32:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/munro-2-2\/\",\"url\":\"https:\/\/www.fmreview.org\/munro-2-2\/\",\"name\":\"Las interpretaciones del Anexo 7: evaluaci\u00f3n del impacto sobre los no retornados en el Reino Unido - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2015-09-02T05:00:00+00:00\",\"dateModified\":\"2025-04-01T12:32:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/munro-2-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/munro-2-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/munro-2-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las interpretaciones del Anexo 7: evaluaci\u00f3n del impacto sobre los no retornados en el Reino Unido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las interpretaciones del Anexo 7: evaluaci\u00f3n del impacto sobre los no retornados en el Reino Unido - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/munro-2-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Las interpretaciones del Anexo 7: evaluaci\u00f3n del impacto sobre los no retornados en el Reino Unido - Forced Migration Review","og_description":"La mayor&iacute;a de las personas de Bosnia-Herzegovina que actualmente residen en el Reino Unido (RU) tomaron la decisi&oacute;n de abandonar su pa&iacute;s de origen y crear un nuevo hogar temporal o permanente all&iacute; como consecuencia directa de la guerra que tuvo lugar entre 1992 y 1995. Todos aquellos que llegaron al Reino Unido en la&hellip;","og_url":"https:\/\/www.fmreview.org\/munro-2-2\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-04-01T12:32:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/munro-2-2\/","url":"https:\/\/www.fmreview.org\/munro-2-2\/","name":"Las interpretaciones del Anexo 7: evaluaci\u00f3n del impacto sobre los no retornados en el Reino Unido - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2015-09-02T05:00:00+00:00","dateModified":"2025-04-01T12:32:16+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/munro-2-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/munro-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/munro-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Las interpretaciones del Anexo 7: evaluaci\u00f3n del impacto sobre los no retornados en el Reino Unido"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/40599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/40599\/revisions"}],"predecessor-version":[{"id":46245,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/40599\/revisions\/46245"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/media?parent=40599"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_themes?post=40599"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_region?post=40599"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_issue?post=40599"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_year?post=40599"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content_type?post=40599"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_languages?post=40599"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_list_years?post=40599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}