{"id":40995,"date":"2018-02-21T00:00:00","date_gmt":"2018-02-21T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/simpson-r-2-2\/"},"modified":"2025-03-17T08:29:31","modified_gmt":"2025-03-17T13:29:31","slug":"simpson-r-2-2","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/fr\/siria2018\/simpson-r-2-2\/","title":{"rendered":"Educaci\u00f3n para la paz y apoyo psicosocial para la cohesi\u00f3n social"},"content":{"rendered":"<p class=\"MsoPlainText\"><span><span><span><span>El conflicto tiene un amplio impacto psicol\u00f3gico en los ni\u00f1os y la gente joven y la ansiedad entre los j\u00f3venes refugiados es generalizada. Los refugiados pueden padecer diversos problemas emocionales, cognitivos, f\u00edsicos, conductuales y sociales, as\u00ed como tambi\u00e9n los impactos de mecanismos de defensa negativos. Con regularidad se se\u00f1ala el aislamiento como forma de salvaguardia psicol\u00f3gica, mientras que las experiencias traum\u00e1ticas de la guerra se exacerban por \u201cfactores estresantes cotidianos como el desplazamiento, la pobreza, la falta de recursos y de servicios para cubrir sus necesidades b\u00e1sicas, el riesgo de sufrir violencia y explotaci\u00f3n, la discriminaci\u00f3n y el aislamiento social\u201d<\/span><\/span><a href=\"#_edn1\" name=\"_ednref1\" title=\"\"><span class=\"MsoEndnoteReference\"><span lang=\"EN-US\"><span><span class=\"MsoEndnoteReference\"><span lang=\"EN-US\"><span><span>[1]<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/a><span><span>. Muchos j\u00f3venes sirios tienen pocas esperanzas de cara al futuro y se sienten en un limbo entre una Siria a la que no pueden regresar y un pa\u00eds de acogida en el que no pueden integrarse. <\/span><\/span><\/span><\/span><\/p>\n<p class=\"MsoPlainText\"><span><span><span><span>En conflictos prolongados, las redes sociales y los sistemas sociales que proporcionan apoyo y regulan el bienestar a menudo se desintegran. La consiguiente falta de cohesi\u00f3n familiar y comunitaria, de una identidad compartida o de relaciones con personas que puedan servir de apoyo puede desembocar en problemas de salud mental y trastornos de estr\u00e9s, especialmente en ni\u00f1os y j\u00f3venes. Aunque est\u00e1 ampliamente reconocido el hecho de que las respuestas humanitarias deber\u00edan incluir servicios de salud mental y de apoyo psicosocial, a menudo se pasa por alto el papel que desempe\u00f1a el trauma en los procesos de cohesi\u00f3n social. Como consecuencia, los programas no abordan de forma consistente las necesidades psicol\u00f3gicas que repercuten en la forma en que las personas se relacionan entre s\u00ed. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span><span>Hasta ahora, el principal enfoque de estos programas ha consistido en abordar las tensiones entre las comunidades sobre el empleo y los servicios o establecer mecanismos de interacci\u00f3n, sin prestar mucha atenci\u00f3n al tratamiento de unos traumas que limitan las oportunidades para la cohesi\u00f3n social en primer lugar. Esto a menudo limita la eficacia del programa. Por ejemplo, los profesionales que trabajan con los refugiados en Tr\u00edpoli (L\u00edbano) han tenido dificultades para implementar programas de dinero por trabajo, formaci\u00f3n profesional y emprendimiento social con j\u00f3venes sirios y libaneses debido al aumento de las tensiones relacionadas con los enfrentamientos espor\u00e1dicos entre las comunidades de Tr\u00edpoli y los recurrentes problemas interpersonales y sociales \u2014como tensiones sociales y laborales, acoso, estr\u00e9s y ansiedad\u2014 que provocan que los participantes abandonen el programa o no consigan mantener un trabajo estable<\/span><\/span><a href=\"#_edn2\" name=\"_ednref2\" title=\"\"><span class=\"MsoEndnoteReference\"><span lang=\"EN-US\"><span><span class=\"MsoEndnoteReference\"><span lang=\"EN-US\"><span><span>[2]<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/a><span><span>. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><b><span><span>El suministro de herramientas <\/span><\/span><\/b><\/span><\/span><\/span><\/p>\n<p><span><span><span><span><span>Los enfoques sensibles al trauma pueden tener repercusiones positivas sobre la cohesi\u00f3n social entre los refugiados. Los proyectos de educaci\u00f3n para la paz liderados por socios locales de International Alert en Siria, el L\u00edbano y Turqu\u00eda inclu\u00edan la formaci\u00f3n de educadores y trabajadores de apoyo que impart\u00edan sesiones peri\u00f3dicas en centros educativos y comunitarios para promover una interacci\u00f3n pac\u00edfica y prestar, a ni\u00f1os y j\u00f3venes, servicios de divulgaci\u00f3n, tutorizaci\u00f3n y derivaci\u00f3n<\/span><\/span><a href=\"#_edn3\" name=\"_ednref3\" title=\"\"><span class=\"MsoEndnoteReference\"><span lang=\"EN-US\"><span><span class=\"MsoEndnoteReference\"><span lang=\"EN-US\"><span><span>[3]<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/a><span><span>. Aunque los proyectos se adaptaron a las necesidades espec\u00edficas de los contextos locales, todos ellos ten\u00edan por objeto abordar las barreras a la cohesi\u00f3n social y restablecer las redes sociales mediante el respeto de la diversidad, la promoci\u00f3n de la autonom\u00eda y la creaci\u00f3n de v\u00edas de acci\u00f3n que beneficiaran a la comunidad en general<\/span><\/span><a href=\"#_edn4\" name=\"_ednref4\" title=\"\"><span class=\"MsoEndnoteReference\"><span lang=\"EN-US\"><span><span class=\"MsoEndnoteReference\"><span lang=\"EN-US\"><span><span>[4]<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/a><span><span>. <\/span><\/span><span><span>Los organismos asociados crearon espacios seguros para permitir que los ni\u00f1os desarrollasen un sentimiento de seguridad f\u00edsica y psicol\u00f3gica y prestaron apoyo a los j\u00f3venes para que pudiesen lidiar con los recuerdos traum\u00e1ticos.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span><span>Los enfoques fueron evaluados antes y despu\u00e9s de la intervenci\u00f3n a trav\u00e9s de encuestas de conocimiento, actitudes y pr\u00e1cticas (CAP), adem\u00e1s de entrevistas cualitativas y grupos de discusi\u00f3n focales. Los datos de la encuesta demuestran consistentemente que, a trav\u00e9s de distintos lugares y enfoques, los ni\u00f1os y j\u00f3venes hab\u00edan incrementado sus conocimientos y aptitudes en lo que respecta a aspectos como la paz, la tolerancia y otras destrezas para la vida. Las mejoras m\u00e1s significativas atribuibles al programa fueron la comprensi\u00f3n de c\u00f3mo se pueden aliviar las tensiones mediante el di\u00e1logo y la escucha, la propia capacidad de expresi\u00f3n y la discusi\u00f3n de los problemas, as\u00ed como la apertura a la diversidad; todas actitudes que favorecen la cohesi\u00f3n social. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span><span>A los j\u00f3venes se les estaba equipando con las herramientas necesarias para manejar y expresar su ira sin utilizar la violencia y los facilitadores observaron una reducci\u00f3n de los casos de acoso y un aumento de la cooperaci\u00f3n y el juego, incluso entre ni\u00f1as y ni\u00f1os. En palabras de uno de los facilitadores: \u201cLes damos herramientas para que se expresen en la comunidad en lugar de usar armas para expresar la ira que sienten por sus p\u00e9rdidas\u201d. Las entrevistas y los grupos de discusi\u00f3n focales con padres y comunidades corroboraron los datos y los participantes afirmaron que el deseo de venganza y el comportamiento agresivo, que muchos j\u00f3venes mostraban antes del inicio del programa, hab\u00edan disminuido. Aunque es importante hacer un seguimiento a largo plazo de estos cambios para evaluar sus repercusiones a la larga, estos resultados iniciales muestran que los programas centrados en la cohesi\u00f3n social entre refugiados a trav\u00e9s del apoyo psicosocial pueden tener un impacto positivo.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><b><span><span>Limitaciones<\/span><\/span><\/b><\/span><\/span><\/span><\/p>\n<p><span><span><span><span><span>Hay cuatro factores principales que influyen en el potencial de estos enfoques basados en el apoyo psicosocial para que su impacto sea duradero o para limitarlo. En primer lugar, la necesidad de una cohesi\u00f3n social a largo plazo o de enfoques basados en la consolidaci\u00f3n de la paz puede verse eclipsada por las necesidades humanitarias y psicosociales de emergencia. En segundo lugar, existen barreras f\u00edsicas muy reales en la interacci\u00f3n entre las comunidades de acogida y de refugiados \u2014por ejemplo, los bloqueos de carreteras o la escolarizaci\u00f3n por separado\u2014 que reducen las oportunidades de cohesi\u00f3n social. En tercer lugar, las repercusiones de los enfoques basados en la psicolog\u00eda ser\u00e1n limitadas cuando no exista un apoyo complementario que permita el acceso a la educaci\u00f3n, el empleo, la sanidad, la cultura y otros servicios. Por \u00faltimo, la falta de personal cualificado y las elevadas tasas de rotaci\u00f3n de personal debidas a la financiaci\u00f3n a corto plazo, as\u00ed como los vac\u00edos entre proyectos, conforman estos problemas.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span><span>La receptividad de la comunidad de acogida tambi\u00e9n influye de manera significativa en la cohesi\u00f3n social. Hacer part\u00edcipe a la poblaci\u00f3n de acogida en actividades grupales mixtas puede constituir todo un reto, especialmente cuando hay poca confianza y altos niveles de miedo. Por ejemplo, los profesionales en el L\u00edbano encuentran constantes dificultades para hacer que las comunidades de acogida participen en actividades conjuntas de apoyo psicosocial con los refugiados debido al estigma y la desconfianza entre comunidades. Para superar este problema, las intervenciones psicosociales deben formar parte de un paquete integral de apoyo hecho a medida que beneficie tanto a refugiados como a comunidades de acogida como, por ejemplo, intervenciones que lleven a los ni\u00f1os y j\u00f3venes de la comunidad de acogida a compartir espacios seguros y los involucren en actividades que desaf\u00eden los estereotipos existentes y fomenten la confianza.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><strong><span><span><span><span><span>Conclusi\u00f3n<\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\n<p><span><span><span><span><span>Los enfoques de la educaci\u00f3n para la paz basados en el apoyo psicosocial pueden ayudar a los individuos a sanar, a recobrar un sentido de la identidad propia y positiva y sentar las bases para construir redes sociales de apoyo entre las comunidades. Todo esto forma parte integral del proceso para crear cohesi\u00f3n social. Si no se aborda el trauma de manera consistente, es probable que la sostenibilidad de los programas de cohesi\u00f3n social sea limitada e, incluso, estos sean contraproducentes. En lugar de considerarlo como un enfoque separado aunque complementario de estos programas, el abordaje de las repercusiones del trauma deber\u00eda ser un elemento b\u00e1sico en todos los esfuerzos de cohesi\u00f3n social cuando se trabaja con comunidades afectadas por conflictos y desplazamientos.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"EN-US\"><span>Ruth Simpson <\/span><\/span><a href=\"mailto:rsimpson@international-alert.org\"><i><span lang=\"EN-US\"><span>rsimpson@international-alert.org<\/span><\/span><\/i><\/a><\/span><\/span><\/span><\/p>\n<p><span><span><span><span><span>Encargada s\u00e9nior (Desarrollo, Impacto y Aprendizaje) de Oriente Medio y Norte de \u00c1frica, International Alert <span class=\"MsoHyperlink\"><span><i>www.international-alert.org<\/i><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<div>&nbsp;<\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p class=\"MsoEndnoteText\"><span><span><a href=\"#_ednref1\" name=\"_edn1\" title=\"\"><span class=\"MsoEndnoteReference\"><span><span><span class=\"MsoEndnoteReference\"><span><span><span>[1]<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/a><span lang=\"EN-US\"><span> ACNUR (2015) <i>Culture, Context and the Mental Health and Psychosocial Wellbeing of Syrians<\/i><\/span><\/span><\/span><\/span><\/p>\n<p class=\"MsoEndnoteText\"><span><span><i><span lang=\"EN-US\"><span>A Review for Mental Health and Psychosocial Support Staff Working with Syrians Affected by Armed Conflict<\/span><\/span><\/i><span lang=\"EN-US\"><span> <span class=\"MsoHyperlink\"><span><a href=\"http:\/\/www.unhcr.org\/55f6b90f9.pdf\">www.unhcr.org\/55f6b90f9.pdf<\/a><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<\/div>\n<div id=\"edn2\">\n<p class=\"MsoEndnoteText\"><span><span><a href=\"#_ednref2\" name=\"_edn2\" title=\"\"><span class=\"MsoEndnoteReference\"><span><span><span class=\"MsoEndnoteReference\"><span><span><span>[2]<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/a><span><span> Entrevista por Skype con un psic\u00f3logo sirio en marzo de 2017.<\/span><\/span><\/span><\/span><\/p>\n<\/div>\n<div id=\"edn3\">\n<p class=\"MsoEndnoteText\"><span><span><a href=\"#_ednref3\" name=\"_edn3\" title=\"\"><span class=\"MsoEndnoteReference\"><span><span><span class=\"MsoEndnoteReference\"><span><span><span>[3]<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/a><span><span> Trabajando con 7000 j\u00f3venes sirios de entre 6-18 a\u00f1os y con j\u00f3venes de m\u00e1s de 18 que viven en Siria o como refugiados en el L\u00edbano y Turqu\u00eda. <\/span><\/span><\/span><\/span><\/p>\n<\/div>\n<div id=\"edn4\">\n<p class=\"MsoEndnoteText\"><span><span><a href=\"#_ednref4\" name=\"_edn4\" title=\"\"><span class=\"MsoEndnoteReference\"><span><span><span class=\"MsoEndnoteReference\"><span><span><span>[4]<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/a><span lang=\"EN-US\"><span> Para ampliar informaci\u00f3n y acceder a la evaluaci\u00f3n completa, v\u00e9ase International Alert (2016) <i>Teaching peace, building resilience: Assessing the impact of peace education for young Syrians<\/i>.<\/span><\/span><\/span><\/span><\/p>\n<p class=\"MsoEndnoteText\"><span><span><span class=\"MsoHyperlink\"><span><span lang=\"EN-US\"><span><a href=\"http:\/\/www.international-alert.org\/publications\/teaching-peace-building-resilience\">www.international-alert.org\/publications\/teaching-peace-building-resilience<\/a> <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"MsoEndnoteText\">&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El conflicto tiene un amplio impacto psicol\u00f3gico en los ni\u00f1os y la gente joven y la ansiedad entre los j\u00f3venes refugiados es generalizada. Los refugiados pueden padecer diversos problemas emocionales, cognitivos, f\u00edsicos, conductuales y sociales, as\u00ed como tambi\u00e9n los impactos de mecanismos de defensa negativos. Con regularidad se se\u00f1ala el aislamiento como forma de salvaguardia&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42696,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[105],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[38],"fmr_list_years":[567],"class_list":["post-40995","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-105","fmr_content_type-article","fmr_languages-spanish","fmr_list_years-567","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Educaci\u00f3n para la paz y apoyo psicosocial para la cohesi\u00f3n social - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Educaci\u00f3n para la paz y apoyo psicosocial para la cohesi\u00f3n social - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"El conflicto tiene un amplio impacto psicol\u00f3gico en los ni\u00f1os y la gente joven y la ansiedad entre los j\u00f3venes refugiados es generalizada. Los refugiados pueden padecer diversos problemas emocionales, cognitivos, f\u00edsicos, conductuales y sociales, as\u00ed como tambi\u00e9n los impactos de mecanismos de defensa negativos. Con regularidad se se\u00f1ala el aislamiento como forma de salvaguardia&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-17T13:29:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/\",\"url\":\"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/\",\"name\":\"Educaci\u00f3n para la paz y apoyo psicosocial para la cohesi\u00f3n social - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2018-02-21T05:00:00+00:00\",\"dateModified\":\"2025-03-17T13:29:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RMF 57 &#8211; Sirios en desplazamiento\",\"item\":\"https:\/\/www.fmreview.org\/siria2018\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Educaci\u00f3n para la paz y apoyo psicosocial para la cohesi\u00f3n social\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Educaci\u00f3n para la paz y apoyo psicosocial para la cohesi\u00f3n social - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Educaci\u00f3n para la paz y apoyo psicosocial para la cohesi\u00f3n social - Forced Migration Review","og_description":"El conflicto tiene un amplio impacto psicol\u00f3gico en los ni\u00f1os y la gente joven y la ansiedad entre los j\u00f3venes refugiados es generalizada. Los refugiados pueden padecer diversos problemas emocionales, cognitivos, f\u00edsicos, conductuales y sociales, as\u00ed como tambi\u00e9n los impactos de mecanismos de defensa negativos. Con regularidad se se\u00f1ala el aislamiento como forma de salvaguardia&hellip;","og_url":"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-03-17T13:29:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/","url":"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/","name":"Educaci\u00f3n para la paz y apoyo psicosocial para la cohesi\u00f3n social - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2018-02-21T05:00:00+00:00","dateModified":"2025-03-17T13:29:31+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/siria2018\/simpson-r-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/fr\/"},{"@type":"ListItem","position":2,"name":"RMF 57 &#8211; Sirios en desplazamiento","item":"https:\/\/www.fmreview.org\/siria2018\/"},{"@type":"ListItem","position":3,"name":"Educaci\u00f3n para la paz y apoyo psicosocial para la cohesi\u00f3n social"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/40995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/40995\/revisions"}],"predecessor-version":[{"id":44871,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/40995\/revisions\/44871"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/42696"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/media?parent=40995"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_themes?post=40995"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_region?post=40995"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_issue?post=40995"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_year?post=40995"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content_type?post=40995"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_languages?post=40995"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_list_years?post=40995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}