{"id":41856,"date":"2017-06-15T00:00:00","date_gmt":"2017-06-15T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/nicholson-2-4\/"},"modified":"2025-04-01T06:46:38","modified_gmt":"2025-04-01T11:46:38","slug":"nicholson-2-4","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/fr\/abris\/nicholson-2-4\/","title":{"rendered":"Le cas des Albanais pauvres qui ont accueilli des d\u00e9plac\u00e9s kosovars"},"content":{"rendered":"<p>Un beau jour en 2001, je suis pass&eacute;e voir une ancienne voisine en Albanie dans sa petite maison de deux pi&egrave;ces. L&rsquo;album de famille contenait des photos de la famille de Kosovars<a href=\"#_edn1\" name=\"_ednref1\" title=\"\">[1]<\/a> qu&rsquo;ils avaient h&eacute;berg&eacute;e suite &agrave; leur expulsion du Kosovo fin mars 1999. Chacune des deux familles de quatre s&rsquo;&eacute;tait entass&eacute;e dans une pi&egrave;ce minuscule et ils partageaient le seul et unique &eacute;vier avec un robinet dans une toute petite arri&egrave;re-cuisine ainsi que des toilettes ext&eacute;rieures primitives. Il &eacute;tait difficile d&rsquo;imaginer comment ils avaient r&eacute;ussi &agrave; vivre de cette mani&egrave;re pendant deux mois.<\/p>\n<p>Les Kosovars qui sont arriv&eacute;s en 1999 et qui avaient des parents dont ils avaient &eacute;t&eacute; s&eacute;par&eacute;s pendant la p&eacute;riode communiste en Albanie sont revenus s&rsquo;installer chez eux, mais la plupart d&rsquo;entre eux ont &eacute;t&eacute; h&eacute;berg&eacute;s par des gens qu&rsquo;ils ne connaissaient pas, comme ma voisine. L&rsquo;hospitalit&eacute;, surtout &agrave; l&rsquo;&eacute;gard d&rsquo;&eacute;trangers, est le principe le plus important du droit coutumier oral albanais, et la vertu qui est y est attach&eacute;e est l&rsquo;une des plus &eacute;lev&eacute;es. Elle est l&rsquo;expression de ce qui est consid&eacute;r&eacute; comme d&eacute;cent et convenable, la mesure m&ecirc;me de ce qui constitue la r&eacute;putation d&rsquo;une famille, et non moins important, la mesure &agrave; l&rsquo;aune de laquelle une famille d&eacute;finit sa propre valeur.&nbsp;<\/p>\n<p>&Agrave; leur arriv&eacute;e et pendant un jour ou deux imm&eacute;diatement apr&egrave;s, les h&ocirc;tes s&rsquo;occupent de leurs invit&eacute;s, m&ecirc;me si les femmes parmi les invit&eacute;s participent &agrave; diff&eacute;rentes t&acirc;ches. Par la suite, un accord est pass&eacute; sur la mani&egrave;re dont les invit&eacute;s vont apporter leur contribution au foyer. Par le pass&eacute;, lorsque des &eacute;trangers de passage &eacute;taient accueillis dans une maison priv&eacute;e parce qu&rsquo;il n&rsquo;y avait pas d&rsquo;auberge dans le voisinage, ceux-ci payaient leur hospitalit&eacute; comme s&rsquo;ils &eacute;taient accueillis dans une auberge. De m&ecirc;me, on attend des &eacute;trangers qu&rsquo;ils paient leur h&eacute;bergement, car il est consid&eacute;r&eacute; comme juste qu&rsquo;ils contribuent aux frais s&rsquo;ils en ont les moyens. Les Kosovars, dans leur majorit&eacute;, &eacute;taient plus ais&eacute;s que leurs h&ocirc;tes albanais, particuli&egrave;rement ceux qui recevaient des virements de parents &eacute;tablis ailleurs. La famille h&eacute;berg&eacute;e par ma voisine avait toutefois perdu sa source de revenus lors de son expulsion du Kosovo et mes voisins les ont donc nourris.<\/p>\n<p>M&ecirc;me en temps normal, la famille de ma voisine vit au jour le jour. Le mari a un emploi mal r&eacute;mun&eacute;r&eacute; et leur terrain minuscule ne produit que suffisamment de foin pour leur vache, ainsi que des haricots et quelques l&eacute;gumes pour leurs propres besoins, mais rien de plus. Et pour comble, les Kosovars sont arriv&eacute;s &agrave; la fin de l&rsquo;hiver, lorsque les r&eacute;serves de la r&eacute;colte pr&eacute;c&eacute;dente &eacute;taient d&eacute;j&agrave; presque &eacute;puis&eacute;es.<\/p>\n<p>Lorsqu&rsquo;on a demand&eacute; aux habitants du village d&rsquo;accueillir des r&eacute;fugi&eacute;s, ma voisine m&rsquo;a dit qu&rsquo;on leur avait laiss&eacute; entendre qu&rsquo;ils recevraient une assistance financi&egrave;re. Le HCR, l&rsquo;agence des Nations Unies pour les r&eacute;fugi&eacute;s, s&rsquo;&eacute;tait engag&eacute; &agrave; verser la somme modeste de 10 $US par personne et par semaine aux familles qui h&eacute;bergeraient des r&eacute;fugi&eacute;s, de mani&egrave;re &agrave; contribuer aux frais expos&eacute;s. C&rsquo;est un facteur dont les gens du village avaient tenu compte lorsqu&rsquo;ils avaient &eacute;valu&eacute; s&rsquo;ils avaient les moyens d&rsquo;accueillir des d&eacute;plac&eacute;s. Mais l&rsquo;argent n&rsquo;a pas suivi. Chaque semaine, la situation financi&egrave;re de ma voisine devenait de plus en plus pr&eacute;caire. T&ocirc;t ou tard allait arriver le moment o&ugrave;, non seulement ils ne pourraient plus nourrir leurs invit&eacute;s, mais ils n&rsquo;auraient plus rien &agrave; manger eux-m&ecirc;mes. Une situation qui devenait apparente &eacute;galement pour les r&eacute;fugi&eacute;s, par le simple fait qu&rsquo;il y avait de moins en moins de nourriture dans les assiettes. Ils ont d&ucirc; se sentir embarrass&eacute;s lorsqu&rsquo;ils se sont rendu compte des difficult&eacute;s qu&rsquo;ils causaient. Et finalement, un beau jour, apr&egrave;s deux mois, et sans pr&eacute;avis ils ont inform&eacute; ma voisine qu&rsquo;ils s&rsquo;en allaient. Ils avaient pris des dispositions pour d&eacute;m&eacute;nager dans la maison d&rsquo;une autre famille. Et c&rsquo;est ainsi qu&rsquo;ils sont partis, m&rsquo;a-t-elle dit, sans m&ecirc;me dire &laquo;&nbsp;merci&nbsp;&raquo;. C&rsquo;est ce qui a le plus bless&eacute; ma voisine. Lorsque je lui ai demand&eacute; si elle avait obtenu ne serait-ce qu&rsquo;une partie de l&rsquo;argent qu&rsquo;elle &eacute;tait suppos&eacute;e recevoir, elle a chuchot&eacute; que &laquo;&nbsp;non&nbsp;&raquo; &#8211; et cela aussi a d&ucirc; lui faire mal.<\/p>\n<p>Les fonds distribu&eacute;s dans le cadre de ce programme du HCR ne sont arriv&eacute;s entre les mains de ceux &agrave; qui ils &eacute;taient destin&eacute;s nulle part avant le mois de juin, c&rsquo;est-&agrave;-dire &agrave; un moment o&ugrave; la plupart des r&eacute;fugi&eacute;s &eacute;taient d&eacute;j&agrave; repartis au Kosovo. De plus, certains villages ont &eacute;t&eacute; compl&egrave;tement oubli&eacute;s. La souffrance caus&eacute;e ainsi s&rsquo;est av&eacute;r&eacute;e bien plus importante que ce qu&rsquo;a pu r&eacute;aliser la communaut&eacute; humanitaire internationale. Ce qui a pu sembler sans importance aux yeux du HCR a constitu&eacute; une perte &eacute;norme pour les individus concern&eacute;s. Plus d&rsquo;une d&eacute;cennie plus tard, un journal albanais a relat&eacute; qu&rsquo;un retrait&eacute; dans un village en p&eacute;riph&eacute;rie imm&eacute;diate de la ville de Kuk&euml;s o&ugrave; de l&rsquo;argent avait &eacute;t&eacute; distribu&eacute; alors que d&rsquo;autres villages environnants n&rsquo;avaient rien re&ccedil;u avait pris l&rsquo;initiative d&rsquo;attaquer les Nations Unies en justice. Une cause, certes, sans espoir, mais les habitants tenaient ainsi &agrave; ne pas laisser passer sous silence un probl&egrave;me aussi s&eacute;rieux.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Beryl Nicholson <em><a href=\"mailto:beryl6b@yahoo.co.uk\">beryl6b@yahoo.co.uk<\/a><\/em><br \/>\n\tSociologue et historienne sociale <em><a href=\"http:\/\/www.beryl-nicholson.co.uk\">www.beryl-nicholson.co.uk<\/a> <\/em><\/p>\n<div>\n\t<br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[1]<\/a> L&rsquo;orthographe albanaise &laquo;&nbsp;Kosovo\/Kosovar&nbsp;&raquo; utilis&eacute;e ici est celle utilis&eacute;e par toutes les personnes mentionn&eacute;es et il s&rsquo;agit maintenant de l&rsquo;orthographe albanaise officielle pour d&eacute;signer l&rsquo;&Eacute;tat du Kosovo et sa population.<\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un beau jour en 2001, je suis pass&eacute;e voir une ancienne voisine en Albanie dans sa petite maison de deux pi&egrave;ces. L&rsquo;album de famille contenait des photos de la famille de Kosovars[1] qu&rsquo;ils avaient h&eacute;berg&eacute;e suite &agrave; leur expulsion du Kosovo fin mars 1999. Chacune des deux familles de quatre s&rsquo;&eacute;tait entass&eacute;e dans une pi&egrave;ce&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42681,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[103],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[566],"class_list":["post-41856","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-103","fmr_content_type-article","fmr_languages-french","fmr_list_years-566","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le cas des Albanais pauvres qui ont accueilli des d\u00e9plac\u00e9s kosovars - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le cas des Albanais pauvres qui ont accueilli des d\u00e9plac\u00e9s kosovars - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"Un beau jour en 2001, je suis pass&eacute;e voir une ancienne voisine en Albanie dans sa petite maison de deux pi&egrave;ces. L&rsquo;album de famille contenait des photos de la famille de Kosovars[1] qu&rsquo;ils avaient h&eacute;berg&eacute;e suite &agrave; leur expulsion du Kosovo fin mars 1999. Chacune des deux familles de quatre s&rsquo;&eacute;tait entass&eacute;e dans une pi&egrave;ce&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T11:46:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/\",\"url\":\"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/\",\"name\":\"Le cas des Albanais pauvres qui ont accueilli des d\u00e9plac\u00e9s kosovars - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2017-06-15T05:00:00+00:00\",\"dateModified\":\"2025-04-01T11:46:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FMR 55 &#8211; Abris en situations de d\u00e9placement\",\"item\":\"https:\/\/www.fmreview.org\/abris\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le cas des Albanais pauvres qui ont accueilli des d\u00e9plac\u00e9s kosovars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le cas des Albanais pauvres qui ont accueilli des d\u00e9plac\u00e9s kosovars - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/","og_locale":"fr_FR","og_type":"article","og_title":"Le cas des Albanais pauvres qui ont accueilli des d\u00e9plac\u00e9s kosovars - Forced Migration Review","og_description":"Un beau jour en 2001, je suis pass&eacute;e voir une ancienne voisine en Albanie dans sa petite maison de deux pi&egrave;ces. L&rsquo;album de famille contenait des photos de la famille de Kosovars[1] qu&rsquo;ils avaient h&eacute;berg&eacute;e suite &agrave; leur expulsion du Kosovo fin mars 1999. Chacune des deux familles de quatre s&rsquo;&eacute;tait entass&eacute;e dans une pi&egrave;ce&hellip;","og_url":"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-04-01T11:46:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/","url":"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/","name":"Le cas des Albanais pauvres qui ont accueilli des d\u00e9plac\u00e9s kosovars - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2017-06-15T05:00:00+00:00","dateModified":"2025-04-01T11:46:38+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/abris\/nicholson-2-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/fr\/"},{"@type":"ListItem","position":2,"name":"FMR 55 &#8211; Abris en situations de d\u00e9placement","item":"https:\/\/www.fmreview.org\/abris\/"},{"@type":"ListItem","position":3,"name":"Le cas des Albanais pauvres qui ont accueilli des d\u00e9plac\u00e9s kosovars"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/41856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/41856\/revisions"}],"predecessor-version":[{"id":45473,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/41856\/revisions\/45473"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/42681"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/media?parent=41856"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_themes?post=41856"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_region?post=41856"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_issue?post=41856"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_year?post=41856"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content_type?post=41856"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_languages?post=41856"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_list_years?post=41856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}