{"id":41859,"date":"2017-06-15T00:00:00","date_gmt":"2017-06-15T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/scottsmith-2-3\/"},"modified":"2025-04-01T06:46:39","modified_gmt":"2025-04-01T11:46:39","slug":"scottsmith-2-3","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/fr\/abris\/scottsmith-2-3\/","title":{"rendered":"Le clivage entre humanitaires et architectes"},"content":{"rendered":"<p>&Agrave; travers l&rsquo;image obsol&egrave;te et us&eacute;e qu&rsquo;elle tend &agrave; perp&eacute;tuer de la migration forc&eacute;e avec ses tentes et ses camps, la couverture m&eacute;diatique ignore bien souvent le fait que les personnes d&eacute;plac&eacute;es finissent par vivre dans une gamme bien plus vari&eacute;e d&rsquo;abris. De nombreux migrants forc&eacute;s vivent dans des appartements lou&eacute;s tout &agrave; fait ordinaires ou habitent avec des amis ou des parents. D&rsquo;autres se trouvent un toit en s&rsquo;adressant &agrave; leurs r&eacute;seaux personnels ou cherchent refuge dans une &eacute;glise ou une mosqu&eacute;e. Certains s&rsquo;installent dans des sites informels comme &laquo;&nbsp;la Jungle&nbsp;&raquo; de Calais et se construisent eux-m&ecirc;mes leur abri &agrave; l&rsquo;aide de bois et de b&acirc;ches. D&rsquo;autres encore vivent dans un environnement naturel, dans des grottes, dorment sous des arbres ou se cachent dans les haies. Dans les grandes m&eacute;tropoles, de nombreux migrants trouvent &agrave; se r&eacute;fugier dans l&rsquo;environnement urbain&nbsp;: ils vivent sous des ponts et des passages souterrains &agrave; Paris, ou dans des tentes dans une gare centrale comme celle de Keleti &agrave; Budapest. Il y en a qui sont log&eacute;s dans des institutions gouvernementales, comme des centres de r&eacute;tention, des bunkers souterrains en Suisse ou des a&eacute;roports comme celui de Tempelhof &agrave; Berlin. Certains r&eacute;fugi&eacute;s squattent dans des b&acirc;timents d&eacute;saffect&eacute;s, c&rsquo;est le cas par exemple dans le quartier d&rsquo;Exarcheia &agrave; Ath&egrave;nes.&nbsp;<\/p>\n<p>La le&ccedil;on d&rsquo;une telle diversit&eacute; est claire&nbsp;: les migrants forc&eacute;s sont capables de trouver &agrave; se loger sans l&rsquo;assistance professionnelle des travailleurs humanitaires ni l&rsquo;expertise des architectes. Effectivement l&rsquo;importance de l&rsquo;improvisation et de l&rsquo;initiative personnelles est l&rsquo;une des caract&eacute;ristiques frappantes de la &laquo;&nbsp;crise&nbsp;&raquo; r&eacute;cente en Europe. Les humanitaires comme les architectes ont &eacute;t&eacute; beaucoup moins pertinents face au d&eacute;placement qu&rsquo;ils ne sont pr&ecirc;ts &agrave; l&rsquo;admettre. D&rsquo;un c&ocirc;t&eacute;, les grandes agences d&rsquo;aide ont &eacute;t&eacute; lentes dans leur intervention et ont fini par &ecirc;tre d&eacute;pass&eacute;es par des humanitaires amateurs et des groupes de solidarit&eacute;. De l&rsquo;autre, les migrants forc&eacute;s ont rarement v&eacute;cu dans des espaces con&ccedil;us par des architectes, malgr&eacute; l&rsquo;attention accord&eacute;e &agrave; l&rsquo;abri pr&eacute;fabriqu&eacute; &laquo;&nbsp;novateur&nbsp;&raquo; dans les milieux du design et le circuit des conf&eacute;rences sur l&rsquo;architecture. Ces deux professions qui, en apparence du moins, sont celles qui ont potentiellement le plus &agrave; apporter pour r&eacute;soudre le probl&egrave;me de l&rsquo;abri, ont une tendance au malentendu r&eacute;ciproque et au d&eacute;saccord, ce qui ne fait qu&rsquo;exacerber leur insignifiance. Cette tension persistante constitue un r&eacute;el obstacle &agrave; la fois au travail collaboratif et &agrave; toute tentative de r&eacute;flexion novatrice sur cet important sujet contemporain. La premi&egrave;re &eacute;tape consiste &agrave; comprendre les st&eacute;r&eacute;otypes de ce clivage entre humanitaires et architectes.<\/p>\n<p><strong>La vision pragmatique de l&rsquo;humanitaire<\/strong><\/p>\n<p>Les humanitaires ont tendance &agrave; voir les architectes comme des r&ecirc;veurs utopistes, compl&egrave;tement d&eacute;connect&eacute;s des r&eacute;alit&eacute;s du terrain et des besoins des b&eacute;n&eacute;ficiaires. Ils lisent des rapports m&eacute;diatiques enthousiastes sur les derniers designs d&rsquo;abris d&rsquo;urgence avec un soupir de d&eacute;sespoir face &agrave; cette certitude qu&rsquo;une solution universelle peut &ecirc;tre trouv&eacute;e. Les humanitaires ont peut-&ecirc;tre aussi &eacute;t&eacute; bombard&eacute;s de suggestions bien intentionn&eacute;es, mais en fin de compte impraticables, dans leurs bo&icirc;tes d&rsquo;e-mails professionnels, ou ont entendu parler de l&rsquo;exposition de la Biennale d&rsquo;architecture de Venise de 2016, avec son m&eacute;lange de jargon imp&eacute;n&eacute;trable et d&rsquo;objectifs par trop ambitieux. En cons&eacute;quence, de nombreux professionnels de l&rsquo;aide en ont conclu que les architectes se m&eacute;prennent enti&egrave;rement sur la nature du probl&egrave;me et qu&rsquo;ils manquent du pragmatisme n&eacute;cessaire pour le r&eacute;soudre. Faire appel &agrave; un architecte peut sembler une bonne id&eacute;e, pensent-ils, mais uniquement si vous avez des masses d&rsquo;argent et si vous souhaitez construire quelque chose de joli&nbsp;; au final, toute r&eacute;flexion architecturale reste cependant inutile en situation d&rsquo;urgence, lorsque le besoin de fournir un simple abri avec des ressources et des d&eacute;lais limit&eacute;s est la pr&eacute;occupation majeure.&nbsp;&nbsp;<\/p>\n<p>Certains humanitaires, particuli&egrave;rement dans le secteur de l&rsquo;abri, ont une formation en architecture ou certaines familiarit&eacute;s avec la profession. Ils peuvent comprendre qu&rsquo;une intervention r&eacute;fl&eacute;chie et correctement inform&eacute;e en termes d&rsquo;architecture est possible et que des conversations productives peuvent avoir lieu. Ils ont toutefois tendance &agrave; avancer le manque de temps. Ils craignent qu&rsquo;apr&egrave;s les diff&eacute;rents processus it&eacute;ratifs de conception et les interminables r&eacute;unions avec les parties prenantes, et apr&egrave;s avoir trouv&eacute; les mat&eacute;riaux et r&eacute;pondu aux appels d&rsquo;offres, les architectes soient encore en train de peser le pour et le contre alors que le sol se d&eacute;robe d&eacute;j&agrave; sous leurs pieds.<\/p>\n<p><strong>La vision professionnelle de l&rsquo;architecte<\/strong><\/p>\n<p>Pour leur part, les architectes professionnels se demandent souvent pourquoi les agences ne s&rsquo;adressent jamais &agrave; eux. Eux aussi lisent la presse et se lamentent des conceptions restrictives, sans imagination et totalement lugubres qui sont trop souvent la marque des camps de r&eacute;fugi&eacute;s. En tant que professionnels form&eacute;s pendant des ann&eacute;es &agrave; r&eacute;fl&eacute;chir &agrave; la mani&egrave;re de construire des abris dans des situations complexes, ils se demandent pourquoi leur expertise de sp&eacute;cialistes n&rsquo;est pas recherch&eacute;e. Apr&egrave;s avoir observ&eacute; l&rsquo;agencement quadrill&eacute; des camps et l&rsquo;uniformit&eacute; implacable des habitations, ils constatent &agrave; quel point le monde de l&rsquo;aide humanitaire reste d&eacute;pourvu de vision conceptuelle. Il est probable qu&rsquo;ils en concluent que le secteur se revendique humanitaire mais semble rarement humain. Ils remarquent &eacute;galement que les humanitaires se pr&eacute;occupent de feuilles de calcul, d&rsquo;indicateurs et de normes minimales, et qu&rsquo;ils paraissent plus pr&eacute;occup&eacute;s par les cases &agrave; cocher et le d&eacute;compte des co&ucirc;ts que par une r&eacute;flexion cr&eacute;ative sur la mani&egrave;re de vivre des gens.<\/p>\n<p>Certains architectes, s&rsquo;ils sont plus familiaris&eacute;s avec le monde de l&rsquo;aide humanitaire, comprendront les contraintes financi&egrave;res et les d&eacute;lais drastiques qui p&egrave;sent sur les agences d&rsquo;aide. Il est probable &eacute;galement qu&rsquo;ils se rendent compte qu&rsquo;en faire davantage est impossible. Mais ils peuvent toutefois regretter que le logement devienne une question relevant de l&rsquo;ing&eacute;nierie, et peuvent en conclure que les humanitaires sont trop pr&eacute;occup&eacute;s d&rsquo;efficacit&eacute; pour trouver les solutions d&rsquo;ensemble n&eacute;cessaires. Les architectes comprennent que toute tentative pour trouver un abri devrait tenir compte de tout, de la formation de la communaut&eacute; &agrave; l&rsquo;utilisation des mat&eacute;riaux les plus r&eacute;cents, des consid&eacute;rations environnementales &agrave; une attention aux formes de construction, de la cr&eacute;ation d&rsquo;un b&acirc;timent esth&eacute;tiquement beau aux aspects pratiques qui le rendent fonctionnel pour la vie quotidienne. Les humanitaires se livrent rarement &agrave; une r&eacute;flexion d&rsquo;une telle d&rsquo;ampleur.<\/p>\n<p><strong>Combler le foss&eacute;<\/strong><\/p>\n<p>Au vu de la persistance de ce clivage qui se fonde bien davantage sur l&rsquo;incompr&eacute;hension que sur un v&eacute;ritable antagonisme, nous nous devons de promouvoir une m&eacute;diation entre ces univers culturels. L&rsquo;humanitarisme est un mode de pens&eacute;e qui se fonde sur un calcul pr&eacute;cautionneux en termes de co&ucirc;ts, de temps et de vies sauv&eacute;es. L&rsquo;architecture par contre est un mode de pens&eacute;es centr&eacute; sur un &eacute;quilibre entre esth&eacute;tique et fonctionnalit&eacute;, entre solidit&eacute; et ad&eacute;quation aux besoins. Les deux parties peuvent contribuer aux besoins d&rsquo;h&eacute;bergement des personnes d&eacute;plac&eacute;es dans toute une vari&eacute;t&eacute; de circonstances, mais de mani&egrave;res diff&eacute;rentes. La t&acirc;che consiste &agrave; les r&eacute;unir. L&rsquo;un des objectifs du projet de recherche &laquo;&nbsp;Architectures du d&eacute;placement&nbsp;&raquo; du Centre d&rsquo;&eacute;tudes sur les r&eacute;fugi&eacute;s est justement d&rsquo;&eacute;tendre la compr&eacute;hension publique de l&rsquo;abri pour les r&eacute;fugi&eacute;s et de guider l&rsquo;&eacute;laboration&nbsp; de politiques r&eacute;ussies en mati&egrave;re d&rsquo;abri et de d&eacute;placement<a href=\"#_edn1\" name=\"_ednref1\" title=\"\">[1]<\/a>. Nous &eacute;tudions dans le d&eacute;tail des interventions d&rsquo;architectes et d&rsquo;humanitaires pour en explorer les avantages et les limitations. Nous commen&ccedil;ons &agrave; organiser et faciliter un dialogue en r&eacute;unissant les principaux acteurs pour qu&rsquo;ils s&rsquo;expriment sur leurs contraintes respectives. Nous sommes convaincus qu&rsquo;en apprenant le mode de r&eacute;flexion des uns et des autres, les architectes et les humanitaires peuvent renforcer leur pertinence &agrave; l&rsquo;&eacute;gard des personnes d&eacute;plac&eacute;es qui cherchent des abris. Prenez-contact et rejoignez-nous dans ce d&eacute;bat. &nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Tom Scott-Smith <a href=\"mailto:tom.scott-smith@qeh.ox.ac.uk\"><em>tom.scott-smith@qeh.ox.ac.uk<\/em><\/a><br \/>\n\tProfesseur associ&eacute;, Centre d&rsquo;&eacute;tudes sur les r&eacute;fugi&eacute;s, Universit&eacute; d&rsquo;Oxford <a href=\"http:\/\/www.rsc.ox.ac.uk\"><em>www.rsc.ox.ac.uk<\/em><\/a><\/p>\n<div>\n\t<br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[1]<\/a> Lanc&eacute; fin 2016 <a href=\"http:\/\/www.rsc.ox.ac.uk\/research\/architectures-of-displacement\">www.rsc.ox.ac.uk\/research\/architectures-of-displacement<\/a><\/p>\n<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&Agrave; travers l&rsquo;image obsol&egrave;te et us&eacute;e qu&rsquo;elle tend &agrave; perp&eacute;tuer de la migration forc&eacute;e avec ses tentes et ses camps, la couverture m&eacute;diatique ignore bien souvent le fait que les personnes d&eacute;plac&eacute;es finissent par vivre dans une gamme bien plus vari&eacute;e d&rsquo;abris. De nombreux migrants forc&eacute;s vivent dans des appartements lou&eacute;s tout &agrave; fait ordinaires&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":42681,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[103],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[566],"class_list":["post-41859","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-103","fmr_content_type-article","fmr_languages-french","fmr_list_years-566","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le clivage entre humanitaires et architectes - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le clivage entre humanitaires et architectes - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"&Agrave; travers l&rsquo;image obsol&egrave;te et us&eacute;e qu&rsquo;elle tend &agrave; perp&eacute;tuer de la migration forc&eacute;e avec ses tentes et ses camps, la couverture m&eacute;diatique ignore bien souvent le fait que les personnes d&eacute;plac&eacute;es finissent par vivre dans une gamme bien plus vari&eacute;e d&rsquo;abris. De nombreux migrants forc&eacute;s vivent dans des appartements lou&eacute;s tout &agrave; fait ordinaires&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T11:46:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/\",\"url\":\"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/\",\"name\":\"Le clivage entre humanitaires et architectes - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2017-06-15T05:00:00+00:00\",\"dateModified\":\"2025-04-01T11:46:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FMR 55 &#8211; Abris en situations de d\u00e9placement\",\"item\":\"https:\/\/www.fmreview.org\/abris\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le clivage entre humanitaires et architectes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le clivage entre humanitaires et architectes - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/","og_locale":"fr_FR","og_type":"article","og_title":"Le clivage entre humanitaires et architectes - Forced Migration Review","og_description":"&Agrave; travers l&rsquo;image obsol&egrave;te et us&eacute;e qu&rsquo;elle tend &agrave; perp&eacute;tuer de la migration forc&eacute;e avec ses tentes et ses camps, la couverture m&eacute;diatique ignore bien souvent le fait que les personnes d&eacute;plac&eacute;es finissent par vivre dans une gamme bien plus vari&eacute;e d&rsquo;abris. De nombreux migrants forc&eacute;s vivent dans des appartements lou&eacute;s tout &agrave; fait ordinaires&hellip;","og_url":"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-04-01T11:46:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/","url":"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/","name":"Le clivage entre humanitaires et architectes - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2017-06-15T05:00:00+00:00","dateModified":"2025-04-01T11:46:39+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/abris\/scottsmith-2-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/fr\/"},{"@type":"ListItem","position":2,"name":"FMR 55 &#8211; Abris en situations de d\u00e9placement","item":"https:\/\/www.fmreview.org\/abris\/"},{"@type":"ListItem","position":3,"name":"Le clivage entre humanitaires et architectes"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/41859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/41859\/revisions"}],"predecessor-version":[{"id":45476,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/41859\/revisions\/45476"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/42681"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/media?parent=41859"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_themes?post=41859"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_region?post=41859"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_issue?post=41859"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_year?post=41859"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content_type?post=41859"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_languages?post=41859"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_list_years?post=41859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}