{"id":42164,"date":"2019-10-09T00:00:00","date_gmt":"2019-10-09T05:00:00","guid":{"rendered":"https:\/\/www.fmreview.org\/osofisan-keen-2-3\/"},"modified":"2025-03-12T17:23:48","modified_gmt":"2025-03-12T22:23:48","slug":"osofisan-keen","status":"publish","type":"fmr_content","link":"https:\/\/www.fmreview.org\/fr\/osofisan-keen\/","title":{"rendered":"Programme communautaire de pr\u00e9vention des conflits et de renforcement de la paix en RDC et en Somalie"},"content":{"rendered":"<p><span><span><span lang=\"FR\"><span>Au cours des ann\u00e9es, du fait de la complexit\u00e9 des facteurs interconnect\u00e9s qui sont en jeu, l\u2019industrie de l\u2019aide s\u2019est heurt\u00e9e \u00e0 des difficult\u00e9s pour trouver des solutions durables au d\u00e9placement. On assiste \u00e0 l\u2019\u00e9mergence d\u2019un consensus selon lequel une meilleure coordination entre les acteurs humanitaires, du d\u00e9veloppement et de la recherche de la paix (connue sous le nom de \u00ab&nbsp;triple nexus&nbsp;\u00bb) pourrait offrir un cadre de travail pour combattre les probl\u00e8mes associ\u00e9s aux d\u00e9placements prolong\u00e9s et donc trouver des solutions durables. C\u2019est dans ce contexte que le <em>Programme pr\u00e9vention des conflits et recherche de la paix<\/em> financ\u00e9 par Sida<a href=\"#_edn1\" name=\"_ednref1\"><span><span><span lang=\"FR\"><span>[1]<\/span><\/span><\/span><\/span><\/a> a \u00e9t\u00e9 con\u00e7u et mis en \u0153uvre. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>Ce programme cherche \u00e0 r\u00e9pondre \u00e0 certaines des&nbsp;causes profondes du d\u00e9placement en R\u00e9publique d\u00e9mocratique du Congo (RDC) et en Somalie. La conception de ce programme s\u2019est appuy\u00e9e sur trois notions cl\u00e9s&nbsp;: <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>Premi\u00e8rement, le programme cherche principalement \u00e0 comprendre et \u00e0 r\u00e9soudre les moteurs structurels et imm\u00e9diats du conflit. Les moteurs structurels contribuent au conflit mais pris isol\u00e9ment n\u2019entrainent pas de violence. En Somalie et en RDC, ils sont associ\u00e9s \u00e0 trois crises&nbsp;: 1)&nbsp;une crise d\u2019identit\u00e9 (par exemple, la nature de la composition ethnique\/tribale et la nature de la comp\u00e9tition entre les \u00e9lites&nbsp;; 2)&nbsp;une crise de repr\u00e9sentation (par exemple, la nature du syst\u00e8me politique et de la culture politique)&nbsp;; 3)&nbsp;une crise de p\u00e9n\u00e9tration (par exemple, la capacit\u00e9 de l\u2019\u00c9tat de s\u2019acquitter de ses fonctions essentielles). Les moteurs imm\u00e9diats sont ceux qui transforment les causes structurelles en conflits potentiellement violents. En Somalie et en RDC, ces derniers incluent&nbsp;: in\u00e9galit\u00e9 d\u2019acc\u00e8s \u00e0 l\u2019information, aux services et autres biens publics&nbsp;; participation in\u00e9gale \u00e0 la prise de d\u00e9cision&nbsp;; et utilisation des identit\u00e9s ethniques et claniques \u00e0 des fins politiques restreintes.&nbsp; <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>Deuxi\u00e8mement, le programme se focalise explicitement sur une paix positive par contraste avec une paix n\u00e9gative. On entend par paix n\u00e9gative, la cessation de la violence physique directe. La paix positive concerne l\u2019\u00e9limination de la violence structurelle, c\u2019est-\u00e0-dire l\u2019\u00e9limination de facteurs comme des griefs profond\u00e9ment ancr\u00e9s, des violations des droits humains, des violences sexistes, des injustices sociales ou l\u2019exclusion et la faiblesse des institutions publiques et de gestion du conflit. Les activit\u00e9s destin\u00e9es \u00e0 construire une paix positive ont pour objectif de supprimer ou de r\u00e9duire progressivement les causes structurelles et imm\u00e9diates du conflit violent. En RDC, dans le Tanganyika nous utilisons comme point d\u2019entr\u00e9e pour promouvoir une paix positive, l\u2019acc\u00e8s \u00e9quitable aux services de sant\u00e9 \u00e0 destination de deux groupes ethniques (Bantou et Twa) et en Somalie l\u2019acc\u00e8s \u00e0 la justice dans les districts de Karaan et Jawl Wadaag de Mogadishu. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>Troisi\u00e8mement, traiter les causes profondes du conflit tout en \u00e9vitant une rechute dans la violence exige une <em>Analyse de la sensibilit\u00e9 au conflit<\/em> qui s\u2019efforce de r\u00e9soudre la relation entre le programme et le contexte du conflit ou du d\u00e9placement. Nous avons inclus cette analyse dans le cadre de notre \u00e9valuation de r\u00e9f\u00e9rence en nous appuyant sur les connaissances de nos partenaires locaux dans le but de mettre en lumi\u00e8re les domaines prioritaires en termes de risques et de strat\u00e9gies d\u2019att\u00e9nuation. Nous avons \u00e9galement int\u00e9gr\u00e9 une approche de type \u00ab&nbsp;agir sans nuire&nbsp;\u00bb ou \u00ab Do No Harm&nbsp;\u00bb, en identifiant certains facteurs sp\u00e9cifiques de division et de coh\u00e9sion sur les lieux du projet \u2013 c\u2019est-\u00e0-dire les \u00e9l\u00e9ments de la soci\u00e9t\u00e9 qui divisent les personnes (et constituent des sources de tension) ou favorisent la coh\u00e9sion (et peuvent \u00eatre d\u00e9terminants dans la r\u00e9solution du probl\u00e8me). Les r\u00e9sultats de ce cette analyse ont permis de fonder les strat\u00e9gies de conception et de mise en \u0153uvre des diverses composantes des programmes respectifs en RDC comme en Somalie. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><strong><span lang=\"FR\"><span>Le programme&nbsp;: causes profondes et paix positive <\/span><\/span><\/strong><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>Au c\u0153ur du programme se trouve une tentative pour aider les personnes touch\u00e9es par le conflit de telle sorte qu\u2019elles puissent rester en s\u00e9curit\u00e9 au sein de leurs communaut\u00e9s en ayant le pouvoir d\u2019influencer les d\u00e9cisions qui affectent leur vie. Le programme s\u2019acquitte de cette mission en soutenant les activit\u00e9s suivantes qui incarnent l\u2019esprit du triple nexus :<\/span><\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><span><span><strong><span lang=\"FR\"><span>Action humanitaire&nbsp;:<\/span><\/span><\/strong><span lang=\"FR\"><span> r\u00e9pondre au besoin humanitaire par le biais d\u2019une fourniture directe de service, en offrant une assistance juridique et en am\u00e9liorant la responsabilit\u00e9 et l\u2019accessibilit\u00e9 des services de sant\u00e9 dans des zones o\u00f9 une partie cons\u00e9quente de la population a besoin d\u2019assistance humanitaire ou risque de d\u00e9velopper ce besoin.<\/span><\/span><\/span><\/span><\/li>\n<li><span><span><strong><span lang=\"FR\"><span>Recherche de la paix et coh\u00e9sion sociale au niveau local&nbsp;:<\/span><\/span><\/strong><span lang=\"FR\"><span> mise en place d\u2019activit\u00e9s qui promeuvent la coh\u00e9sion sociale comme des dialogues intra\/inter communautaires et qui incluent la participation des groupes marginalis\u00e9s dans les processus de prise de d\u00e9cision en mati\u00e8re de services de sant\u00e9 et de justice. <\/span><\/span><\/span><\/span><\/li>\n<li><span><span><span><strong><span lang=\"FR\"><span>Gouvernance et \u00c9tat de droit&nbsp;au niveau local&nbsp;: <\/span><\/span><\/strong><span lang=\"FR\"><span>se concentrer sur le renforcement des syst\u00e8mes et le d\u00e9veloppement de la capacit\u00e9 des d\u00e9tenteurs d\u2019obligations auxquels il incombe de fournir des services de sant\u00e9 et de justice, tout en contribuant \u00e0 renforcer les capacit\u00e9s et les connaissances au niveau communautaire pour que leurs membres (les d\u00e9tenteurs de droits) soient en mesure de demander aux d\u00e9tenteurs d\u2019obligations de rendre des comptes. <\/span><\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span><span><span><span lang=\"FR\"><span>L\u2019appropriation locale fait partie int\u00e9grante de la conception m\u00e9thodologique et de la mise en \u0153uvre des deux projets. Les partenariats int\u00e8grent des membres de la communaut\u00e9 et des d\u00e9tenteurs d\u2019obligations, plus particuli\u00e8rement des acteurs du gouvernement local ainsi que la soci\u00e9t\u00e9 civile. <\/span><\/span><span lang=\"FR\"><span>Les acteurs locaux sont les agents les mieux plac\u00e9s mais aussi les plus aptes, les plus effectifs et les plus investis sur la dur\u00e9e pour am\u00e9liorer le degr\u00e9 de responsabilisation et d\u2019inclusion, pour att\u00e9nuer le conflit et pour identifier et r\u00e9soudre des probl\u00e8mes locaux.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>En <strong>RDC<\/strong>, nous travaillons avec une organisation confessionnelle locale, Commission Dioc\u00e9saine de la Justice et Paix. Dans ce cas le programme contribue \u00e0 renforcer la r\u00e9silience, le bien-\u00eatre et la participation inclusive de personnes des groupes ethniques Bantou et Twa, \u00e0 travers des initiatives de recherche de la paix et d\u2019acc\u00e8s \u00e0 la sant\u00e9 dans les zones sanitaires de Nyunzu et Kalemie de la province Tanganyika. Ce programme cherche \u00e0 r\u00e9soudre les causes profondes du conflit entre Twa et Bantou en cr\u00e9ant ou rajeunissant les plateformes communautaires repr\u00e9sentatives de ces deux groupes ethniques<em>. <\/em><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span>\u00c0 Nyunzu, un territoire qui a connu une pauvret\u00e9 extr\u00eame et dont la coh\u00e9sion communautaire a \u00e9t\u00e9 fortement \u00e9branl\u00e9e apr\u00e8s des dizaines d\u2019ann\u00e9es de sous-investissement, des b\u00e9n\u00e9voles issus de la communaut\u00e9 ont \u00e9t\u00e9 mobilis\u00e9s et \u00e9lus au sein de comit\u00e9s locaux de promotion de la paix et de la sant\u00e9. \u00c0 travers ces comit\u00e9s, des membres des communaut\u00e9s Bantou et Twa coop\u00e8rent pour construire la paix et promouvoir le rel\u00e8vement. Les comit\u00e9s mixtes ont \u00e9t\u00e9 essentiels pour r\u00e9tablir la confiance<\/span><\/span><span lang=\"FR\"><span><span>. Les actions de plaidoyer des comit\u00e9s, y compris aupr\u00e8s des milices locales, ont permis le retour de la s\u00e9curit\u00e9 et des personnes d\u00e9plac\u00e9es dans les zones du projet cr\u00e9ant ainsi des conditions dans lesquelles des services de sant\u00e9 peuvent \u00eatre r\u00e9instaur\u00e9s et \u00e0 nouveau accessibles. <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span lang=\"FR\"><span><span>Les travailleurs de sant\u00e9 communautaire m\u00e8nent des activit\u00e9s de sensibilisation dans leurs villages, ils contribuent \u00e0 faire connaitre les services locaux de sant\u00e9 et \u00e0 redonner confiance \u00e0 leurs usagers. Les Twa sont maintenant beaucoup plus nombreux \u00e0 utiliser des services qu\u2019ils \u00e9vitaient auparavant par crainte de discrimination et de mauvais traitements. Les femmes Twa choisissent maintenant d\u2019accoucher dans les centres de sant\u00e9, plut\u00f4t que seules \u00e0 domicile et elles sont maintenant beaucoup plus nombreuses \u00e0 y amener leurs enfants pour \u00eatre vaccin\u00e9s.<\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span><span>\u00c0 Mogadishu et dans l\u2019ensemble du sud et du centre de la <strong>Somalie<\/strong> en g\u00e9n\u00e9ral, l\u2019une des principales causes de conflit et de d\u00e9placement est l\u2019incapacit\u00e9 de l\u2019\u00c9tat de fournir des services essentiels, notamment la gestion et l\u2019administration d\u2019un syst\u00e8me de justice \u00e9quitable et transparent. Le programme en Somalie m\u00e8ne son action en partenariat avec deux districts, Hawl Wadaag et Karaan. Il \u0153uvre \u00e0 faciliter l\u2019acc\u00e8s aux syst\u00e8mes de justice et cherche \u00e0 renforcer les capacit\u00e9s des membres de la communaut\u00e9 et des autorit\u00e9s locales en vue de pr\u00e9venir et g\u00e9rer les conflits et les disputes de mani\u00e8re non violente. Le projet s\u2019efforce sp\u00e9cifiquement d\u2019amener ceux charg\u00e9s d\u2019administrer les services de justice \u00e0 changer de comportement de mani\u00e8re \u00e0 ce qu\u2019ils prot\u00e8gent le droit \u00e0 un proc\u00e8s \u00e9quitable&nbsp;; son but est \u00e9galement d\u2019encourager les citoyens \u00e0 recourir \u00e0 des services de justice s\u00fbrs et de soutenir les communaut\u00e9s pour qu\u2019elles d\u00e9veloppent des strat\u00e9gies d\u2019action collective o\u00f9 toutes les voix peuvent se faire entendre, quelle que soit l\u2019affiliation clanique. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span><span>Le programme agit en \u00e9troite collaboration avec les deux conseils de district en insistant sur la mise en \u0153uvre locale, la r\u00e9appropriation et la durabilit\u00e9 du projet. En outre, les repr\u00e9sentants des communaut\u00e9s qui comprennent des membres issus des groupes de femmes et de jeunes, ont \u00e9t\u00e9 impliqu\u00e9s dans l\u2019analyse initiale portant sur la nature des conflits \u00e0 Mogadishu.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span><span>Conscient du pluralisme juridique propre \u00e0 la Somalie ainsi que de la pr\u00e9f\u00e9rence et de la confiance de la communaut\u00e9 dans les syst\u00e8mes informels de justice traditionnelle et coutumi\u00e8re, le projet a cherch\u00e9 \u00e0 \u00e9tablir un dialogue et \u00e0 renforcer la capacit\u00e9 et la volont\u00e9 des fournisseurs de justice formels et informels de mani\u00e8re \u00e0 promouvoir le droit \u00e0 un proc\u00e8s \u00e9quitable. Des activit\u00e9s participatives sous forme de forums de partenaires, de plateformes de dialogues ainsi que la planification d\u2019une action communautaire d\u2019att\u00e9nuation du conflit ont aid\u00e9 \u00e0 g\u00e9n\u00e9rer des communications r\u00e9guli\u00e8res entre les communaut\u00e9s et le gouvernement local sur la question de la gestion du conflit et de l\u2019acc\u00e8s \u00e0 la justice. Tout cela a contribu\u00e9 \u00e0 promouvoir une reddition de comptes fond\u00e9e sur des r\u00f4les et des responsabilit\u00e9s ayant fait l\u2019objet d\u2019un accord des diff\u00e9rents acteurs.&nbsp; <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span><span><strong><span lang=\"FR\"><span>Implications en termes de politique et de pratique<\/span><\/span><\/strong><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>Bien qu\u2019encore dans sa phase initiale, le programme g\u00e9n\u00e8re d\u00e9j\u00e0 des enseignements pr\u00e9cieux en mati\u00e8re de pr\u00e9vention des conflits et de pratique de recherche de la paix. L\u2019apprentissage et la recherche ont \u00e9t\u00e9 int\u00e9gr\u00e9s au cycle-m\u00eame du programme et maintenant, dans sa deuxi\u00e8me ann\u00e9e, trois le\u00e7ons m\u00e9ritent tout particuli\u00e8rement d\u2019\u00eatre mises en exergue. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>La fourniture de service s\u2019est av\u00e9r\u00e9e un point d\u2019entr\u00e9e utile ainsi qu\u2019une plateforme viable autour de laquelle organiser les approches de recherche de la paix et renforcer la coh\u00e9sion sociale entre les groupes en conflit. Renforcer l\u2019\u00c9tat au niveau local, les institutions informelles et la responsabilisation en mati\u00e8re de prestation de services est essentiel pour que les approches soient men\u00e9es localement et de mani\u00e8re durable. Le potentiel de collaboration et d\u2019action collective par le biais du b\u00e9n\u00e9volat au niveau de la base est \u00e9norme.<\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>Travailler avec les comit\u00e9s b\u00e9n\u00e9voles en RDC, par exemple, s\u2019est av\u00e9r\u00e9 un facteur essentiel pour promouvoir la repr\u00e9sentation des femmes et de la minorit\u00e9 ethnique dans les processus locaux de prise de d\u00e9cision. C\u2019est un aspect qui a aid\u00e9 \u00e0 cr\u00e9er la confiance en d\u00e9montrant que la coop\u00e9ration entre les communaut\u00e9s \u00e9tait d\u00e9terminante dans la r\u00e9solution des probl\u00e8mes locaux. Pour instaurer avec succ\u00e8s la coh\u00e9sion sociale, il est n\u00e9cessaire de comprendre les dynamiques de pouvoir \u00e0 l\u2019int\u00e9rieur du groupe et de traiter les in\u00e9galit\u00e9s et les obstacles de participation auxquels les exclus se trouvent confront\u00e9s&nbsp;; cela exige \u00e9galement des ressources ad\u00e9quates permettant de compenser les co\u00fbts de participation. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>Identifier et soutenir des institutions locales tout en maintenant l\u2019impartialit\u00e9 exige une compr\u00e9hension profonde des dynamiques du conflit local. Cela demande de proc\u00e9der r\u00e9guli\u00e8rement \u00e0 une analyse de sensibilit\u00e9 du conflit et de recourir \u00e0 des approches de type \u00ab&nbsp;agir sans nuire&nbsp;\u00bb. De tels processus doivent s\u2019appuyer sur des ressources et un soutien ad\u00e9quats et s\u2019accompagner d\u2019une capacit\u00e9 d\u2019adaptation en r\u00e9ponse \u00e0 une compr\u00e9hension de l\u2019\u00e9volution des r\u00e9alit\u00e9s et des dynamiques locales. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>Tout ce qui pr\u00e9c\u00e8de comporte de claires implications pour les donateurs et les pratiques et politiques de leurs partenaires de mise en \u0153uvre et nous allons en souligner cinq.<\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>Premi\u00e8rement, les donateurs doivent exiger des partenaires de mise en \u0153uvre qu\u2019ils adoptent explicitement une programmation adapt\u00e9e au contexte et dirig\u00e9e localement&nbsp;; les donateurs peuvent faciliter cela en soutenant des approches plus flexibles qui s\u2019appuient sur l\u2019enseignement au cours du cycle de programmation et permettent l\u2019adaptation. Une difficult\u00e9 \u00e0 laquelle nous nous sommes heurt\u00e9s est que la conception initiale du projet se fondait sur une th\u00e9orie g\u00e9n\u00e9rique et mondiale du changement. Pendant la phase de lancement <\/span><\/span><span lang=\"FR\"><span>du projet en RDC et en Somalie, et conform\u00e9ment \u00e0 l\u2019\u00e9tude de r\u00e9f\u00e9rence men\u00e9e sur le terrain, l\u2019\u00e9quipe du projet a pris conscience que chaque projet national n\u00e9cessitait sa propre th\u00e9orie du changement sp\u00e9cifique \u00e0 son contexte pour ensuite informer les diff\u00e9rentes adaptations de conception du projet. La flexibilit\u00e9 des donateurs et leur ouverture \u00e0 une gestion aussi souple du projet est vitale, comme l\u2019a d\u00e9montr\u00e9, en ce qui nous concerne, l\u2019approche de Sida. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>Deuxi\u00e8mement, ceux qui au sein de la communaut\u00e9 de l\u2019aide recherchent des solutions durables au d\u00e9placement induit par le conflit doivent investir dans des \u00e9tudes et une analyse appropri\u00e9es. Dans le but de mesurer les r\u00e9sultats de la recherche de la paix, il est crucial, par exemple, de prendre conscience que tout ce qui compte ne peut pas \u00eatre compt\u00e9. Une analyse qualitative riche comprenant des r\u00e9cits et des anecdotes associ\u00e9e \u00e0 une analyse quantitative peut apporter une perception et des r\u00e9sultats plus profond\u00e9ment r\u00e9v\u00e9lateurs des dynamiques de consolidation de la paix qu\u2019une m\u00e9thode quantitative seule.<\/span><\/span><\/span><\/span><\/p>\n<p><span lang=\"FR\"><span>Troisi\u00e8mement, il est important de casser la compartimentation entre action humanitaire, d\u00e9veloppement et recherche de la paix. Les engagements pris lors de la Grande N\u00e9gociation<a href=\"#_edn2\" name=\"_ednref2\"><span><span><span lang=\"FR\"><span>[2]<\/span><\/span><\/span><\/span><\/a> (The Grand Bargain) \u00e0 l\u2019\u00e9gard de solutions durables et du triple nexus sont bienvenus dans la mesure o\u00f9 ils mettent l\u2019accent sur les synergies entre ces domaines d\u2019intervention. Au niveau de la base, les personnes ne vivent pas leur existence dans des compartiments m\u00eame si la communaut\u00e9 de l\u2019aide continue d\u2019\u00eatre organis\u00e9e et de fonctionner de mani\u00e8re compartiment\u00e9e. Cette compartimentation peut \u00eatre impos\u00e9e par des donateurs qui financent des flux diff\u00e9rents dans les environnements touch\u00e9s par les conflits et qui tendent \u00e0 s\u00e9parer d\u00e9lib\u00e9r\u00e9ment les actions humanitaires du d\u00e9veloppement et de la recherche de la paix. <\/span><\/span><\/p>\n<p><span lang=\"FR\"><span>Quatri\u00e8mement, les m\u00e9canismes de financement doivent \u00eatre adapt\u00e9s au cas par cas de mani\u00e8re \u00e0 soutenir des solutions dirig\u00e9es localement pour r\u00e9pondre \u00e0 des crises prolong\u00e9es, en utilisant des flux de financement conjoints con\u00e7us pour incorporer des \u00e9l\u00e9ments de paix positive en se focalisant sur la r\u00e9solution de certaines causes profondes de conflit violent et de d\u00e9placement. <\/span><\/span><\/p>\n<p><span lang=\"FR\"><span>Finalement notre exp\u00e9rience \u00e0 travers la mise en place de ce projet d\u00e9montre qu\u2019il est possible pour des acteurs humanitaires de s\u2019impliquer dans un m\u00e9canisme de recherche de la paix dirig\u00e9 localement et d\u2019entrer en partenariat avec des acteurs locaux du d\u00e9veloppement et du travail sur la paix tout en maintenant leur neutralit\u00e9 et leur impartialit\u00e9. Pour que les solutions durables de recherche de la paix soient un succ\u00e8s, il incombe aux acteurs ext\u00e9rieurs de recherche de la paix de comprendre le r\u00f4le des structures et des dynamiques locales et d\u2019identifier des moyens pour soutenir une participation inclusive favorisant la confiance et garantissant l\u2019impartialit\u00e9. <\/span><\/span><\/p>\n<p><strong><span lang=\"FR\"><span>Au-del\u00e0 du local<\/span><\/span><\/strong><\/p>\n<p><span lang=\"FR\"><span>\u00c9tablir des connexions entre la recherche de la paix au niveau local et des efforts plus larges \u00e0 l\u2019\u00e9chelle d\u2019une province ou d\u2019un pays est l\u2019un des d\u00e9fis majeurs du travail dans le domaine de la recherche de la paix, et ce, pas uniquement parce que les \u00e9v\u00e9nements, les acteurs et les enjeux \u00e0 des niveaux sup\u00e9rieurs fa\u00e7onnent et influencent les efforts de recherche de la paix au niveau local. Une planification effective \u00e0 long-terme par les acteurs internationaux d\u00e9pend de l\u2019existence et de la mise en application de plans de d\u00e9veloppement et d\u2019att\u00e9nuation du conflit et d\u2019une volont\u00e9 politique dont la communaut\u00e9 locale et nationale puisse v\u00e9ritablement s\u2019approprier. Cet aspect est particuli\u00e8rement compliqu\u00e9 en RDC o\u00f9 l\u2019\u00c9tat est d\u00e9faillant et o\u00f9 les autorit\u00e9s et les \u00e9lites nationales manquent souvent de volont\u00e9 politique. <\/span><\/span><\/p>\n<p><span lang=\"FR\"><span>N\u00e9anmoins, il existe tout de m\u00eame en RDC un \u00e9norme potentiel pour que des efforts de recherche de la paix conduits localement aient un impact positif au-del\u00e0 de la sph\u00e8re strictement locale. Des initiatives comme celles du projet financ\u00e9 par Sida ont le potentiel d\u2019instaurer une dynamique favorable au d\u00e9veloppement et \u00e0 la recherche de la paix propre \u00e0 contrebalancer le manque de volont\u00e9 politique des \u00e9lites en renfor\u00e7ant la coh\u00e9sion sociale et la volont\u00e9 politique de la base vers le haut. <\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span lang=\"FR\"><span>Wale Osofisan<\/span><\/span> <a href=\"mailto:Wale.Osofisan@rescue-uk.org\"><em><span lang=\"FR\"><span>Wale.Osofisan@rescue-uk.org<\/span><\/span><\/em><\/a><br \/>\n<span lang=\"FR\"><span>Directeur technique principal (par int\u00e9rim), Unit\u00e9 technique sur la gouvernance <\/span><\/span><\/p>\n<p><span lang=\"FR\"><span>Shuna Keen<\/span><\/span> <a href=\"mailto:Shuna.Keen@rescue.org\"><em><span lang=\"FR\"><span>Shuna.Keen@rescue.org<\/span><\/span><\/em><\/a><em> <\/em><br \/>\n<span lang=\"FR\"><span>Responsable principale Cadres de travail et apprentissage \u2013 Recherche de la paix <\/span><\/span><\/p>\n<p><span><span><span lang=\"FR\"><span>International Rescue Committee<\/span><\/span> <a href=\"http:\/\/www.rescue.org\"><em><span lang=\"FR\"><span>www.rescue.org<\/span><\/span><\/em><\/a><em> <\/em><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span><span><a href=\"#_ednref1\" name=\"_edn1\"><span><span lang=\"EN-US\"><span><span><span lang=\"EN-US\"><span>[1]<\/span><\/span><\/span><\/span><\/span><\/span><\/a> <span lang=\"FR\"><span>Agence su\u00e9doise de coop\u00e9ration internationale pour le d\u00e9veloppement <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><a href=\"#_ednref2\" name=\"_edn2\"><span><span lang=\"EN-US\"><span><span><span lang=\"EN-US\"><span>[2]<\/span><\/span><\/span><\/span><\/span><\/span><\/a> <a href=\"https:\/\/interagencystandingcommittee.org\/grand-bargain-hosted-iasc\/\"><span><span>https:\/\/interagencystandingcommittee.org\/grand-bargain-hosted-iasc\/<\/span><\/span><\/a> <\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au cours des ann\u00e9es, du fait de la complexit\u00e9 des facteurs interconnect\u00e9s qui sont en jeu, l\u2019industrie de l\u2019aide s\u2019est heurt\u00e9e \u00e0 des difficult\u00e9s pour trouver des solutions durables au d\u00e9placement. On assiste \u00e0 l\u2019\u00e9mergence d\u2019un consensus selon lequel une meilleure coordination entre les acteurs humanitaires, du d\u00e9veloppement et de la recherche de la paix&hellip;<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","fmr_themes":[],"fmr_region":[],"fmr_issue":[110],"fmr_year":[],"fmr_content_type":[27],"fmr_languages":[37],"fmr_list_years":[568],"class_list":["post-42164","fmr_content","type-fmr_content","status-publish","hentry","fmr_issue-110","fmr_content_type-article","fmr_languages-french","fmr_list_years-568","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Programme communautaire de pr\u00e9vention des conflits et de renforcement de la paix en RDC et en Somalie - Forced Migration Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fmreview.org\/osofisan-keen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programme communautaire de pr\u00e9vention des conflits et de renforcement de la paix en RDC et en Somalie - Forced Migration Review\" \/>\n<meta property=\"og:description\" content=\"Au cours des ann\u00e9es, du fait de la complexit\u00e9 des facteurs interconnect\u00e9s qui sont en jeu, l\u2019industrie de l\u2019aide s\u2019est heurt\u00e9e \u00e0 des difficult\u00e9s pour trouver des solutions durables au d\u00e9placement. On assiste \u00e0 l\u2019\u00e9mergence d\u2019un consensus selon lequel une meilleure coordination entre les acteurs humanitaires, du d\u00e9veloppement et de la recherche de la paix&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fmreview.org\/osofisan-keen\/\" \/>\n<meta property=\"og:site_name\" content=\"Forced Migration Review\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T22:23:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fmreview.org\/osofisan-keen\/\",\"url\":\"https:\/\/www.fmreview.org\/osofisan-keen\/\",\"name\":\"Programme communautaire de pr\u00e9vention des conflits et de renforcement de la paix en RDC et en Somalie - Forced Migration Review\",\"isPartOf\":{\"@id\":\"https:\/\/www.fmreview.org\/#website\"},\"datePublished\":\"2019-10-09T05:00:00+00:00\",\"dateModified\":\"2025-03-12T22:23:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fmreview.org\/osofisan-keen\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fmreview.org\/osofisan-keen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fmreview.org\/osofisan-keen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fmreview.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programme communautaire de pr\u00e9vention des conflits et de renforcement de la paix en RDC et en Somalie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fmreview.org\/#website\",\"url\":\"https:\/\/www.fmreview.org\/\",\"name\":\"Forced Migration Review\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fmreview.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fmreview.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fmreview.org\/#organization\",\"name\":\"Forced Migration Review\",\"url\":\"https:\/\/www.fmreview.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"contentUrl\":\"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg\",\"width\":53,\"height\":62,\"caption\":\"Forced Migration Review\"},\"image\":{\"@id\":\"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programme communautaire de pr\u00e9vention des conflits et de renforcement de la paix en RDC et en Somalie - Forced Migration Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fmreview.org\/osofisan-keen\/","og_locale":"fr_FR","og_type":"article","og_title":"Programme communautaire de pr\u00e9vention des conflits et de renforcement de la paix en RDC et en Somalie - Forced Migration Review","og_description":"Au cours des ann\u00e9es, du fait de la complexit\u00e9 des facteurs interconnect\u00e9s qui sont en jeu, l\u2019industrie de l\u2019aide s\u2019est heurt\u00e9e \u00e0 des difficult\u00e9s pour trouver des solutions durables au d\u00e9placement. On assiste \u00e0 l\u2019\u00e9mergence d\u2019un consensus selon lequel une meilleure coordination entre les acteurs humanitaires, du d\u00e9veloppement et de la recherche de la paix&hellip;","og_url":"https:\/\/www.fmreview.org\/osofisan-keen\/","og_site_name":"Forced Migration Review","article_modified_time":"2025-03-12T22:23:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fmreview.org\/osofisan-keen\/","url":"https:\/\/www.fmreview.org\/osofisan-keen\/","name":"Programme communautaire de pr\u00e9vention des conflits et de renforcement de la paix en RDC et en Somalie - Forced Migration Review","isPartOf":{"@id":"https:\/\/www.fmreview.org\/#website"},"datePublished":"2019-10-09T05:00:00+00:00","dateModified":"2025-03-12T22:23:48+00:00","breadcrumb":{"@id":"https:\/\/www.fmreview.org\/osofisan-keen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fmreview.org\/osofisan-keen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fmreview.org\/osofisan-keen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fmreview.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Programme communautaire de pr\u00e9vention des conflits et de renforcement de la paix en RDC et en Somalie"}]},{"@type":"WebSite","@id":"https:\/\/www.fmreview.org\/#website","url":"https:\/\/www.fmreview.org\/","name":"Forced Migration Review","description":"","publisher":{"@id":"https:\/\/www.fmreview.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fmreview.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.fmreview.org\/#organization","name":"Forced Migration Review","url":"https:\/\/www.fmreview.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","contentUrl":"https:\/\/www.fmreview.org\/wp-content\/uploads\/2024\/02\/FMR_logo1.svg","width":53,"height":62,"caption":"Forced Migration Review"},"image":{"@id":"https:\/\/www.fmreview.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/42164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content"}],"about":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/types\/fmr_content"}],"version-history":[{"count":1,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/42164\/revisions"}],"predecessor-version":[{"id":44578,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content\/42164\/revisions\/44578"}],"wp:attachment":[{"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/media?parent=42164"}],"wp:term":[{"taxonomy":"fmr_themes","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_themes?post=42164"},{"taxonomy":"fmr_region","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_region?post=42164"},{"taxonomy":"fmr_issue","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_issue?post=42164"},{"taxonomy":"fmr_year","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_year?post=42164"},{"taxonomy":"fmr_content_type","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_content_type?post=42164"},{"taxonomy":"fmr_languages","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_languages?post=42164"},{"taxonomy":"fmr_list_years","embeddable":true,"href":"https:\/\/www.fmreview.org\/fr\/wp-json\/wp\/v2\/fmr_list_years?post=42164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}